{"id":2786,"date":"2020-02-24T00:00:00","date_gmt":"2020-02-24T00:00:00","guid":{"rendered":"https:\/\/toffolettodeluca.it\/\/webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro\/"},"modified":"2020-02-24T00:00:00","modified_gmt":"2020-02-24T00:00:00","slug":"webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro","status":"publish","type":"post","link":"https:\/\/toffolettodeluca.it\/en\/webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro\/","title":{"rendered":"Webinar: L\u2019uso in giudizio delle registrazioni di conversazioni tra colleghi sul luogo di lavoro"},"content":{"rendered":"<p>Relatore: Avv. Elio Cherubini, Partner<\/p>\n<p>NB: l&#8217;evento sar\u00e0 esclusivamente un seminario online, senza possibilit\u00e0 di partecipare live presso lo Studio.<\/p>\n<p>Per richiedere l\u2019iscrizione al webinar, scrivere a <a href=mailto:eventi@toffolettodeluca.it?subject=Vorrei%20partecipare%20al%20webinar%20(iscrizione%20richiesta%20dal%20sito%20Studio)\">eventi@toffolettodeluca.it<\/a><\/p>\n<p> &#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Relatore: Avv. Elio Cherubini, Partner NB: l&#8217;evento sar\u00e0 esclusivamente un seminario online, senza possibilit\u00e0 di partecipare live presso lo Studio. Per richiedere l\u2019iscrizione al webinar, scrivere a<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[23],"tags":[],"class_list":["post-2786","post","type-post","status-publish","format-standard","hentry","category-webinar-eventi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Webinar: L\u2019uso in giudizio delle registrazioni di conversazioni tra colleghi sul luogo di lavoro - Toffoletto De Luca Tamajo e Soci<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toffolettodeluca.it\/en\/webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Webinar: L\u2019uso in giudizio delle registrazioni di conversazioni tra colleghi sul luogo di lavoro - Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"og:description\" content=\"Relatore: Avv. Elio Cherubini, Partner NB: l&#8217;evento sar\u00e0 esclusivamente un seminario online, senza possibilit\u00e0 di partecipare live presso lo Studio. Per richiedere l\u2019iscrizione al webinar, scrivere a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toffolettodeluca.it\/en\/webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro\/\" \/>\n<meta property=\"og:site_name\" content=\"Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-24T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\"},\"headline\":\"Webinar: L\u2019uso in giudizio delle registrazioni di conversazioni tra colleghi sul luogo di lavoro\",\"datePublished\":\"2020-02-24T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro\\\/\"},\"wordCount\":44,\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"articleSection\":[\"Webinar &amp; Events\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro\\\/\",\"name\":\"Webinar: L\u2019uso in giudizio delle registrazioni di conversazioni tra colleghi sul luogo di lavoro - Toffoletto De Luca Tamajo e Soci\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\"},\"datePublished\":\"2020-02-24T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/studio-diritto-del-lavoro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Learn & Connect\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/learn-connect\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Webinar &amp; Events\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/category\\\/webinar-eventi\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Webinar: L\u2019uso in giudizio delle registrazioni di conversazioni tra colleghi sul luogo di lavoro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"contentUrl\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"caption\":\"Toffoletto De Luca Tamajo e Soci\"},\"image\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Webinar: L\u2019uso in giudizio delle registrazioni di conversazioni tra colleghi sul luogo di lavoro - Toffoletto De Luca Tamajo e Soci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toffolettodeluca.it\/en\/webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro\/","og_locale":"en_US","og_type":"article","og_title":"Webinar: L\u2019uso in giudizio delle registrazioni di conversazioni tra colleghi sul luogo di lavoro - Toffoletto De Luca Tamajo e Soci","og_description":"Relatore: Avv. Elio Cherubini, Partner NB: l&#8217;evento sar\u00e0 esclusivamente un seminario online, senza possibilit\u00e0 di partecipare live presso lo Studio. Per richiedere l\u2019iscrizione al webinar, scrivere a","og_url":"https:\/\/toffolettodeluca.it\/en\/webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro\/","og_site_name":"Toffoletto De Luca Tamajo e Soci","article_published_time":"2020-02-24T00:00:00+00:00","author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/toffolettodeluca.it\/en\/webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro\/#article","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro\/"},"author":{"name":"Redazione","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559"},"headline":"Webinar: L\u2019uso in giudizio delle registrazioni di conversazioni tra colleghi sul luogo di lavoro","datePublished":"2020-02-24T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/toffolettodeluca.it\/en\/webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro\/"},"wordCount":44,"publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"articleSection":["Webinar &amp; Events"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/toffolettodeluca.it\/en\/webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro\/","url":"https:\/\/toffolettodeluca.it\/en\/webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro\/","name":"Webinar: L\u2019uso in giudizio delle registrazioni di conversazioni tra colleghi sul luogo di lavoro - Toffoletto De Luca Tamajo e Soci","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/#website"},"datePublished":"2020-02-24T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/toffolettodeluca.it\/en\/webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toffolettodeluca.it\/en\/webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/toffolettodeluca.it\/en\/webinar-luso-in-giudizio-delle-registrazioni-di-conversazioni-tra-colleghi-sul-luogo-di-lavoro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toffolettodeluca.it\/en\/studio-diritto-del-lavoro\/"},{"@type":"ListItem","position":2,"name":"Learn & Connect","item":"https:\/\/toffolettodeluca.it\/en\/learn-connect\/"},{"@type":"ListItem","position":3,"name":"Webinar &amp; Events","item":"https:\/\/toffolettodeluca.it\/en\/category\/webinar-eventi\/"},{"@type":"ListItem","position":4,"name":"Webinar: L\u2019uso in giudizio delle registrazioni di conversazioni tra colleghi sul luogo di lavoro"}]},{"@type":"WebSite","@id":"https:\/\/toffolettodeluca.it\/en\/#website","url":"https:\/\/toffolettodeluca.it\/en\/","name":"Toffoletto De Luca Tamajo e Soci","description":"","publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toffolettodeluca.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/toffolettodeluca.it\/en\/#organization","name":"Toffoletto De Luca Tamajo e Soci","url":"https:\/\/toffolettodeluca.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","contentUrl":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","caption":"Toffoletto De Luca Tamajo e Soci"},"image":{"@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/toffolettodeluca.it\/en\/author\/redazione\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/2786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/comments?post=2786"}],"version-history":[{"count":0,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/2786\/revisions"}],"wp:attachment":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/media?parent=2786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/categories?post=2786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/tags?post=2786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}