{"id":2861,"date":"2019-11-13T00:00:00","date_gmt":"2019-11-13T00:00:00","guid":{"rendered":"https:\/\/toffolettodeluca.it\/\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\/"},"modified":"2019-11-13T00:00:00","modified_gmt":"2019-11-13T00:00:00","slug":"protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product","status":"publish","type":"post","link":"https:\/\/toffolettodeluca.it\/en\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\/","title":{"rendered":"Protecting trade secrets and employment law: Toffoletto De Luca Tamajo launches a new product"},"content":{"rendered":"<p>Toffoletto De Luca Tamajo lancia il nuovo prodotto legale \u201ctutela dei segreti industriali\u201d.<\/p>\n<p>\u00abOggi, nell\u2019epoca della digitalizzazione, la tutela dei segreti aziendali \u00e8 sempre pi\u00f9 rilevante, tenuto conto che pu\u00f2 bastare un click per sottrarre e divulgare enormi quantitativi di dati, anche riservati &#8211; sottolinea Stefano de Luca Tamajo, partner di Toffoletto De Luca Tamajo &#8211; Il rischio \u00e8 ancor pi\u00f9 rilevante nell\u2019ambito del rapporto di lavoro, in cui i dipendenti nello svolgimento delle proprie mansioni possono avere accesso a dati altamente riservati\u00bb.\u00a0<\/p>\n<p>Le recenti riforme hanno aggiunto altri strumenti di protezione per i datori di lavoro, prevedendo una serie di tutele, sia dal punto di vista civilistico che penalistico. Peraltro, gi\u00e0 da qualche tempo, a seguito delle modifiche all\u2019articolo 4 dello Statuto dei Lavoratori, il datore di lavoro ha maggiori possibilit\u00e0 di controllo su luoghi e strumenti di lavoro, anche al fine di tutelare dati e segreti aziendali.\u00a0<\/p>\n<p>Tuttavia, per poter effettivamente beneficiare di tutti gli strumenti di protezione offerti dall\u2019ordinamento, \u00e8 necessario che le aziende adottino le opportune misure.<\/p>\n<p>\u00abIn particolare, per garantire la massima tutela dei propri segreti industriali e commerciali \u00e8 necessario che le aziende adottino preventivamente specifiche protezioni contrattuali, misure organizzative, e una specifica policy ai sensi dell\u2019art. 4 dello Statuto dei Lavoratori contenente adeguata informativa sulle modalit\u00e0 di utilizzo degli strumenti e sui possibili controlli che saranno effettuati dal datore di lavoro, sempre nel rispetto della disciplina in materia di privacy\u00bb, conclude l\u2019avvocato de Luca Tamajo.<\/p>\n<p>Proprio per venire incontro a queste esigenze, lo studio ha costituito un team specializzato nella predisposizione di protezioni contrattuali, misure organizzative e policy per la tutela dei dati aziendali riservati.<\/p>\n<p>La Tutela dei segreti aziendali si aggiunge ai numerosi prodotti, anche digitali, &#8211; fra cui Welfare, GDPR e Privacy, Procedure articolo 4 e utilizzo degli strumenti informatici, Smart Working, Whistleblowing, Politiche retributive, Contratti di agenzia, Contratti Digitali, e Flexit \u00abstrumenti di flessibilit\u00e0 in uscita\u00bb &#8211; creati da Toffoletto De Luca Tamajo per le aziende: dei team dedicati che offrono servizi specifici pi\u00f9 efficienti e ad alto valore aggiunto, con una qualit\u00e0 molto elevata, a un costo preciso e predefinito per il cliente. Per i prodotti legali lo Studio \u00e8 entrato nella classifica FT Innovative Lawyers Report 2019, la survey del Financial Times sulle law firm europee pi\u00f9 innovative.<\/p>\n<div class=boxout\">\n<h3><span style=\"color: #FF0000;\">Chi posso contattare per saperne di pi\u00f9?<\/span><\/h3>\n<p>Per maggiori informazioni, potete contattare l\u2019 <a href=\"https:\/\/toffolettodeluca.it\/it\/avvocati-diritto-del-lavoro\/i-nostri-soci\/stefano.delucatamajo\/\" >Avv. Stefano de Luca Tamajo<\/a>  \u00a0( <a href=\"mailto:sdlt@toffolettodeluca.it\" >sdlt@toffolettodeluca.it<\/a>  ), Partner dello Studio e Responsabile del team dedicato al prodotto Tutela dei segreti aziendali.<\/p>\n<\/p><\/div>\n<p>&#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toffoletto De Luca Tamajo lancia il nuovo prodotto legale \u201ctutela dei segreti industriali\u201d. \u00abOggi, nell\u2019epoca della digitalizzazione, la tutela dei segreti aziendali \u00e8 sempre pi\u00f9 rilevante, tenuto conto che pu\u00f2 bastare un click per sottrarre e divulgare enormi quantitativi di dati, anche riservati &#8211; sottolinea Stefano de Luca Tamajo, partner di Toffoletto De Luca Tamajo &#8230; <a title=\"Protecting trade secrets and employment law: Toffoletto De Luca Tamajo launches a new product\" class=\"read-more\" href=\"https:\/\/toffolettodeluca.it\/en\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\/\" aria-label=\"Read more about Protecting trade secrets and employment law: Toffoletto De Luca Tamajo launches a new product\">Read more<\/a><\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[21],"tags":[56],"class_list":["post-2861","post","type-post","status-publish","format-standard","hentry","category-newsflash-insight","tag-segreti-aziendali-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Protecting trade secrets and employment law: Toffoletto De Luca Tamajo launches a new product - Toffoletto De Luca Tamajo e Soci<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toffolettodeluca.it\/en\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protecting trade secrets and employment law: Toffoletto De Luca Tamajo launches a new product - Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"og:description\" content=\"Toffoletto De Luca Tamajo lancia il nuovo prodotto legale \u201ctutela dei segreti industriali\u201d. \u00abOggi, nell\u2019epoca della digitalizzazione, la tutela dei segreti aziendali \u00e8 sempre pi\u00f9 rilevante, tenuto conto che pu\u00f2 bastare un click per sottrarre e divulgare enormi quantitativi di dati, anche riservati &#8211; sottolinea Stefano de Luca Tamajo, partner di Toffoletto De Luca Tamajo ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toffolettodeluca.it\/en\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\/\" \/>\n<meta property=\"og:site_name\" content=\"Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-13T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\"},\"headline\":\"Protecting trade secrets and employment law: Toffoletto De Luca Tamajo launches a new product\",\"datePublished\":\"2019-11-13T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\\\/\"},\"wordCount\":391,\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"keywords\":[\"Trade Secrets\"],\"articleSection\":[\"Newsflash &amp; Insights\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\\\/\",\"name\":\"Protecting trade secrets and employment law: Toffoletto De Luca Tamajo launches a new product - Toffoletto De Luca Tamajo e Soci\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\"},\"datePublished\":\"2019-11-13T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/studio-diritto-del-lavoro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Learn & Connect\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/learn-connect\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Newsflash &amp; Insights\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/category\\\/newsflash-insight\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Protecting trade secrets and employment law: Toffoletto De Luca Tamajo launches a new product\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"contentUrl\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"caption\":\"Toffoletto De Luca Tamajo e Soci\"},\"image\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Protecting trade secrets and employment law: Toffoletto De Luca Tamajo launches a new product - Toffoletto De Luca Tamajo e Soci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toffolettodeluca.it\/en\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\/","og_locale":"en_US","og_type":"article","og_title":"Protecting trade secrets and employment law: Toffoletto De Luca Tamajo launches a new product - Toffoletto De Luca Tamajo e Soci","og_description":"Toffoletto De Luca Tamajo lancia il nuovo prodotto legale \u201ctutela dei segreti industriali\u201d. \u00abOggi, nell\u2019epoca della digitalizzazione, la tutela dei segreti aziendali \u00e8 sempre pi\u00f9 rilevante, tenuto conto che pu\u00f2 bastare un click per sottrarre e divulgare enormi quantitativi di dati, anche riservati &#8211; sottolinea Stefano de Luca Tamajo, partner di Toffoletto De Luca Tamajo ... Read more","og_url":"https:\/\/toffolettodeluca.it\/en\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\/","og_site_name":"Toffoletto De Luca Tamajo e Soci","article_published_time":"2019-11-13T00:00:00+00:00","author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redazione","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/toffolettodeluca.it\/en\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\/#article","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\/"},"author":{"name":"Redazione","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559"},"headline":"Protecting trade secrets and employment law: Toffoletto De Luca Tamajo launches a new product","datePublished":"2019-11-13T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/toffolettodeluca.it\/en\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\/"},"wordCount":391,"publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"keywords":["Trade Secrets"],"articleSection":["Newsflash &amp; Insights"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/toffolettodeluca.it\/en\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\/","url":"https:\/\/toffolettodeluca.it\/en\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\/","name":"Protecting trade secrets and employment law: Toffoletto De Luca Tamajo launches a new product - Toffoletto De Luca Tamajo e Soci","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/#website"},"datePublished":"2019-11-13T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/toffolettodeluca.it\/en\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toffolettodeluca.it\/en\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/toffolettodeluca.it\/en\/protecting-trade-secrets-and-employment-law-toffoletto-de-luca-tamajo-launches-a-new-product\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toffolettodeluca.it\/en\/studio-diritto-del-lavoro\/"},{"@type":"ListItem","position":2,"name":"Learn & Connect","item":"https:\/\/toffolettodeluca.it\/en\/learn-connect\/"},{"@type":"ListItem","position":3,"name":"Newsflash &amp; Insights","item":"https:\/\/toffolettodeluca.it\/en\/category\/newsflash-insight\/"},{"@type":"ListItem","position":4,"name":"Protecting trade secrets and employment law: Toffoletto De Luca Tamajo launches a new product"}]},{"@type":"WebSite","@id":"https:\/\/toffolettodeluca.it\/en\/#website","url":"https:\/\/toffolettodeluca.it\/en\/","name":"Toffoletto De Luca Tamajo e Soci","description":"","publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toffolettodeluca.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/toffolettodeluca.it\/en\/#organization","name":"Toffoletto De Luca Tamajo e Soci","url":"https:\/\/toffolettodeluca.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","contentUrl":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","caption":"Toffoletto De Luca Tamajo e Soci"},"image":{"@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/toffolettodeluca.it\/en\/author\/redazione\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/2861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/comments?post=2861"}],"version-history":[{"count":0,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/2861\/revisions"}],"wp:attachment":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/media?parent=2861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/categories?post=2861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/tags?post=2861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}