{"id":2910,"date":"2019-09-17T00:00:00","date_gmt":"2019-09-17T00:00:00","guid":{"rendered":"https:\/\/toffolettodeluca.it\/\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\/"},"modified":"2019-09-17T00:00:00","modified_gmt":"2019-09-17T00:00:00","slug":"early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit","status":"publish","type":"post","link":"https:\/\/toffolettodeluca.it\/en\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\/","title":{"rendered":"Early retirement programmes &#8211; TOFFOLETTO DE LUCA TAMAJO PRESENTS: FLEXIT"},"content":{"rendered":"<p> <picture><!--[if IE 9]><video style=display: none;\"><![endif]--><source srcset=\"\/media\/filer_public_thumbnails\/filer_public\/10\/ba\/10baa478-e22b-43a8-812d-4ec617a56a09\/flexit.jpg__1440x0_q80_crop_subsampling-2_upscale.jpg\" media=\"(min-width: 100em)\"><source srcset=\"\/media\/filer_public_thumbnails\/filer_public\/10\/ba\/10baa478-e22b-43a8-812d-4ec617a56a09\/flexit.jpg__1440x0_q80_crop_subsampling-2_upscale.jpg, \/media\/filer_public_thumbnails\/filer_public\/10\/ba\/10baa478-e22b-43a8-812d-4ec617a56a09\/flexit.jpg__2880x0_q80_crop_subsampling-2_upscale.jpg 2x\" media=\"(min-width: 80em)\"><source srcset=\"\/media\/filer_public_thumbnails\/filer_public\/10\/ba\/10baa478-e22b-43a8-812d-4ec617a56a09\/flexit.jpg__1024x0_q85_crop_subsampling-2_upscale.jpg, \/media\/filer_public_thumbnails\/filer_public\/10\/ba\/10baa478-e22b-43a8-812d-4ec617a56a09\/flexit.jpg__2048x0_q85_crop_subsampling-2_upscale.jpg 2x\" media=\"(min-width: 48em)\"><source srcset=\"\/media\/filer_public_thumbnails\/filer_public\/10\/ba\/10baa478-e22b-43a8-812d-4ec617a56a09\/flexit.jpg__416x0_q60_crop_subsampling-2_upscale.jpg, \/media\/filer_public_thumbnails\/filer_public\/10\/ba\/10baa478-e22b-43a8-812d-4ec617a56a09\/flexit.jpg__832x0_q60_crop_subsampling-2_upscale.jpg 2x\" media=\"(max-width: 26em)\"><!--[if IE 9]><\/video><![endif]--><img srcset=\"\/media\/filer_public_thumbnails\/filer_public\/10\/ba\/10baa478-e22b-43a8-812d-4ec617a56a09\/flexit.jpg__560x0_q85_crop_subsampling-2_upscale.jpg, \/media\/filer_public_thumbnails\/filer_public\/10\/ba\/10baa478-e22b-43a8-812d-4ec617a56a09\/flexit.jpg__1020x0_q85_crop_subsampling-2_upscale.jpg 2x\" alt=\"Flexit - Strumenti di flessibilit\u00e0 in uscita\" class=\"img--block\"><\/picture><\/p>\n<p>\u00a0<\/p>\n<p>Orientarsi tra le differenti normative in vigore sull\u2019accesso alla pensione, comprendere quale sia la misura pi\u00f9 idonea al caso di specie e seguire tutte le fasi delle procedure non \u00e8 semplice: per questo motivo\u00a0<strong>Toffoletto De Luca Tamajo<\/strong>\u2013 studio legale specializzato nella consulenza alle imprese nel diritto del lavoro, sindacale e contratti di agenzia &#8211; ha ideato\u00a0 <a href=\"https:\/\/toffolettodeluca.it\/it\/specializzati-diritto-del-lavoro-e-sindacale\/flexit-strumenti-di-flessibilita-uscita\/\" >Flexit<\/a>  , un pacchetto di servizi e strumenti di \u201cflessibilit\u00e0 in uscita\u201d, grazie al quale \u00e8 possibile orientarsi tra le differenti normative e seguire l\u2019iter in tutte le sue fasi, evitando situazioni conflittuali.<\/p>\n<p>\u00abLa riforma Fornero del 2011 ha progressivamente innalzato i requisiti per l\u2019accesso alla pensione &#8211;\u00a0<strong>commenta l\u2019<\/strong> <a href=\"https:\/\/toffolettodeluca.it\/it\/avvocati-diritto-del-lavoro\/i-nostri-soci\/emanuela.nespoli\/\" >avvocato Emanuela Nespoli<\/a>  <strong>, partner dello Studio<\/strong>. &#8211; Per bilanciare tale effetto, nel corso degli ultimi anni sono stati introdotti numerosi strumenti, di carattere collettivo o individuale, volti a consentire un accesso anticipato alla pensione, favorendo cos\u00ec anche un maggiore ricambio generazionale. Quota 100, Opzione donna, APE, RITA, accordi di isopensione, prestazioni dei Fondi di solidariet\u00e0 bilaterali: sono solo alcuni dei possibili strumenti oggi a disposizione, il cui utilizzo mirato consente di creare percorsi, individuali o collettivi, di accompagnamento alla pensione e di gestire i processi di uscita in maniera non traumatica e conflittuale.\u00bb<\/p>\n<p>Gestire correttamente le fasi dei diversi processi di accompagnamento alla pensione, destreggiandosi tra le diverse normative in vigore ed individuando le misure pi\u00f9 idonee a ciascun caso: \u00e8 un processo che pu\u00f2 comportare notevoli benefici, sia per le aziende che per i singoli lavoratori. Dall\u2019analisi della popolazione aziendale alla stima dei costi, fino alla definizione della strategia che consenta l\u2019accompagnamento dei lavoratori prossimi alla pensione tramite strumenti di carattere collettivo o individuale, Flexit consente di individuare quale sia la misura pi\u00f9 idonea al caso di specie.\u00a0<\/p>\n<p><strong>Flexit \u00e8 il focus della nuova campagna pubblicitaria di Toffoletto De Luca Tamajo<\/strong>, on air all\u2019aeroporto di Milano Malpensa. La\u00a0<strong>direzione creativa \u00e8 affidata anche questa volta a Francesco Emiliani e Paola Bussa<\/strong>, anche art director, il copy \u00e8 di Davide Donati e la fotografia di Andrea Melcangi.<\/p>\n<p>\u00ab\u00c8 sempre una grande opportunit\u00e0 lavorare per i prodotti legali dello Studio Toffoletto De Luca Tamajo, uno studio che rappresenta la perfetta sinergia tra innovazione e senso del contemporaneo &#8211; commenta Francesco Emiliani. &#8211; Qui la sfida \u00e8 stata quella di trattare la ricerca del naming Flexit e poi declinarne la comunicazione. L\u2019insight era trovare un tono di voce adeguato, consono all\u2019argomento. Nel visual, la centralit\u00e0 dello Studio \u201capre\u201d, nel vero senso della parola, verso prospettive concrete in linea con un mondo che ha sempre pi\u00f9 bisogno di nuovi punti di riferimento.\u00bb<\/p>\n<p>La campagna, oltre alla maxi-affissione a Malpensa, sar\u00e0 declinata sui principali media nazionali, generalisti e specializzati, oltre che online e su LinkedIN con un video emozionale.\u00a0<\/p>\n<p>Flexit si aggiunge ai numerosi prodotti &#8211; fra cui Welfare, GDPR e Privacy, Procedure articolo 4 e utilizzo degli strumenti informatici, Smart Working, Whistleblowing, Politiche retributive, Contratti di agenzia, Contratti Digitali, Strumenti di riorganizzazione aziendale &#8211; creati da Toffoletto De Luca Tamajo per le aziende. Ciascun prodotto \u00e8 gestito da team dedicati, che offrono servizi specifici pi\u00f9 efficienti e ad alto valore aggiunto, con una qualit\u00e0 molto elevata, a un costo preciso e predefinito per ciascun cliente.<\/p>\n<div class=\"boxout\">\n<h3><span style=\"color: #FF0000;\">Chi posso contattare per saperne di pi\u00f9?<\/span><\/h3>\n<p>Per maggiori informazioni o un colloquio informale, potete contattare l\u2019 <a href=\"https:\/\/toffolettodeluca.it\/it\/avvocati-diritto-del-lavoro\/i-nostri-soci\/emanuela.nespoli\/\" >Avv. Emanuela Nespoli<\/a>  <b> (<\/b> <a href=\"mailto:sen@toffolettodeluca.it\" target=\"_blank\" rel=\"noopener\">sen@toffolettodeluca.it<\/a>  <b>)<\/b>, Partner dello Studio e Responsabile del Team.<\/p>\n<\/p><\/div>\n<p>&#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0 Orientarsi tra le differenti normative in vigore sull\u2019accesso alla pensione, comprendere quale sia la misura pi\u00f9 idonea al caso di specie e seguire tutte le fasi delle procedure non \u00e8 semplice: per questo motivo\u00a0Toffoletto De Luca Tamajo\u2013 studio legale specializzato nella consulenza alle imprese nel diritto del lavoro, sindacale e contratti di agenzia &#8211; &#8230; <a title=\"Early retirement programmes &#8211; TOFFOLETTO DE LUCA TAMAJO PRESENTS: FLEXIT\" class=\"read-more\" href=\"https:\/\/toffolettodeluca.it\/en\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\/\" aria-label=\"Read more about Early retirement programmes &#8211; TOFFOLETTO DE LUCA TAMAJO PRESENTS: FLEXIT\">Read more<\/a><\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[21],"tags":[159,191,201],"class_list":["post-2910","post","type-post","status-publish","format-standard","hentry","category-newsflash-insight","tag-flexit-en","tag-prodotti-en","tag-strumenti-di-flessibilita-in-uscita-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Early retirement programmes - TOFFOLETTO DE LUCA TAMAJO PRESENTS: FLEXIT - Toffoletto De Luca Tamajo e Soci<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toffolettodeluca.it\/en\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Early retirement programmes - TOFFOLETTO DE LUCA TAMAJO PRESENTS: FLEXIT - Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"og:description\" content=\"\u00a0 Orientarsi tra le differenti normative in vigore sull\u2019accesso alla pensione, comprendere quale sia la misura pi\u00f9 idonea al caso di specie e seguire tutte le fasi delle procedure non \u00e8 semplice: per questo motivo\u00a0Toffoletto De Luca Tamajo\u2013 studio legale specializzato nella consulenza alle imprese nel diritto del lavoro, sindacale e contratti di agenzia &#8211; ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toffolettodeluca.it\/en\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\/\" \/>\n<meta property=\"og:site_name\" content=\"Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-17T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\"},\"headline\":\"Early retirement programmes &#8211; TOFFOLETTO DE LUCA TAMAJO PRESENTS: FLEXIT\",\"datePublished\":\"2019-09-17T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\\\/\"},\"wordCount\":564,\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"keywords\":[\"Flexit\",\"Products\",\"Strumenti di flessibilit\u00e0 in uscita\"],\"articleSection\":[\"Newsflash &amp; Insights\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\\\/\",\"name\":\"Early retirement programmes - TOFFOLETTO DE LUCA TAMAJO PRESENTS: FLEXIT - Toffoletto De Luca Tamajo e Soci\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\"},\"datePublished\":\"2019-09-17T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/studio-diritto-del-lavoro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Learn & Connect\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/learn-connect\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Newsflash &amp; Insights\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/category\\\/newsflash-insight\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Early retirement programmes &#8211; TOFFOLETTO DE LUCA TAMAJO PRESENTS: FLEXIT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"contentUrl\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"caption\":\"Toffoletto De Luca Tamajo e Soci\"},\"image\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Early retirement programmes - TOFFOLETTO DE LUCA TAMAJO PRESENTS: FLEXIT - Toffoletto De Luca Tamajo e Soci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toffolettodeluca.it\/en\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\/","og_locale":"en_US","og_type":"article","og_title":"Early retirement programmes - TOFFOLETTO DE LUCA TAMAJO PRESENTS: FLEXIT - Toffoletto De Luca Tamajo e Soci","og_description":"\u00a0 Orientarsi tra le differenti normative in vigore sull\u2019accesso alla pensione, comprendere quale sia la misura pi\u00f9 idonea al caso di specie e seguire tutte le fasi delle procedure non \u00e8 semplice: per questo motivo\u00a0Toffoletto De Luca Tamajo\u2013 studio legale specializzato nella consulenza alle imprese nel diritto del lavoro, sindacale e contratti di agenzia &#8211; ... Read more","og_url":"https:\/\/toffolettodeluca.it\/en\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\/","og_site_name":"Toffoletto De Luca Tamajo e Soci","article_published_time":"2019-09-17T00:00:00+00:00","author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redazione","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/toffolettodeluca.it\/en\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\/#article","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\/"},"author":{"name":"Redazione","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559"},"headline":"Early retirement programmes &#8211; TOFFOLETTO DE LUCA TAMAJO PRESENTS: FLEXIT","datePublished":"2019-09-17T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/toffolettodeluca.it\/en\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\/"},"wordCount":564,"publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"keywords":["Flexit","Products","Strumenti di flessibilit\u00e0 in uscita"],"articleSection":["Newsflash &amp; Insights"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/toffolettodeluca.it\/en\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\/","url":"https:\/\/toffolettodeluca.it\/en\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\/","name":"Early retirement programmes - TOFFOLETTO DE LUCA TAMAJO PRESENTS: FLEXIT - Toffoletto De Luca Tamajo e Soci","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/#website"},"datePublished":"2019-09-17T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/toffolettodeluca.it\/en\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toffolettodeluca.it\/en\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/toffolettodeluca.it\/en\/early-retirement-programmes-toffoletto-de-luca-tamajo-presents-flexit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toffolettodeluca.it\/en\/studio-diritto-del-lavoro\/"},{"@type":"ListItem","position":2,"name":"Learn & Connect","item":"https:\/\/toffolettodeluca.it\/en\/learn-connect\/"},{"@type":"ListItem","position":3,"name":"Newsflash &amp; Insights","item":"https:\/\/toffolettodeluca.it\/en\/category\/newsflash-insight\/"},{"@type":"ListItem","position":4,"name":"Early retirement programmes &#8211; TOFFOLETTO DE LUCA TAMAJO PRESENTS: FLEXIT"}]},{"@type":"WebSite","@id":"https:\/\/toffolettodeluca.it\/en\/#website","url":"https:\/\/toffolettodeluca.it\/en\/","name":"Toffoletto De Luca Tamajo e Soci","description":"","publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toffolettodeluca.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/toffolettodeluca.it\/en\/#organization","name":"Toffoletto De Luca Tamajo e Soci","url":"https:\/\/toffolettodeluca.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","contentUrl":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","caption":"Toffoletto De Luca Tamajo e Soci"},"image":{"@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/toffolettodeluca.it\/en\/author\/redazione\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/2910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/comments?post=2910"}],"version-history":[{"count":0,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/2910\/revisions"}],"wp:attachment":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/media?parent=2910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/categories?post=2910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/tags?post=2910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}