{"id":2911,"date":"2020-03-05T00:00:00","date_gmt":"2020-03-05T00:00:00","guid":{"rendered":"https:\/\/toffolettodeluca.it\/\/newsflash-emergenza-coronavirus-update\/"},"modified":"2020-03-05T00:00:00","modified_gmt":"2020-03-05T00:00:00","slug":"newsflash-emergenza-coronavirus-update","status":"publish","type":"post","link":"https:\/\/toffolettodeluca.it\/en\/newsflash-emergenza-coronavirus-update\/","title":{"rendered":"NEWSFLASH: Emergenza Coronavirus &#8211; Update"},"content":{"rendered":"<p>Si sono moltiplicati negli ultimi giorni gli interventi in relazione all\u2019emergenza epidemiologica da COVID-19.<\/p>\n<p>Ecco le novit\u00e0 ad oggi.<\/p>\n<h2><span style=color: #FF0000;\">Misure generali \u00a0<\/span><\/h2>\n<p>Il <a href=\"https:\/\/www.gazzettaufficiale.it\/eli\/id\/2020\/03\/01\/20A01381\/sg\">DPCM del 1 marzo 2020<\/a> ha sostituito i precedenti provvedimenti del 23 e del 25 febbraio, unificando e riordinando le misure di contenimento e gestione dell\u2019emergenza epidemiologica da COVID-19. Un ulteriore <a href=\"https:\/\/www.gazzettaufficiale.it\/atto\/serie_generale\/caricaDettaglioAtto\/originario?atto.dataPubblicazioneGazzetta=2020-03-04&amp;atto.codiceRedazionale=20A01475&amp;elenco30giorni=false\">DPCM del 4 marzo 2020<\/a> ha introdotto modifiche e integrazioni.<\/p>\n<p>L\u2019Italia risulta oggi divisa, ai fini delle differenti misure da adottare, in tre parti: gli undici Comuni gi\u00e0 costituenti la cd. zona rossa; tre regioni (Lombardia, Veneto ed Emilia Romagna) oltre ad alcune province (Pesaro Urbino, Savona, Bergamo, Lodi, Piacenza, Cremona) che formano ora la cd. zona gialla; il resto del territorio nazionale.<\/p>\n<p>La novit\u00e0 pi\u00f9 importante rispetto ai decreti precedenti \u00e8 la possibilit\u00e0 per il datore di lavoro di attuare lo <i>smart working<\/i> in forma semplificata (cio\u00e8 senza accordo individuale e con informazione sui rischi \u201cstandard\u201d a mezzo email) in tutta Italia sino al 31 luglio 2020 (il cd. periodo di emergenza).<\/p>\n<p>Per quanto riguarda la comunicazione obbligatoria dell\u2019attivazione dello <i>smart working<\/i> sul portale <a href=\"https:\/\/servizi.lavoro.gov.it\/ModalitaSemplificataComunicazioneSmartWorking\/\">Cliclavoro<\/a>, \u00e8 stata implementata dal 4 marzo 2020 una speciale procedura semplificata che consente, per il periodo di emergenza, di effettuare la comunicazione con modalit\u00e0 massiva e non per singolo dipendente.<\/p>\n<p>Ecco le altre principali disposizioni che interessano i rapporti di lavoro:<\/p>\n<h3><span style=\"color: #FF0000;\">ZONA ROSSA<\/span><\/h3>\n<p>(<i>Comuni di Bertonico, Casalpusterlengo, Castelgerundo, Castiglione d\u2019Adda, Codogno, Fombio, Maleo, San Fiorano, Somaglia, Terranova dei Passerini, V\u00f2<\/i>)<\/p>\n<p><u>Fino all\u20198 marzo 2020<\/u><\/p>\n<ul>\n<li>Sospensione delle attivit\u00e0 lavorative per tutte le imprese, tranne quelle che erogano servizi essenziali e di pubblica utilit\u00e0<\/li>\n<li>Interdizione al lavoro per chi risiede o ha domicilio nella zona, anche se l\u2019impresa ha sede fuori di essa<\/li>\n<\/ul>\n<p><b>Che cosa pu\u00f2 fare il datore di lavoro?<\/b><\/p>\n<ul>\n<li>disporre lo <i>smartworking<\/i> in forma \u201csemplificata\u201d<\/li>\n<li>In alternativa, sospendere il rapporto di lavoro per impossibilit\u00e0 sopravvenuta della prestazione, con il conseguente venire meno dell\u2019obbligo retributivo. E\u2019 possibile utilizzare gli istituti contrattuali individuali quali ferie e permessi. Possono intervenire la Cassa integrazione ordinaria, l\u2019assegno ordinario o la Cassa integrazione in deroga alle condizioni indicate nel DL 2 marzo 2020 n. 9 (vedi <i>infra<\/i>).<\/li>\n<\/ul>\n<h3><span style=\"color: #FF0000;\">ZONA GIALLA<\/span><\/h3>\n<p>(<i>Regioni: Lombardia, Veneto, Emilia Romagna; Province: Pesaro Urbino, Savona, Bergamo, Lodi, Piacenza, Cremona<\/i>)<\/p>\n<p><u>Fino all\u20198 marzo 2020<\/u><\/p>\n<ul>\n<li>Apertura di musei, luoghi culturali e esercizi commerciali a condizione che siano attuate misure di fruizione contingentata o comunque tali da evitare assembramenti<\/li>\n<li>Attivit\u00e0 di ristorazione per i soli posti a sedere<\/li>\n<li>Adozione in via privilegiata, nello svolgimento di incontri o riunioni, di modalit\u00e0 di collegamento da remoto<\/li>\n<li>Nelle province elencate chiusura al pubblico nelle giornate di sabato e domenica degli esercizi commerciali presenti all\u2019interno dei centri commerciali, tranne farmacie e para farmacie e punti vendita di generi alimentari<\/li>\n<li>In Lombardia e in provincia di Piacenza sospensione delle attivit\u00e0 di palestre, piscine, centri benessere e termali<\/li>\n<\/ul>\n<p><b>Che cosa pu\u00f2 fare il datore di lavoro?<\/b><\/p>\n<ul>\n<li>disporre lo <i>smartworking<\/i> in forma \u201csemplificata\u201d<\/li>\n<li>In alternativa, nelle attivit\u00e0 chiuse al pubblico o ivi comprese, dove vi \u00e8 solo la sospensione dell\u2019attivit\u00e0 didattica pu\u00f2 essere svolta attivit\u00e0 lavorativa \u201cinterna\u201d (ad esempio, scuole).<\/li>\n<li>E\u2019 possibile utilizzare gli istituti contrattuali individuali quali ferie e permessi. Possono intervenire la Cassa integrazione ordinaria, l\u2019assegno ordinario o la Cassa integrazione in deroga alle condizioni\u00a0<\/li>\n<\/ul>\n<p>indicate nel DL 2 marzo 2020 n. 9 (vedi <i>infra<\/i>).<\/p>\n<h3><span style=\"color: #FF0000;\">TUTTO IL TERRITORIO NAZIONALE<\/span><\/h3>\n<ul>\n<li>Sospensione di tutte le attivit\u00e0 didattiche tranne quelle a distanza fino al 15 marzo 2020<\/li>\n<li>Sospensione e\/o differimento di ogni attivit\u00e0 convegnistica o congressuale fino al 3 aprile 2020<\/li>\n<li>Sospensione di manifestazioni ed eventi che comportano affollamento di persone, di eventi e competizioni sportive tranne quelli a porte chiuse o senza la presenza di pubblico fino al 3 aprile 2020<\/li>\n<\/ul>\n<p><b>Che cosa pu\u00f2 fare il datore di lavoro?<\/b><\/p>\n<ul>\n<li>Disporre lo <i>smartworking<\/i> in forma \u201csemplificata\u201d sino al 31 luglio 2020\u00a0<\/li>\n<li>Ricorrere agli ammortizzatori sociali ordinari (ove ve ne siano i requisiti)<\/li>\n<li>Ridurre per quanto possibile le occasioni di contatto e di affollamento<\/li>\n<li>Aggiornare il Documento di Valutazione dei Rischi<\/li>\n<li>Adottare misure igieniche di prevenzione generale del contagio, informare e aggiornare i dipendenti, mettere a disposizione soluzioni disinfettanti.<\/li>\n<\/ul>\n<h2><span style=\"color: #FF0000;\">Ammortizzatori sociali\u00a0<\/span><\/h2>\n<p>Il <a href=\"https:\/\/www.gazzettaufficiale.it\/eli\/id\/2020\/03\/02\/20G00026\/sg\">Decreto Legge n. 9 del 2 marzo 2020<\/a> ha previsto disposizioni volte a semplificare, ovvero a consentire in deroga alle norme ordinarie, l\u2019accesso agli ammortizzatori sociali. Per ciascuna misura, sono stanziati limiti massimi di spesa.<\/p>\n<h3><span style=\"color: #FF0000;\">ZONA ROSSA<\/span><\/h3>\n<ul>\n<li>I datori di lavoro che, avendone i requisiti, presentino domanda di concessione del trattamento ordinario di integrazione salariale o di accesso all\u2019assegno ordinario, per sospensione o riduzione dell\u2019attivit\u00e0 lavorativa, sono dispensati dalla procedura di informazione e consultazione sindacale. La disposizione si applica anche ai datori che abbiano unit\u00e0 produttive fuori dalla zona rossa relativamente a lavoratori domiciliati o residenti in questi luoghi e impossibilitati a rendere la prestazione lavorativa. Il periodo di sospensione, che non pu\u00f2 essere superiore a tre mesi, non viene conteggiato ai fini della durata massima complessiva dei trattamenti di integrazione salariale.\u00a0<\/li>\n<li>E\u2019 possibile chiedere l\u2019interruzione della CIGS gi\u00e0 in corso al fine di fruire del trattamento di CIGO.\u00a0<\/li>\n<li>E\u2019 previsto l\u2019intervento della Cassa integrazione in deroga<b>,<\/b> per le imprese escluse dal campo di applicazione delle tutele ordinarie in materia di sospensione e riduzione di orario. La domanda deve essere presentata alla Regione. Il periodo di sospensione dal lavoro non pu\u00f2 superare i tre mesi, e il trattamento \u00e8 concesso esclusivamente con pagamento diretto della prestazione da parte dell\u2019INPS.<\/li>\n<\/ul>\n<h3><span style=\"color: #FF0000;\">LOMBARDIA, VENETO ED EMILIA-ROMAGNA<\/span><\/h3>\n<ul>\n<li>per i datori di lavoro, esclusi dalle tutele ordinarie, con unit\u00e0 produttive in Lombardia, Veneto ed Emilia Romagna (ma non nei Comuni in zona rossa), o con unit\u00e0 produttive al di fuori di dette regioni limitatamente ai lavoratori residenti o domiciliati nelle predette regioni, \u00e8 possibile ricorrere alla cassa integrazione in deroga per un periodo massimo di un mese, a condizione che sussista una situazione di \u201caccertato pregiudizio\u201d, conseguente alle ordinanze emanate dal Ministero della Salute nell\u2019ambito dei provvedimenti volti a contenere la diffusione del virus CODIV-19, e previo accordo sindacale con le organizzazioni sindacali comparativamente pi\u00f9 rappresentative. La domanda va presentata alle Regioni.<\/li>\n<\/ul>\n<h2><span style=\"color: #FF0000;\">Privacy\u00a0<\/span><\/h2>\n<p>Con una <a href=\"https:\/\/www.garanteprivacy.it\/web\/guest\/home\/docweb\/-\/docweb-display\/docweb\/9282117\">nota del 2 marzo 2020 il Garante della Privacy <\/a>\u00e8 intervenuto negando la possibilit\u00e0 per i datori di lavoro di procedere ad indagini autonome (anche tramite semplici questionari) nei confronti dei propri dipendenti in ordine alla presenza o meno di sintomi influenzali, agli spostamenti effettuati e in generale a vicende relative alla sfera privata. Il Garante ha chiarito che la finalit\u00e0 di prevenzione e diffusione del Coronavirus deve essere perseguita dai soggetti che istituzionalmente esercitano queste funzioni in modo qualificato. Resta fermo l\u2019obbligo del lavoratore di segnalare al datore di lavoro qualsiasi situazione di pericolo per la salute e la sicurezza sui luoghi di lavoro. Il datore di lavoro pu\u00f2 invitare i propri dipendenti a segnalare la provenienza da un\u2019area a rischio.<\/p>\n<div class=\"boxout\">\n<p class=\"lead\"><span style=\"color: #FF0000;\">Chi posso contattare per saperne di pi\u00f9?<\/span><\/p>\n<p>Per supportare le aziende, abbiamo costituito un team specializzato e dedicato a questa emergenza, coordinato dai nostri partner Aldo Bottini e Lea Rossi, ai quali potete rivolgervi per ogni necessit\u00e0 (<a href=\"mailto:sab@toffolettodeluca.it\">sab@toffolettodeluca.it<\/a>)<\/p>\n<\/p><\/div>\n<p>&#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si sono moltiplicati negli ultimi giorni gli interventi in relazione all\u2019emergenza epidemiologica da COVID-19. Ecco le novit\u00e0 ad oggi.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[21],"tags":[145],"class_list":["post-2911","post","type-post","status-publish","format-standard","hentry","category-newsflash-insight","tag-coronavirus-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NEWSFLASH: Emergenza Coronavirus - Update - Toffoletto De Luca Tamajo e Soci<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toffolettodeluca.it\/en\/newsflash-emergenza-coronavirus-update\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NEWSFLASH: Emergenza Coronavirus - Update - Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"og:description\" content=\"Si sono moltiplicati negli ultimi giorni gli interventi in relazione all\u2019emergenza epidemiologica da COVID-19. Ecco le novit\u00e0 ad oggi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toffolettodeluca.it\/en\/newsflash-emergenza-coronavirus-update\/\" \/>\n<meta property=\"og:site_name\" content=\"Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-05T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-emergenza-coronavirus-update\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-emergenza-coronavirus-update\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\"},\"headline\":\"NEWSFLASH: Emergenza Coronavirus &#8211; Update\",\"datePublished\":\"2020-03-05T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-emergenza-coronavirus-update\\\/\"},\"wordCount\":25,\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"keywords\":[\"Coronavirus\"],\"articleSection\":[\"Newsflash &amp; Insights\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-emergenza-coronavirus-update\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-emergenza-coronavirus-update\\\/\",\"name\":\"NEWSFLASH: Emergenza Coronavirus - Update - Toffoletto De Luca Tamajo e Soci\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\"},\"datePublished\":\"2020-03-05T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-emergenza-coronavirus-update\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-emergenza-coronavirus-update\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-emergenza-coronavirus-update\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/studio-diritto-del-lavoro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Learn & Connect\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/learn-connect\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Newsflash &amp; Insights\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/category\\\/newsflash-insight\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"NEWSFLASH: Emergenza Coronavirus &#8211; Update\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"contentUrl\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"caption\":\"Toffoletto De Luca Tamajo e Soci\"},\"image\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NEWSFLASH: Emergenza Coronavirus - Update - Toffoletto De Luca Tamajo e Soci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toffolettodeluca.it\/en\/newsflash-emergenza-coronavirus-update\/","og_locale":"en_US","og_type":"article","og_title":"NEWSFLASH: Emergenza Coronavirus - Update - Toffoletto De Luca Tamajo e Soci","og_description":"Si sono moltiplicati negli ultimi giorni gli interventi in relazione all\u2019emergenza epidemiologica da COVID-19. Ecco le novit\u00e0 ad oggi.","og_url":"https:\/\/toffolettodeluca.it\/en\/newsflash-emergenza-coronavirus-update\/","og_site_name":"Toffoletto De Luca Tamajo e Soci","article_published_time":"2020-03-05T00:00:00+00:00","author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/toffolettodeluca.it\/en\/newsflash-emergenza-coronavirus-update\/#article","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/newsflash-emergenza-coronavirus-update\/"},"author":{"name":"Redazione","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559"},"headline":"NEWSFLASH: Emergenza Coronavirus &#8211; Update","datePublished":"2020-03-05T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/toffolettodeluca.it\/en\/newsflash-emergenza-coronavirus-update\/"},"wordCount":25,"publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"keywords":["Coronavirus"],"articleSection":["Newsflash &amp; Insights"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/toffolettodeluca.it\/en\/newsflash-emergenza-coronavirus-update\/","url":"https:\/\/toffolettodeluca.it\/en\/newsflash-emergenza-coronavirus-update\/","name":"NEWSFLASH: Emergenza Coronavirus - Update - Toffoletto De Luca Tamajo e Soci","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/#website"},"datePublished":"2020-03-05T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/toffolettodeluca.it\/en\/newsflash-emergenza-coronavirus-update\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toffolettodeluca.it\/en\/newsflash-emergenza-coronavirus-update\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/toffolettodeluca.it\/en\/newsflash-emergenza-coronavirus-update\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toffolettodeluca.it\/en\/studio-diritto-del-lavoro\/"},{"@type":"ListItem","position":2,"name":"Learn & Connect","item":"https:\/\/toffolettodeluca.it\/en\/learn-connect\/"},{"@type":"ListItem","position":3,"name":"Newsflash &amp; Insights","item":"https:\/\/toffolettodeluca.it\/en\/category\/newsflash-insight\/"},{"@type":"ListItem","position":4,"name":"NEWSFLASH: Emergenza Coronavirus &#8211; Update"}]},{"@type":"WebSite","@id":"https:\/\/toffolettodeluca.it\/en\/#website","url":"https:\/\/toffolettodeluca.it\/en\/","name":"Toffoletto De Luca Tamajo e Soci","description":"","publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toffolettodeluca.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/toffolettodeluca.it\/en\/#organization","name":"Toffoletto De Luca Tamajo e Soci","url":"https:\/\/toffolettodeluca.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","contentUrl":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","caption":"Toffoletto De Luca Tamajo e Soci"},"image":{"@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/toffolettodeluca.it\/en\/author\/redazione\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/2911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/comments?post=2911"}],"version-history":[{"count":0,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/2911\/revisions"}],"wp:attachment":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/media?parent=2911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/categories?post=2911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/tags?post=2911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}