{"id":2918,"date":"2020-02-24T00:00:00","date_gmt":"2020-02-24T00:00:00","guid":{"rendered":"https:\/\/toffolettodeluca.it\/\/newsflash-il-rinnovo-del-ccnl-credito\/"},"modified":"2020-02-24T00:00:00","modified_gmt":"2020-02-24T00:00:00","slug":"newsflash-il-rinnovo-del-ccnl-credito","status":"publish","type":"post","link":"https:\/\/toffolettodeluca.it\/en\/newsflash-il-rinnovo-del-ccnl-credito\/","title":{"rendered":"NEWSFLASH: Il rinnovo del CCNL Credito"},"content":{"rendered":"<p>Il 19 dicembre 2019 ABI e FABI, Cgil, Cisl, Uil e Unit\u00e0 Sindacale Falcri, Silcea e Sinfub, hanno firmato un\u2019ipotesi di intesa che rinnova il CCNL per i quadri direttivi e il personale delle imprese creditizie, finanziarie e strumentali del 31 marzo 2015.<\/p>\n<p>Di seguito una breve sintesi delle principali novit\u00e0 del contratto che si applicher\u00e0 fino al 31 dicembre 2022.<\/p>\n<ol>\n<li>Aumentati i tempi della procedura per il coinvolgimento delle rappresentanze sindacali in caso di concessione di un servizio in appalto e inserita una \u201craccomandazione delle parti\u201d affinch\u00e9, all\u2019atto della stipulazione del rinnovo di un contratto di appalto con diversa societ\u00e0 appaltatrice, le imprese committenti promuovano l\u2019inserimento nel contratto di una \u201cclausola sociale\u201d a garanzia dei livelli occupazionali del personale impiegato da almeno 6 mesi nell\u2019appalto precedente (Articolo 19 CCNL).<\/li>\n<li>Aumentato a 3.500 euro l\u2019importo annuo erogabile dal Fondo per l\u2019occupazione in caso di assunzione a tempo indeterminato di lavoratori nelle Regioni del Mezzogiorno (art. 32 CCNL).<\/li>\n<li>Prevista la facolt\u00e0 per i lavoratori con figlio convivente portatore di handicap di trasformare il rapporto di lavoro da tempo pieno a tempo parziale e, su loro richiesta, di ritornare a tempo pieno. In tutti i casi di richiesta di trasformazione del rapporto da full time a part time viene riconosciuta la priorit\u00e0 in caso di patologie gravi riguardanti i familiari del dipendente. Viene poi soppresso il limite del 20% del personale a tempo a pieno quale soglia per la sottoscrizione di contratti a tempo parziale (Articolo 35 CCNL).<\/li>\n<li>Introdotte nuove disposizioni restrittive della normativa sul lavoro agile. La prestazione lavorativa &#8211; svolta in altra sede aziendale, nel proprio domicilio o in altro luogo previamente autorizzato &#8211; sar\u00e0 effettuata entro i limiti di durata dell\u2019orario giornaliero e settimanale e non potr\u00e0 superare il limite massimo di 10 giornate mensili, salvo diversi limiti stabiliti dagli accordi aziendali o di gruppo.<\/li>\n<li>Aggiunto un comma all\u2019articolo 41 CCNL in materia di lavoratori sottoposti a procedimento penale, per cui, su richiesta del lavoratore allontanato dal servizio per motivi cautelari a seguito di procedimento penale per fatti estranei all\u2019attivit\u00e0 lavorativa, l\u2019impresa \u00e8 tenuta ad effettuare un colloquio ed udire la posizione del dipendente.<\/li>\n<li>Inserito un comma all\u2019articolo 42 CCNL con cui si estendono garanzie e tutele nei confronti dei dipendenti sottoposti a procedimento penale e civile per fatti commessi nell\u2019esercizio delle funzioni.<\/li>\n<li>Introdotte importanti novit\u00e0 in materia di procedimento disciplinare. Tra le altre si segnala l\u2019estensione da 5 a 7 giorni del termine entro il quale il lavoratore &#8211; a seguito della contestazione disciplinare &#8211; deve fornire le proprie giustificazioni. Inoltre, entro tale termine, il dipendente pu\u00f2 chiedere per iscritto l\u2019accesso a specifici documenti necessari ad un compiuto esercizio del diritto di difesa. La richiesta sospende il decorso del termine. (Articolo 44 CCNL).<\/li>\n<li>Abolito il c.d. \u201csalario d\u2019ingresso\u201d per i neoassunti (ex art. 46 CCNL) e ridotto a 18 mesi il termine per la parificazione di inquadramento degli apprendisti al livello retributivo spettante (art. 33 CCNL).\u00a0<\/li>\n<li>In via transitoria, ai soggetti destinatari di livello retributivo di inserimento professionale, ivi inclusi gli apprendisti, viene riconosciuto un importo denominato \u201cintegrazione ex F.O.C. 2019\u201d dalla data di entrata in vigore dell\u2019accordo e sino al 4\u00b0 anno di anzianit\u00e0 aziendale (Articolo 45 CCNL).<\/li>\n<li>Si segnalano inoltre le seguenti modifiche:\u00a0<\/li>\n<\/ol>\n<ul>\n<li>estensione a 7 giorni del congedo di paternit\u00e0 (in linea con quanto stabilito dalla Legge di Bilancio 2020) e previsione di ulteriori permessi in caso di ricovero del figlio o del genitore (Articolo 59 CCNL);<\/li>\n<li>flessibilit\u00e0 di orario in entrata e in uscita, permessi ed aspettativa ad hoc per dipendenti affetti da patologie oncologiche (Articolo 58 CCNL);<\/li>\n<li>adozione di un\u2019organizzazione \u201cdisability friendly\u201d che prevede l\u2019eliminazione di barriere architettoniche in caso di ristrutturazioni e l\u2019individuazione di un disability manager (Articolo 69 CCNL);<\/li>\n<li>integrale recepimento delle disposizioni di cui alla Legge Cirinn\u00e0 in tema di unioni civili tra persone dello stesso sesso (Art. 69 CCNL);<\/li>\n<li>conciliazione vita\/lavoro attraverso l\u2019istituzione della \u201cBanca del tempo\u201d.<\/li>\n<\/ul>\n<ol start=11\">\n<li>Innalzati i limiti di et\u00e0 anagrafica per cui diventa necessario il consenso del lavoratore in caso di trasferimento (Articoli 88 e 111 CCNL).<\/li>\n<li>Modificata la classificazione del personale prevedendo 9 livelli (rispetto ai 13 del precedente contratto).\u00a0<\/li>\n<li>Previsto un aumento retributivo di 190 euro che verr\u00e0 corrisposto in tre tranches: 1\u00b0 gennaio 2020, 1\u00b0 gennaio 2021 e 1\u00b0 dicembre 2022.\u00a0<\/li>\n<\/ol>\n<div class=\"boxout\">\n<h3><span style=\"color: #FF0000;\"><b>Chi posso contattare per saperne di pi\u00f9?<\/b><\/span><\/h3>\n<p>Restiamo a disposizione per eventuali ulteriori approfondimenti. Per maggiori informazioni o un colloquio informale,\u00a0<a href=\"mailto:info@toffolettodeluca.it\">contattaci<\/a><\/p>\n<\/p><\/div>\n<p>&#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 19 dicembre 2019 ABI e FABI, Cgil, Cisl, Uil e Unit\u00e0 Sindacale Falcri, Silcea e Sinfub, hanno firmato un\u2019ipotesi di intesa che rinnova il CCNL per i quadri direttivi e il personale delle imprese creditizie, finanziarie e strumentali del 31 marzo 2015. Di seguito una breve sintesi delle principali novit\u00e0 del contratto che si &#8230; <a title=\"NEWSFLASH: Il rinnovo del CCNL Credito\" class=\"read-more\" href=\"https:\/\/toffolettodeluca.it\/en\/newsflash-il-rinnovo-del-ccnl-credito\/\" aria-label=\"Read more about NEWSFLASH: Il rinnovo del CCNL Credito\">Read more<\/a><\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[21],"tags":[],"class_list":["post-2918","post","type-post","status-publish","format-standard","hentry","category-newsflash-insight"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NEWSFLASH: Il rinnovo del CCNL Credito - Toffoletto De Luca Tamajo e Soci<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toffolettodeluca.it\/en\/newsflash-il-rinnovo-del-ccnl-credito\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NEWSFLASH: Il rinnovo del CCNL Credito - Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"og:description\" content=\"Il 19 dicembre 2019 ABI e FABI, Cgil, Cisl, Uil e Unit\u00e0 Sindacale Falcri, Silcea e Sinfub, hanno firmato un\u2019ipotesi di intesa che rinnova il CCNL per i quadri direttivi e il personale delle imprese creditizie, finanziarie e strumentali del 31 marzo 2015. Di seguito una breve sintesi delle principali novit\u00e0 del contratto che si ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toffolettodeluca.it\/en\/newsflash-il-rinnovo-del-ccnl-credito\/\" \/>\n<meta property=\"og:site_name\" content=\"Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-24T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-il-rinnovo-del-ccnl-credito\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-il-rinnovo-del-ccnl-credito\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\"},\"headline\":\"NEWSFLASH: Il rinnovo del CCNL Credito\",\"datePublished\":\"2020-02-24T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-il-rinnovo-del-ccnl-credito\\\/\"},\"wordCount\":647,\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"articleSection\":[\"Newsflash &amp; Insights\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-il-rinnovo-del-ccnl-credito\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-il-rinnovo-del-ccnl-credito\\\/\",\"name\":\"NEWSFLASH: Il rinnovo del CCNL Credito - Toffoletto De Luca Tamajo e Soci\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\"},\"datePublished\":\"2020-02-24T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-il-rinnovo-del-ccnl-credito\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-il-rinnovo-del-ccnl-credito\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-il-rinnovo-del-ccnl-credito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/studio-diritto-del-lavoro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Learn & Connect\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/learn-connect\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Newsflash &amp; Insights\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/category\\\/newsflash-insight\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"NEWSFLASH: Il rinnovo del CCNL Credito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"contentUrl\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"caption\":\"Toffoletto De Luca Tamajo e Soci\"},\"image\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NEWSFLASH: Il rinnovo del CCNL Credito - Toffoletto De Luca Tamajo e Soci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toffolettodeluca.it\/en\/newsflash-il-rinnovo-del-ccnl-credito\/","og_locale":"en_US","og_type":"article","og_title":"NEWSFLASH: Il rinnovo del CCNL Credito - Toffoletto De Luca Tamajo e Soci","og_description":"Il 19 dicembre 2019 ABI e FABI, Cgil, Cisl, Uil e Unit\u00e0 Sindacale Falcri, Silcea e Sinfub, hanno firmato un\u2019ipotesi di intesa che rinnova il CCNL per i quadri direttivi e il personale delle imprese creditizie, finanziarie e strumentali del 31 marzo 2015. Di seguito una breve sintesi delle principali novit\u00e0 del contratto che si ... Read more","og_url":"https:\/\/toffolettodeluca.it\/en\/newsflash-il-rinnovo-del-ccnl-credito\/","og_site_name":"Toffoletto De Luca Tamajo e Soci","article_published_time":"2020-02-24T00:00:00+00:00","author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redazione","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/toffolettodeluca.it\/en\/newsflash-il-rinnovo-del-ccnl-credito\/#article","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/newsflash-il-rinnovo-del-ccnl-credito\/"},"author":{"name":"Redazione","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559"},"headline":"NEWSFLASH: Il rinnovo del CCNL Credito","datePublished":"2020-02-24T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/toffolettodeluca.it\/en\/newsflash-il-rinnovo-del-ccnl-credito\/"},"wordCount":647,"publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"articleSection":["Newsflash &amp; Insights"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/toffolettodeluca.it\/en\/newsflash-il-rinnovo-del-ccnl-credito\/","url":"https:\/\/toffolettodeluca.it\/en\/newsflash-il-rinnovo-del-ccnl-credito\/","name":"NEWSFLASH: Il rinnovo del CCNL Credito - Toffoletto De Luca Tamajo e Soci","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/#website"},"datePublished":"2020-02-24T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/toffolettodeluca.it\/en\/newsflash-il-rinnovo-del-ccnl-credito\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toffolettodeluca.it\/en\/newsflash-il-rinnovo-del-ccnl-credito\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/toffolettodeluca.it\/en\/newsflash-il-rinnovo-del-ccnl-credito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toffolettodeluca.it\/en\/studio-diritto-del-lavoro\/"},{"@type":"ListItem","position":2,"name":"Learn & Connect","item":"https:\/\/toffolettodeluca.it\/en\/learn-connect\/"},{"@type":"ListItem","position":3,"name":"Newsflash &amp; Insights","item":"https:\/\/toffolettodeluca.it\/en\/category\/newsflash-insight\/"},{"@type":"ListItem","position":4,"name":"NEWSFLASH: Il rinnovo del CCNL Credito"}]},{"@type":"WebSite","@id":"https:\/\/toffolettodeluca.it\/en\/#website","url":"https:\/\/toffolettodeluca.it\/en\/","name":"Toffoletto De Luca Tamajo e Soci","description":"","publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toffolettodeluca.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/toffolettodeluca.it\/en\/#organization","name":"Toffoletto De Luca Tamajo e Soci","url":"https:\/\/toffolettodeluca.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","contentUrl":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","caption":"Toffoletto De Luca Tamajo e Soci"},"image":{"@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/toffolettodeluca.it\/en\/author\/redazione\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/2918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/comments?post=2918"}],"version-history":[{"count":0,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/2918\/revisions"}],"wp:attachment":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/media?parent=2918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/categories?post=2918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/tags?post=2918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}