{"id":2919,"date":"2020-02-28T00:00:00","date_gmt":"2020-02-28T00:00:00","guid":{"rendered":"https:\/\/toffolettodeluca.it\/\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\/"},"modified":"2020-02-28T00:00:00","modified_gmt":"2020-02-28T00:00:00","slug":"smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19","status":"publish","type":"post","link":"https:\/\/toffolettodeluca.it\/en\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\/","title":{"rendered":"Smart working: tra incremento di produttivit\u00e0, conciliazione dei tempi di vita\/lavoro e prevenzione dei rischi di contagio da COVID-19"},"content":{"rendered":"<p>Di:\u00a0<a href=\"https:\/\/toffolettodeluca.it\/it\/avvocati-diritto-del-lavoro\/redazione-insight\/\">Avv. Wanda Falco<\/a><\/p>\n<p><span style=\"color: #FF0000;\"><em>*aggiornato al 2 marzo 2020\u00a0<\/em><\/span><\/p>\n<p>I pi\u00f9 recenti fatti di cronaca legati\u00a0<strong>all\u2019emergenza Coronavirus<\/strong>\u00a0hanno messo in luce ulteriormente l\u2019istituto dello\u00a0<strong><em>smart working<\/em><\/strong>\u00a0quale strumento individuato dal governo per\u00a0<strong>contenere il rischio di contagio<\/strong>\u00a0e per consentire alle aziende di tutelare la\u00a0<strong>salute e la sicurezza dei propri dipendenti<\/strong>.<\/p>\n<p>Non si tratta di una tipologia contrattuale, ma di una\u00a0<strong>diversa modalit\u00e0 di svolgimento della prestazione lavorativa<\/strong>\u00a0introdotta dalla L. n. 81\/2017 e finalizzata a\u00a0<strong>incrementare la produttivit\u00e0<\/strong>\u00a0e ad agevolare la\u00a0<strong>conciliazione dei tempi di vita e di lavoro<\/strong>.\u00a0<\/p>\n<p>Vediamo nel dettaglio in cosa consiste e cosa prevedono i recenti provvedimenti adottati per far fronte all\u2019emergenza\u00a0<strong>Coronavirus\u00a0<\/strong>nelle aziende.<\/p>\n<h2><span style=\"color: #FF0000;\"><em>Smart working<\/em>: caratteristiche e contenuto dell\u2019accordo<\/span><\/h2>\n<p>Secondo l\u2019art. 18 della L. n. 81\/2017 questa nuova modalit\u00e0 di esecuzione del rapporto di lavoro subordinato \u00e8 stabilita \u201c<strong>mediante accordo tra le parti<\/strong>, anche con forme di organizzazione\u00a0<strong>per fasi, cicli e obiettivi<\/strong>\u00a0e senza precisi vincoli di orario o di luogo di lavoro, con il possibile utilizzo di\u00a0<strong>strumenti tecnologici<\/strong>\u00a0per lo svolgimento dell\u2019attivit\u00e0 lavorativa. La prestazione viene eseguita,\u00a0<strong>in parte all\u2019interno di locali aziendali e in parte all\u2019esterno\u00a0<\/strong><strong>senza una postazione fissa<\/strong>, entro i soli limiti di durata massima dell\u2019orario di lavoro giornaliero e settimanale, derivanti dalla legge e dalla contrattazione collettiva\u201d.<\/p>\n<p>Le caratteristiche del lavoro agile, dunque, sono:<\/p>\n<ul>\n<li>l\u2019<strong>assenza di vincoli orari o spaziali;<\/strong><\/li>\n<li>l\u2019<strong>accordo<\/strong>\u00a0tra dipendente e datore di lavoro;<\/li>\n<li>il\u00a0<strong>possibile utilizzo di strumentazioni che consentano di lavorare da remoto<\/strong>\u00a0(come ad esempio:\u00a0<em>pc portatili, tablet e smartphone<\/em>).<\/li>\n<\/ul>\n<p>In sostanza, la prestazione lavorativa pu\u00f2 essere svolta all\u2019esterno dell\u2019azienda per una parte del giorno, della settimana o del mese e pu\u00f2 essere resa anche in pi\u00f9 luoghi scelti al fine di una migliore conciliazione dei tempi di vita e di lavoro.\u00a0<\/p>\n<p>In ci\u00f2 il lavoro agile si differenzia dal\u00a0<strong>telelavoro<\/strong>\u00a0(Accordo interconfederale del 9 giugno 2004 cui fanno riferimento i CCNL di diversi settori) che, invece, impone che l\u2019attivit\u00e0 sia svolta completamente fuori dei locali dell\u2019impresa e da una postazione fissa che in genere coincide con l\u2019abitazione del lavoratore.<\/p>\n<p>Gli artt. 19 e 21, in particolare, delineano il contenuto dell\u2019accordo di smart working stabilendo che sia stipulato per iscritto ai fini della regolarit\u00e0 amministrativa e della prova, e che disciplini:<\/p>\n<ol>\n<li>le\u00a0<strong>modalit\u00e0 di esecuzione della prestazione<\/strong>\u00a0resa fuori dai locali aziendali, anche con riferimento alle forme di esercizio del\u00a0<strong>potere direttivo<\/strong>\u00a0del datore di lavoro e agli strumenti utilizzati dal lavoratore;<\/li>\n<li>i\u00a0<strong>tempi e i luoghi di riposo<\/strong>\u00a0del lavoratore e le misure tecniche e organizzative necessarie per assicurare la\u00a0<strong>disconnessione del dipendente<\/strong>\u00a0dalle strumentazioni tecnologiche di lavoro;<\/li>\n<li>\u00a0le modalit\u00e0 di esercizio del\u00a0<strong>potere di controllo<\/strong>\u00a0del datore di lavoro sulla prestazione resa dal lavoratore all\u2019esterno dei locali aziendali;<\/li>\n<li>le condotte, connesse all\u2019esecuzione della prestazione al di fuori dei locali aziendali, che danno luogo all\u2019applicazione di\u00a0<strong>sanzioni disciplinari.<\/strong><\/li>\n<\/ol>\n<p>Tale accordo pu\u00f2 essere a termine o a tempo indeterminato e pu\u00f2 essere concluso sia per rapporti gi\u00e0 in corso, con conseguente modifica delle originarie condizioni di lavoro, sia contestualmente alla stipula del contratto di lavoro.\u00a0<\/p>\n<h2><span style=\"color: #FF0000;\">Le tutele per i \u201clavoratori agili\u201d<\/span><\/h2>\n<p>Qualunque sia il contenuto dell\u2019accordo, restano ferme le tutele di fonte legale che consistono:<\/p>\n<ol>\n<li><strong>nella garanzia di un trattamento economico e normativo<\/strong>\u00a0<strong>non inferiore<\/strong>\u00a0a quello complessivamente applicato ai lavoratori che svolgono le medesime mansioni solo all\u2019interno dell\u2019azienda;<\/li>\n<li><strong>nella tutela contro gli infortuni sul lavoro e le malattie professionali<\/strong>\u00a0dipendenti da rischi connessi alle prestazioni rese fuori dall\u2019azienda;<\/li>\n<li><strong>nella tutela in caso di infortunio in itinere;<\/strong><\/li>\n<li><strong>nella tutela della salute e sicurezza<\/strong>\u00a0con l\u2019esplicita imposizione al datore di una informativa scritta sui rischi collegati alla particolare modalit\u00e0 di esecuzione del rapporto (articoli 20 e 22). In particolare, il datore consegna al lavoratore e al rappresentante dei lavoratori per la sicurezza, con cadenza almeno annuale,\u00a0<strong>un\u2019informativa scritta<\/strong>\u00a0nella quale sono individuati i\u00a0<strong>rischi generali e i rischi specifici<\/strong>\u00a0connessi alla particolare modalit\u00e0 di esecuzione del rapporto di lavoro.\u00a0<strong>Il lavoratore, dal canto suo, \u00e8 tenuto a cooperare all\u2019attuazione delle misure di prevenzione<\/strong>\u00a0predisposte dal datore di lavoro per fronteggiare i rischi connessi all\u2019esecuzione della prestazione all\u2019esterno dei locali aziendali.<\/li>\n<\/ol>\n<h2><span style=\"color: #FF0000;\">I vantaggi del lavoro agile<\/span><\/h2>\n<p>Il lavoro agile presenta sicuramente dei vantaggi sia per i lavoratori che per le aziende.\u00a0<\/p>\n<p>In particolare, si segnala la\u00a0<strong>maggiore flessibilit\u00e0<\/strong>\u00a0che permette al lavoratore di bilanciare al meglio i tempi di lavoro con le esigenze della vita privata, risparmiando notevolmente anche sui\u00a0<strong>costi connessi agli spostamenti<\/strong>\u00a0pi\u00f9 o meno lunghi da casa al luogo di lavoro. Dalla flessibilit\u00e0 e dalle migliori condizioni di lavoro discende inevitabilmente un\u00a0<strong>incremento della produttivit\u00e0<\/strong>\u00a0dei lavoratori e una\u00a0<strong>riduzione del tasso di assenteismo<\/strong>, come emerge dai dati dell\u2019Osservatorio Smart Working 2019 del Politecnico di Milano.<\/p>\n<p>A ci\u00f2 si aggiungano i benefici che l\u2019azienda pu\u00f2 trarre dalla\u00a0<strong>riduzione dei costi di gestione\u00a0<\/strong>degli spazi di lavoro in termini di\u00a0<strong>utenze, pulizia e attrezzature.<\/strong><\/p>\n<p>L\u2019art. 18 della L. n. 81\/2017 stabilisce, inoltre, che ai lavoratori agili sono riconosciuti gli\u00a0<strong>incentivi di carattere fiscale e contributivo<\/strong>\u00a0in relazione agli incrementi di produttivit\u00e0 ed efficienza del lavoro subordinato. Risultano, pertanto, applicabili la detassazione dei premi di produzione e la detassazione e decontribuzione delle misure di welfare aziendale.<\/p>\n<h2><span style=\"color: #FF0000;\">Lo\u00a0<em>Smart Working<\/em>\u00a0come misura da adottare in casi di emergenza<\/span><strong>\u00a0<\/strong><\/h2>\n<p>Accanto ai vantaggi appena esaminati, occorre evidenziare che lo\u00a0<em>smart working<\/em>\u00a0si sta rivelando un utilissimo strumento per far fronte\u00a0<strong>all\u2019emergenza Coronavirus.<\/strong><\/p>\n<p>Accanto ai vantaggi appena esaminati, occorre evidenziare che lo\u00a0<em>smart working<\/em>\u00a0si sta rivelando un utilissimo strumento per far fronte\u00a0<strong>all\u2019emergenza Coronavirus.<\/strong><\/p>\n<p>In particolare, si segnala il\u00a0nuovo\u00a0 <a href=\"https:\/\/www.gazzettaufficiale.it\/eli\/id\/2020\/03\/01\/20A01381\/sg\" target=\"_blank\" rel=\"noopener\">Dpcm dell\u20191 marzo 2020 <\/a>  \u00a0attuativo del decreto-legge 23 febbraio 2020, n. 6 recante misure urgenti in materia di contenimento e gestione dell\u2019emergenza epidemiologica da COVID-19.<\/p>\n<p>Il Governo \u00e8 intervenuto per rendere pi\u00f9 immediato il ricorso allo\u00a0<em>smart working<\/em>\u00a0nelle\u00a0<strong>aree considerate a rischio per l\u2019emergenza Coronavirus<\/strong>.<\/p>\n<p>In sostanza, la modalit\u00e0 di lavoro agile \u00e8 applicabile dai datori di lavoro,\u00a0<strong>anche in assenza degli accordi individuali\u00a0<\/strong>previsti dalla L. n. 81\/2017,\u00a0<strong>per tutta la durata dello stato di emergenza<\/strong>(e non pi\u00f9 solo fino al 15 marzo 2020, come previsto dal precedente Dpcm del 25 febbraio).<\/p>\n<p>Pertanto, possono ricorrere\u00a0<strong>senza accordo\u00a0<\/strong>allo\u00a0<em>smart working<\/em>\u00a0<strong>tutti i datori di lavoro<\/strong>\u00a0e non pi\u00f9 solo quelli aventi sede legale o operativa nelle Regioni Emilia Romagna, Friuli Venezia Giulia, Lombardia, Piemonte, Veneto e Liguria o quelli che, pur avendo sede fuori da tali territori, abbiano dipendenti ivi residenti o domiciliati (come previsto dal precedente Dpcm del 25 febbraio).<\/p>\n<p>Resta semplificato l\u2019adempimento\u00a0<strong>all\u2019obbligo di informativa<\/strong>\u00a0sui rischi per la salute e sicurezza del lavoro previsto dall\u2019articolo 22 della L. n. 81\/2017, che pu\u00f2 avvenire in via telematica (es. con una semplice e-mail al dipendente), utilizzando i moduli disponibili sul sito Inail.<\/p>\n<h2><span style=\"color: #FF0000;\">Conclusioni<\/span><\/h2>\n<p>Dalla breve analisi delle caratteristiche dello\u00a0<em>smart working<\/em>\u00a0emergono gli evidenti vantaggi del ricorso al lavoro agile, strumento che oltre a favorire il\u00a0<strong><em>work\/life balance<\/em><\/strong>\u00a0e incrementare la produttivit\u00e0, con conseguente riduzione dell\u2019assenteismo, \u00e8 diventato negli ultimi giorni un alleato per fronteggiare\u00a0<strong>l\u2019emergenza sanitaria di rischio contagio da Coronavirus<\/strong>.<\/p>\n<p> &#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Di:\u00a0Avv. Wanda Falco *aggiornato al 2 marzo 2020\u00a0 I pi\u00f9 recenti fatti di cronaca legati\u00a0all\u2019emergenza Coronavirus\u00a0hanno messo in luce ulteriormente l\u2019istituto dello\u00a0smart working\u00a0quale strumento individuato dal governo per\u00a0contenere il rischio di contagio\u00a0e per consentire alle aziende di tutelare la\u00a0salute e la sicurezza dei propri dipendenti. Non si tratta di una tipologia contrattuale, ma di una\u00a0diversa &#8230; <a title=\"Smart working: tra incremento di produttivit\u00e0, conciliazione dei tempi di vita\/lavoro e prevenzione dei rischi di contagio da COVID-19\" class=\"read-more\" href=\"https:\/\/toffolettodeluca.it\/en\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\/\" aria-label=\"Read more about Smart working: tra incremento di produttivit\u00e0, conciliazione dei tempi di vita\/lavoro e prevenzione dei rischi di contagio da COVID-19\">Read more<\/a><\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[],"tags":[],"class_list":["post-2919","post","type-post","status-publish","format-standard","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Smart working: tra incremento di produttivit\u00e0, conciliazione dei tempi di vita\/lavoro e prevenzione dei rischi di contagio da COVID-19 - Toffoletto De Luca Tamajo e Soci<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toffolettodeluca.it\/en\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Smart working: tra incremento di produttivit\u00e0, conciliazione dei tempi di vita\/lavoro e prevenzione dei rischi di contagio da COVID-19 - Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"og:description\" content=\"Di:\u00a0Avv. Wanda Falco *aggiornato al 2 marzo 2020\u00a0 I pi\u00f9 recenti fatti di cronaca legati\u00a0all\u2019emergenza Coronavirus\u00a0hanno messo in luce ulteriormente l\u2019istituto dello\u00a0smart working\u00a0quale strumento individuato dal governo per\u00a0contenere il rischio di contagio\u00a0e per consentire alle aziende di tutelare la\u00a0salute e la sicurezza dei propri dipendenti. Non si tratta di una tipologia contrattuale, ma di una\u00a0diversa ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toffolettodeluca.it\/en\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-28T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\"},\"headline\":\"Smart working: tra incremento di produttivit\u00e0, conciliazione dei tempi di vita\\\/lavoro e prevenzione dei rischi di contagio da COVID-19\",\"datePublished\":\"2020-02-28T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\\\/\"},\"wordCount\":1197,\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\\\/\",\"name\":\"Smart working: tra incremento di produttivit\u00e0, conciliazione dei tempi di vita\\\/lavoro e prevenzione dei rischi di contagio da COVID-19 - Toffoletto De Luca Tamajo e Soci\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\"},\"datePublished\":\"2020-02-28T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/studio-diritto-del-lavoro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Newsflash &amp; Insights\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/category\\\/newsflash-insight\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Smart working: tra incremento di produttivit\u00e0, conciliazione dei tempi di vita\\\/lavoro e prevenzione dei rischi di contagio da COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"contentUrl\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"caption\":\"Toffoletto De Luca Tamajo e Soci\"},\"image\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Smart working: tra incremento di produttivit\u00e0, conciliazione dei tempi di vita\/lavoro e prevenzione dei rischi di contagio da COVID-19 - Toffoletto De Luca Tamajo e Soci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toffolettodeluca.it\/en\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\/","og_locale":"en_US","og_type":"article","og_title":"Smart working: tra incremento di produttivit\u00e0, conciliazione dei tempi di vita\/lavoro e prevenzione dei rischi di contagio da COVID-19 - Toffoletto De Luca Tamajo e Soci","og_description":"Di:\u00a0Avv. Wanda Falco *aggiornato al 2 marzo 2020\u00a0 I pi\u00f9 recenti fatti di cronaca legati\u00a0all\u2019emergenza Coronavirus\u00a0hanno messo in luce ulteriormente l\u2019istituto dello\u00a0smart working\u00a0quale strumento individuato dal governo per\u00a0contenere il rischio di contagio\u00a0e per consentire alle aziende di tutelare la\u00a0salute e la sicurezza dei propri dipendenti. Non si tratta di una tipologia contrattuale, ma di una\u00a0diversa ... Read more","og_url":"https:\/\/toffolettodeluca.it\/en\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\/","og_site_name":"Toffoletto De Luca Tamajo e Soci","article_published_time":"2020-02-28T00:00:00+00:00","author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redazione","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/toffolettodeluca.it\/en\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\/#article","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\/"},"author":{"name":"Redazione","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559"},"headline":"Smart working: tra incremento di produttivit\u00e0, conciliazione dei tempi di vita\/lavoro e prevenzione dei rischi di contagio da COVID-19","datePublished":"2020-02-28T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/toffolettodeluca.it\/en\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\/"},"wordCount":1197,"publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/toffolettodeluca.it\/en\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\/","url":"https:\/\/toffolettodeluca.it\/en\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\/","name":"Smart working: tra incremento di produttivit\u00e0, conciliazione dei tempi di vita\/lavoro e prevenzione dei rischi di contagio da COVID-19 - Toffoletto De Luca Tamajo e Soci","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/#website"},"datePublished":"2020-02-28T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/toffolettodeluca.it\/en\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toffolettodeluca.it\/en\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/toffolettodeluca.it\/en\/smart-working-tra-incremento-di-produttivita-conciliazione-dei-tempi-di-vita-lavoro-e-prevenzione-dei-rischi-di-contagio-da-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toffolettodeluca.it\/en\/studio-diritto-del-lavoro\/"},{"@type":"ListItem","position":2,"name":"Newsflash &amp; Insights","item":"https:\/\/toffolettodeluca.it\/en\/category\/newsflash-insight\/"},{"@type":"ListItem","position":3,"name":"Smart working: tra incremento di produttivit\u00e0, conciliazione dei tempi di vita\/lavoro e prevenzione dei rischi di contagio da COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/toffolettodeluca.it\/en\/#website","url":"https:\/\/toffolettodeluca.it\/en\/","name":"Toffoletto De Luca Tamajo e Soci","description":"","publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toffolettodeluca.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/toffolettodeluca.it\/en\/#organization","name":"Toffoletto De Luca Tamajo e Soci","url":"https:\/\/toffolettodeluca.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","contentUrl":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","caption":"Toffoletto De Luca Tamajo e Soci"},"image":{"@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/toffolettodeluca.it\/en\/author\/redazione\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/2919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/comments?post=2919"}],"version-history":[{"count":0,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/2919\/revisions"}],"wp:attachment":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/media?parent=2919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/categories?post=2919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/tags?post=2919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}