{"id":2921,"date":"2020-03-20T00:00:00","date_gmt":"2020-03-20T00:00:00","guid":{"rendered":"https:\/\/toffolettodeluca.it\/\/patto-di-prova-cose-e-come-funziona\/"},"modified":"2020-03-20T00:00:00","modified_gmt":"2020-03-20T00:00:00","slug":"patto-di-prova-cose-e-come-funziona","status":"publish","type":"post","link":"https:\/\/toffolettodeluca.it\/en\/patto-di-prova-cose-e-come-funziona\/","title":{"rendered":"Patto di prova: cos\u2019\u00e8 e come funziona"},"content":{"rendered":"<p>Di:\u00a0<a href=\"https:\/\/toffolettodeluca.it\/it\/avvocati-diritto-del-lavoro\/redazione-insight\/\">Avv. Wanda Falco<\/a><\/p>\n<p>Il\u00a0<strong>patto di prova<\/strong>\u00a0\u00e8 una clausola che pu\u00f2 essere apposta al contratto di lavoro per subordinare\u00a0<strong>l\u2019assunzione definitiva<\/strong>\u00a0all\u2019esito positivo di un periodo di prova.\u00a0<\/p>\n<p>Come previsto dall\u2019art. 2096 c.c., l\u2019assunzione del lavoratore per un periodo di prova deve risultare da\u00a0<strong>atto scritto<\/strong>\u00a0e durante tale periodo ciascuna delle parti pu\u00f2\u00a0<strong>recedere dal contratto senza obbligo di preavviso<\/strong>\u00a0o di indennit\u00e0. La\u00a0<strong>durata<\/strong>\u00a0della prova \u00e8 stabilita dalla contrattazione collettiva nazionale e trascorso il relativo periodo, l\u2019assunzione diviene definitiva.<\/p>\n<p><strong>La causa<\/strong>\u00a0del patto di prova risiede nella tutela dell\u2019interesse comune alle due parti del rapporto di lavoro di verificare la\u00a0<strong>reciproca convenienza del contratto.\u00a0<\/strong>Infatti,\u00a0durante il periodo di prova il datore di lavoro ha la possibilit\u00e0 di valutare le\u00a0<strong>capacit\u00e0 e le competenze del lavoratore<\/strong>, mentre quest\u2019ultimo pu\u00f2 valutare l\u2019entit\u00e0 della prestazione richiestagli, le condizioni di svolgimento del rapporto di lavoro e l\u2019interesse verso il ruolo assegnato (Cass. 4635\/2016).<\/p>\n<p>Vediamo ora nel dettaglio quali sono le caratteristiche del patto di prova e quando \u00e8 possibile stipulare pi\u00f9 patti successivi tra le medesime parti.<\/p>\n<h2><span style=\"color: #FF0000;\">Caratteristiche del patto di prova<\/span><\/h2>\n<p>Affinch\u00e9 sia valido il patto di prova deve presentare alcune caratteristiche. In particolare:<\/p>\n<ul>\n<li>deve risultare\u00a0<strong>da atto scritto<\/strong>\u00a0a pena di nullit\u00e0 della prova; di solito consiste in un\u2019apposita\u00a0<strong>clausola\u00a0<\/strong>del contratto individuale di lavoro;<\/li>\n<li>deve contenere specifica indicazione\u00a0<strong>delle mansioni<\/strong>\u00a0che il lavoratore \u00e8 chiamato a svolgere; tale indicazione pu\u00f2 essere operata anche\u00a0<em>per relationem<\/em>, ovvero mediante rinvio alle declaratorie del contratto collettivo che definiscano le mansioni comprese nella qualifica di assunzione, purch\u00e9 il rinvio sia sufficientemente specifico ovvero \u201cfatto alla nozione pi\u00f9 dettagliata rispetto alla scala definitoria di categorie, qualifiche, livelli e profili professionali in esso contenuta\u201d (Cass. 9597\/2017; Cass. 16587\/2017);<\/li>\n<li>deve avere una\u00a0<strong>durata massima<\/strong>, di solito fissata dai CCNL di settore (che generalmente si aggira intorno ai\u00a0<strong>sei mesi<\/strong>); nel caso in cui datore e lavoratore si accordino per una\u00a0<strong>durata minima<\/strong>\u00a0del periodo di prova, l\u2019art. 2096 c.c. dispone che la facolt\u00e0 di recesso non possa esercitarsi prima della scadenza del termine;\u00a0<\/li>\n<li>se nessuna parte esprime volont\u00e0 di recedere, la prova si ritiene automaticamente superata e il contratto prosegue in via definitiva, senza che sia necessario provvedere ad alcuna formalit\u00e0 in tal senso.<\/li>\n<\/ul>\n<p>A ci\u00f2 si aggiunga che il\u00a0<strong>licenziamento<\/strong>\u00a0intimato nel corso o al termine del periodo di prova,\u00a0<strong>ha natura discrezionale e non deve essere motivato<\/strong>\u00a0neppure in caso di contestazione in ordine alla valutazione della capacit\u00e0 e del comportamento professionale del lavoratore. Su quest\u2019ultimo, pertanto, incombe\u00a0<strong>l\u2019onere di provare<\/strong>\u00a0sia il\u00a0<strong>positivo superamento<\/strong>\u00a0del periodo di prova sia che il recesso sia stato determinato da un\u00a0<strong>motivo illecito<\/strong>\u00a0e, quindi, estraneo alla funzione del patto di prova (si veda in tal senso Cass. 1180\/2017, che ha cassato con rinvio la sentenza di merito che aveva ritenuto illegittimo il licenziamento di un informatore farmaceutico per mancato superamento della prova in quanto il lavoratore aveva dimostrato l\u2019esito positivo della stessa senza, per\u00f2, verificare se il recesso fosse stato determinato da altri motivi illeciti).<\/p>\n<h2><span style=\"color: #FF0000;\">Successione di plurimi patti di prova<\/span><\/h2>\n<p>Come anticipato, la\u00a0<em>ratio<\/em>\u00a0del patto di prova \u00e8 quella di consentire a entrambe le parti di valutare la\u00a0<strong>reciproca convenienza<\/strong>\u00a0del contratto.\u00a0<\/p>\n<p>Da ci\u00f2 consegue che, in genere, non \u00e8 possibile stipulare pi\u00f9 patti di prova successivi tra le medesime parti e che abbiano ad oggetto le medesime mansioni, avendo il datore di lavoro gi\u00e0 verificato le capacit\u00e0 professionali del dipendente (Cass. 6633\/2020).<\/p>\n<p>Tuttavia, non mancano casi in cui la\u00a0<strong>ripetizione del patto di prova<\/strong>\u00a0in due successivi contratti aventi ad oggetto le medesime mansioni si renda\u00a0<strong>necessaria per l\u2019intervento di molteplici fattori<\/strong>, attinenti, ad esempio, alle abitudini di vita o a problemi di salute del lavoratore o al contesto di svolgimento della prestazione. In tali casi, il datore di lavoro ha bisogno di verificare che il sopraggiungere di\u00a0<strong>circostanze nuove<\/strong>\u00a0non abbia inciso in nessun modo sulle capacit\u00e0 e sulle attitudini del dipendente (Cass. 28930\/2018).<\/p>\n<p>In altre parole, la ripetizione del patto di prova in due successivi contratti di lavoro tra le stesse parti \u00e8 ammissibile solo se essa risponda all\u2019esigenza effettiva dell\u2019imprenditore di verificare non solo le qualit\u00e0 professionali, ma anche il comportamento e la personalit\u00e0 del lavoratore in relazione all\u2019adempimento della prestazione,\u00a0<strong>elementi suscettibili di modificarsi nel tempo.<\/strong><\/p>\n<p>Si pensi al caso del postino che aveva inizialmente svolto per brevi periodi l\u2019attivit\u00e0 di portalettere in\u00a0<strong>un paesino in provincia di Lecce<\/strong>; successivamente era stato assunto nuovamente in prova, ma per svolgere le medesime mansioni\u00a0<strong>a Milano<\/strong>. In tal caso, \u00e8 stata confermata la\u00a0<strong>legittimit\u00e0 del patto di prova<\/strong>\u00a0apposto al contratto nonostante il dipendente fosse stato gi\u00e0 assunto in precedenza con vari contratti a termine e con le medesime mansioni di portalettere. Infatti, i precedenti contratti erano troppo brevi e la nuova sede di lavoro si trovava in un contesto inevitabilmente\u00a0<strong>pi\u00f9 stressante e caotico<\/strong>\u00a0rispetto a quello cui era abituato il lavoratore (Cass. 28252\/2018).<\/p>\n<p>Analogamente, \u00e8 stata confermata la legittimit\u00e0 del nuovo patto di prova stipulato con un postino in considerazione del fatto che nel corso del tempo erano intervenute\u00a0<strong>nuove tecniche operative e variazioni concernenti le modalit\u00e0 di consegna<\/strong>\u00a0della corrispondenza tali da rendere necessaria l\u2019ulteriore verifica della professionalit\u00e0 e personalit\u00e0 del lavoratore (Cass. 25368\/2016).<\/p>\n<h2><span style=\"color: #FF0000;\">Licenziamento via mail del lavoratore in prova<\/span><\/h2>\n<p>Sono sorti alcuni dubbi circa la legittimit\u00e0 del\u00a0<strong>licenziamento via\u00a0<em>mail<\/em><\/strong>\u00a0per mancato superamento della prova.<\/p>\n<p>Tuttavia, la giurisprudenza ha risolto la questione partendo dall\u2019art.10 della legge 604\/66 secondo cui le garanzie previste dalla stessa per il caso di licenziamento si applicano ai\u00a0<strong>lavoratori in prova soltanto dal momento in cui l\u2019assunzione diviene definitiva<\/strong>\u00a0e, in ogni caso, quando sono decorsi sei mesi dall\u2019inizio del rapporto di lavoro (Cass. 297453\/2017).\u00a0<\/p>\n<p>Dunque,\u00a0<strong>\u00e8 escluso<\/strong>\u00a0che durante il periodo di prova il licenziamento del lavoratore\u00a0<strong>debba avvenire in forma scritta\u00a0<\/strong>(richiesta dall\u2019art. 2 della legge 604\/66).\u00a0<\/p>\n<p>Fatta questa premessa con riguardo al licenziamento nel periodo di prova, va ricordato che per giurisprudenza consolidata il\u00a0requisito della comunicazione per iscritto\u00a0del licenziamento deve ritenersi\u00a0assolto, in assenza della previsione di modalit\u00e0 specifiche, con\u00a0qualunque modalit\u00e0\u00a0che comporti la trasmissione al destinatario del documento scritto nella sua materialit\u00e0. Pertanto, tale requisito sussiste anche in caso di licenziamento via\u00a0<em>mail<\/em>\u00a0(sul punto si veda il nostro approfondimento\u00a0<a href=\"https:\/\/toffolettodeluca.it\/it\/notizie-eventi\/notizie-eventi\/a\/il-licenziamento-intimato-mail-whatsapp-o-sms-quali-condizioni-e-legittimo\/\">\u201cIl licenziamento intimato via mail, whatsapp o sms: a quali condizioni \u00e8 legittimo?\u201d<\/a>).<\/p>\n<h2> <span style=\"color: #FF0000;\">Conclusioni<\/span><\/h2>\n<p>Come emerso nel corso della trattazione, il\u00a0patto di prova\u00a0costituisce un adeguato strumento per il datore di lavoro di verifica, durante la fase iniziale del rapporto, della capacit\u00e0 professionale e delle attitudini del lavoratore, consentendo anche di recedere senza necessit\u00e0 che sussista una giusta causa o un giustificato motivo, ove queste capacit\u00e0 e attitudini siano diverse da quelle attese.\u00a0<\/p>\n<p>Inoltre, considerata la causa del patto di prova, quale strumento di verifica della convenienza del rapporto di lavoro, non \u00e8 in assoluto vietato stipulare pi\u00f9 di un patto di prova con il medesimo lavoratore. Ci\u00f2 sia quando si tratti di patti aventi ad oggetto mansioni diverse, sia quando si tratti di patti aventi ad oggetto mansioni identiche, ma che rendano necessaria una ulteriore verifica delle competenze e capacit\u00e0 del lavoratore a causa di circostanze nuove che potrebbero incidere sulla salute, sul contesto lavorativo o sulle abitudini di vita del dipendente.<\/p>\n<p> &#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Di:\u00a0Avv. Wanda Falco Il\u00a0patto di prova\u00a0\u00e8 una clausola che pu\u00f2 essere apposta al contratto di lavoro per subordinare\u00a0l\u2019assunzione definitiva\u00a0all\u2019esito positivo di un periodo di prova.\u00a0 Come previsto dall\u2019art. 2096 c.c., l\u2019assunzione del lavoratore per un periodo di prova deve risultare da\u00a0atto scritto\u00a0e durante tale periodo ciascuna delle parti pu\u00f2\u00a0recedere dal contratto senza obbligo di preavviso\u00a0o &#8230; <a title=\"Patto di prova: cos\u2019\u00e8 e come funziona\" class=\"read-more\" href=\"https:\/\/toffolettodeluca.it\/en\/patto-di-prova-cose-e-come-funziona\/\" aria-label=\"Read more about Patto di prova: cos\u2019\u00e8 e come funziona\">Read more<\/a><\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[],"tags":[185],"class_list":["post-2921","post","type-post","status-publish","format-standard","hentry","tag-patto-di-prova-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Patto di prova: cos\u2019\u00e8 e come funziona - Toffoletto De Luca Tamajo e Soci<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toffolettodeluca.it\/en\/patto-di-prova-cose-e-come-funziona\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Patto di prova: cos\u2019\u00e8 e come funziona - Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"og:description\" content=\"Di:\u00a0Avv. Wanda Falco Il\u00a0patto di prova\u00a0\u00e8 una clausola che pu\u00f2 essere apposta al contratto di lavoro per subordinare\u00a0l\u2019assunzione definitiva\u00a0all\u2019esito positivo di un periodo di prova.\u00a0 Come previsto dall\u2019art. 2096 c.c., l\u2019assunzione del lavoratore per un periodo di prova deve risultare da\u00a0atto scritto\u00a0e durante tale periodo ciascuna delle parti pu\u00f2\u00a0recedere dal contratto senza obbligo di preavviso\u00a0o ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toffolettodeluca.it\/en\/patto-di-prova-cose-e-come-funziona\/\" \/>\n<meta property=\"og:site_name\" content=\"Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-20T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/patto-di-prova-cose-e-come-funziona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/patto-di-prova-cose-e-come-funziona\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\"},\"headline\":\"Patto di prova: cos\u2019\u00e8 e come funziona\",\"datePublished\":\"2020-03-20T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/patto-di-prova-cose-e-come-funziona\\\/\"},\"wordCount\":1210,\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"keywords\":[\"Patto di prova\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/patto-di-prova-cose-e-come-funziona\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/patto-di-prova-cose-e-come-funziona\\\/\",\"name\":\"Patto di prova: cos\u2019\u00e8 e come funziona - Toffoletto De Luca Tamajo e Soci\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\"},\"datePublished\":\"2020-03-20T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/patto-di-prova-cose-e-come-funziona\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/patto-di-prova-cose-e-come-funziona\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/patto-di-prova-cose-e-come-funziona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/studio-diritto-del-lavoro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Newsflash &amp; Insights\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/category\\\/newsflash-insight\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Patto di prova: cos\u2019\u00e8 e come funziona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"contentUrl\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"caption\":\"Toffoletto De Luca Tamajo e Soci\"},\"image\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Patto di prova: cos\u2019\u00e8 e come funziona - Toffoletto De Luca Tamajo e Soci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toffolettodeluca.it\/en\/patto-di-prova-cose-e-come-funziona\/","og_locale":"en_US","og_type":"article","og_title":"Patto di prova: cos\u2019\u00e8 e come funziona - Toffoletto De Luca Tamajo e Soci","og_description":"Di:\u00a0Avv. Wanda Falco Il\u00a0patto di prova\u00a0\u00e8 una clausola che pu\u00f2 essere apposta al contratto di lavoro per subordinare\u00a0l\u2019assunzione definitiva\u00a0all\u2019esito positivo di un periodo di prova.\u00a0 Come previsto dall\u2019art. 2096 c.c., l\u2019assunzione del lavoratore per un periodo di prova deve risultare da\u00a0atto scritto\u00a0e durante tale periodo ciascuna delle parti pu\u00f2\u00a0recedere dal contratto senza obbligo di preavviso\u00a0o ... Read more","og_url":"https:\/\/toffolettodeluca.it\/en\/patto-di-prova-cose-e-come-funziona\/","og_site_name":"Toffoletto De Luca Tamajo e Soci","article_published_time":"2020-03-20T00:00:00+00:00","author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redazione","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/toffolettodeluca.it\/en\/patto-di-prova-cose-e-come-funziona\/#article","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/patto-di-prova-cose-e-come-funziona\/"},"author":{"name":"Redazione","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559"},"headline":"Patto di prova: cos\u2019\u00e8 e come funziona","datePublished":"2020-03-20T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/toffolettodeluca.it\/en\/patto-di-prova-cose-e-come-funziona\/"},"wordCount":1210,"publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"keywords":["Patto di prova"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/toffolettodeluca.it\/en\/patto-di-prova-cose-e-come-funziona\/","url":"https:\/\/toffolettodeluca.it\/en\/patto-di-prova-cose-e-come-funziona\/","name":"Patto di prova: cos\u2019\u00e8 e come funziona - Toffoletto De Luca Tamajo e Soci","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/#website"},"datePublished":"2020-03-20T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/toffolettodeluca.it\/en\/patto-di-prova-cose-e-come-funziona\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toffolettodeluca.it\/en\/patto-di-prova-cose-e-come-funziona\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/toffolettodeluca.it\/en\/patto-di-prova-cose-e-come-funziona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toffolettodeluca.it\/en\/studio-diritto-del-lavoro\/"},{"@type":"ListItem","position":2,"name":"Newsflash &amp; Insights","item":"https:\/\/toffolettodeluca.it\/en\/category\/newsflash-insight\/"},{"@type":"ListItem","position":3,"name":"Patto di prova: cos\u2019\u00e8 e come funziona"}]},{"@type":"WebSite","@id":"https:\/\/toffolettodeluca.it\/en\/#website","url":"https:\/\/toffolettodeluca.it\/en\/","name":"Toffoletto De Luca Tamajo e Soci","description":"","publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toffolettodeluca.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/toffolettodeluca.it\/en\/#organization","name":"Toffoletto De Luca Tamajo e Soci","url":"https:\/\/toffolettodeluca.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","contentUrl":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","caption":"Toffoletto De Luca Tamajo e Soci"},"image":{"@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/toffolettodeluca.it\/en\/author\/redazione\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/2921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/comments?post=2921"}],"version-history":[{"count":0,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/2921\/revisions"}],"wp:attachment":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/media?parent=2921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/categories?post=2921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/tags?post=2921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}