{"id":2956,"date":"2020-08-13T00:00:00","date_gmt":"2020-08-13T00:00:00","guid":{"rendered":"https:\/\/toffolettodeluca.it\/\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\/"},"modified":"2020-08-13T00:00:00","modified_gmt":"2020-08-13T00:00:00","slug":"buoni-pasto-alcune-conseguenze-della-natura-non-retributiva","status":"publish","type":"post","link":"https:\/\/toffolettodeluca.it\/en\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\/","title":{"rendered":"Buoni pasto: alcune conseguenze della natura non retributiva"},"content":{"rendered":"<p>Di:\u00a0<a href=\"https:\/\/toffolettodeluca.it\/it\/avvocati-diritto-del-lavoro\/redazione-insight\/\">Avv. Wanda Falco<\/a><\/p>\n<p><strong>Il buono basto (o\u00a0<em>ticket restaurant<\/em><\/strong>) \u00e8 un documento, in formato cartaceo o elettronico, che d\u00e0 diritto a un\u00a0<strong>servizio\u00a0sostitutivo\u00a0di\u00a0mensa\u00a0aziendale<\/strong>\u00a0per un importo pari al suo valore.<\/p>\n<p>Si tratta di un\u00a0<strong><em>benefit<\/em><\/strong>\u00a0con cui il datore di lavoro assicura ai propri dipendenti\u00a0<strong>la somministrazione di pasti<\/strong>\u00a0da parte di pubblici esercizi convenzionati.\u00a0<\/p>\n<p>La relativa disciplina \u00e8 stata riformata con il\u00a0<a href=\"https:\/\/www.gazzettaufficiale.it\/atto\/stampa\/serie_generale\/originario\">Decreto del Ministero dello sviluppo economico n. 122 del 7 giugno 2017<\/a>\u00a0che specifica che i buoni pasto sono\u00a0<strong>utilizzabili da<\/strong>:<\/p>\n<ul>\n<li><strong>prestatori di lavoro subordinato<\/strong>, a tempo pieno o parziale;<\/li>\n<li><strong>soggetti che hanno instaurato con il cliente un rapporto di collaborazione\u00a0<\/strong>anche non subordinato.<\/li>\n<\/ul>\n<p>Inoltre, i\u00a0buoni pasto:<\/p>\n<ul>\n<li><strong>non sono cedibili, commercializzabili e convertibili in denaro<\/strong>;<\/li>\n<li>sono cumulabili nel\u00a0<strong>limite di 8;<\/strong><\/li>\n<li>possono essere\u00a0<strong>utilizzati esclusivamente dal titolare<\/strong>\u00a0per l\u2019intero valore.<\/li>\n<\/ul>\n<p>Si segnala, inoltre, che la legge di bilancio 2020 ha previsto che dal 1\u00b0 gennaio 2020 i buoni pasto elettronici sono pi\u00f9 convenienti di quelli cartacei in quanto l\u2019importo giornaliero massimo che non concorre a formare il reddito di lavoro del dipendente \u00e8 elevato\u00a0<strong>da 7 a 8 euro ove siano erogati in formato elettronico<\/strong>\u00a0ed \u00e8 ridotto da 5,29 a 4 euro in caso di buoni cartacei (art. 1, comma 677, L. 160\/2019).\u00a0<\/p>\n<p>Sono sorti alcuni dubbi circa la natura (retributiva o assistenziale) dei buoni pasto, questione dalla cui risoluzione discendono alcune conseguenze in materia, ad esempio, di\u00a0<strong><em>smart working<\/em>, permessi per allattamento e responsabilit\u00e0 solidale in materia di appalti.<\/strong><\/p>\n<p>Vediamo, pertanto, nel dettaglio cosa dice la giurisprudenza.<\/p>\n<h2><span style=\"color: #FF0000;\">Buoni pasto e\u00a0<em>smart working<\/em><\/span><\/h2>\n<p>Soprattutto a seguito della particolare risonanza data al lavoro agile durante l\u2019emergenza Coronavirus, ci si chiede se il lavoratore in\u00a0<strong><em>smart working<\/em><\/strong>\u00a0abbia diritto comunque ai buoni pasto.<\/p>\n<p>Sulla questione si \u00e8 recentemente pronunciato il Tribunale di Venezia che, in linea con la giurisprudenza consolidata, esclude la natura di \u201celemento normale\u201d della retribuzione, trattandosi di un\u2019agevolazione di\u00a0<strong>carattere assistenziale<\/strong>\u00a0collegata al rapporto di lavoro da un\u00a0<strong>nesso meramente occasionale<\/strong>\u00a0(Trib. Venezia, 8 luglio 2020, n. 3463; Cass. 16135\/2020; Cass. 14388\/2016).\u00a0<\/p>\n<p>In altre parole, il buono pasto \u00e8 un beneficio che consente, nell\u2019ambito dell\u2019organizzazione di lavoro,\u00a0<strong>la conciliazione delle esigenze di servizio con le esigenze quotidiane del lavoratore<\/strong>, al quale viene cos\u00ec consentita &#8211; laddove non sia previsto un servizio mensa &#8211; la fruizione del pasto i cui costi vengono assunti dal datore di lavoro. Ci\u00f2 al fine di garantire il benessere fisico necessario per la prosecuzione dell\u2019attivit\u00e0 lavorativa al lavoratore\u00a0<strong>obbligato a rendere la prestazione in un orario comprensivo della fisiologica pausa pranzo e in un luogo<\/strong>, la sede di lavoro,\u00a0<strong>diverso dalla propria abitazione<\/strong>.\u00a0<\/p>\n<p><strong>Non si tratta, quindi, di un elemento della retribuzione<\/strong>\u00a0n\u00e9 di un trattamento necessariamente conseguente alla prestazione di lavoro in quanto tale, ma di un\u00a0<strong>beneficio conseguente alle modalit\u00e0 concrete di organizzazione dell\u2019orario di lavoro<\/strong>.<\/p>\n<p>L\u2019esigenza di assicurare al lavoratore la fruizione del pasto, dunque,\u00a0<strong>non ricorre nel caso in cui la prestazione lavorativa sia svolta in regime di\u00a0<em>smart working<\/em><\/strong>\u00a0essendo in tal caso il dipendente libero di organizzare in piena autonomia i tempi di svolgimento del lavoro:\u00a0<strong>i buoni pasto, dunque, non rientrano nella nozione di trattamento economico e normativo, che deve essere garantito in ogni caso al lavoratore in\u00a0<em>smart working ex\u00a0<\/em>art. 20 Legge n. 81 del 2017.<\/strong><\/p>\n<p>A tale riguardo occorre precisare, inoltre, che l\u2019articolo 6 del D.l. 333\/1992 (convertito con legge 359\/1992) esclude, in linea generale, la connotazione retributiva dell\u2019indennit\u00e0 di mensa, in quanto servizio sociale predisposto nei confronti della generalit\u00e0 dei lavoratori,\u00a0<strong>salvo che la contrattazione collettiva non ne preveda una diversa qualificazione<\/strong>\u00a0(\u201cSalvo che gli accordi ed i contratti collettivi, anche aziendali, dispongano diversamente, stabilendo se e in quale misura la mensa \u00e8 retribuzione in natura, il valore del servizio di mensa, comunque gestito ed erogato, e l\u2019importo della prestazione pecuniaria sostitutiva di esso, percepita da chi non usufruisce del servizio istituito dall\u2019azienda, non fanno parte della retribuzione a nessun effetto attinente a istituti legali e contrattuali del rapporto di lavoro subordinato\u201d).<\/p>\n<p>Considerato che la disciplina dello\u00a0<em>smart working<\/em>\u00a0\u2013 al di l\u00e0 delle tutele garantite dalla legge \u2013 \u00e8 rimessa all\u2019accordo delle parti, a livello collettivo o individuale, \u00e8 possibile che l\u2019accordo aziendale preveda che il\u00a0buono pasto\u00a0spetti ugualmente, ossia anche nei giorni di lavoro in modalit\u00e0 \u201cagile\u201d.<\/p>\n<p>Diversamente, non vi sarebbero i presupposti per il riconoscimento dei\u00a0buoni pasto\u00a0ai lavoratori \u201cagili\u201d.\u00a0<\/p>\n<h2><span style=\"color: #FF0000;\">Buoni pasto e permessi per allattamento<\/span><\/h2>\n<p>Altra problematica concerne la spettanza dei buoni pasto alla lavoratrice madre che fruisca dei\u00a0<strong>permessi per allattamento<\/strong>.\u00a0<\/p>\n<p>Sul punto la Suprema Corte ha spiegato che il buono pasto\u00a0<strong>non \u00e8 un corrispettivo obbligatorio della prestazione lavorativa, ossia legato alla prestazione di lavoro in quanto tale<\/strong>, ma un beneficio connesso alle modalit\u00e0\u00a0<strong>concrete del suo svolgimento orario<\/strong>e, quindi, alla relativa organizzazione: esso, infatti, serve a consentire al lavoratore il\u00a0<strong>recupero delle energie psico-fisiche\u00a0<\/strong>mediante una\u00a0<strong>pausa da utilizzare per l\u2019eventuale consumazione del pasto<\/strong>, laddove non sia organizzato un servizio mensa.\u00a0\u00a0<\/p>\n<p>Dunque, il buono pasto non spetta per il fatto stesso di aver prestato l\u2019attivit\u00e0 lavorativa, ma in tanto spetta in quanto la durata della giornata lavorativa\u00a0<strong>ricomprenda anche le ore destinate alla pausa pranzo<\/strong>\u00a0(Cass. 31137\/2019).\u00a0\u00a0<\/p>\n<p>Il comma 1 dell\u2019art. 8, d.lgs. 8 aprile 2003, n. 66, infatti, stabilisce che \u201cqualora l\u2019orario di lavoro giornaliero\u00a0<strong>ecceda il limite di sei ore<\/strong>\u00a0il lavoratore deve beneficiare di un intervallo per pausa, le cui modalit\u00e0 e la cui durata sono stabilite dai contratti collettivi di lavoro, ai fini del recupero delle energie psico-fisiche e della eventuale consumazione del pasto anche al fine di attenuare il lavoro monotono e ripetitivo\u201d.\u00a0<\/p>\n<p>In sostanza,\u00a0<strong>se l\u2019orario di lavoro ha durata superiore a 6 ore il lavoratore ha diritto alla pausa pranzo e di conseguenza al buono pasto.<\/strong><\/p>\n<p>Pertanto,\u00a0<strong>la dipendente che fruisce dei permessi per allattamento e non raggiunge le 6 ore di lavoro effettivo, non ha diritto alla pausa pranzo e, dunque, non matura il diritto al buono pasto<\/strong>: ci\u00f2 in quanto le ore di permesso godute per tali motivi\u00a0<strong>sono equiparate dall\u2019art. 39 D.lgs. 151\/2001 alle ore di lavoro solo ai fini retributivi<\/strong>, mentre non rilevano per il godimento di elementi come il buono pasto, che sono agevolazioni di carattere assistenziale collegate al rapporto di lavoro da un nesso meramente occasionale.\u00a0Inoltre, ci\u00f2 che conta\u00a0<strong>ai fini della fruizione della pausa pranzo<\/strong>\u00a0e quindi del\u00a0<strong>riconoscimento del buono pasto sono le ore di lavoro effettivamente prestate<\/strong>\u00a0(cio\u00e8 quelle in cui il lavoratore \u00e8 presente a lavoro) e non anche le ore di permesso per allattamento, in quanto\u00a0<strong>l\u2019esigenza di reintegrare le energie psico-fisiche sussiste solo in relazione alle prime.<\/strong><\/p>\n<p>Sul punto si \u00e8 pronunciato anche il\u00a0<a href=\"https:\/\/www.lavoro.gov.it\/documenti-e-norme\/interpelli\/Documents\/Interpello-2-2019.pdf\">Ministero del lavoro con risposta a interpello n. 2\/2019<\/a>: sebbene secondo l\u2019art. 39, del D.lgs. 151\/2001 i riposi per allattamento debbano essere \u201cconsiderati ore lavorative agli effetti della durata e della retribuzione del lavoro\u201d, non bisogna trascurare la\u00a0<em>ratio\u00a0<\/em>dell\u2019art. 8 del D.lgs. 66\/2003; la pausa pranzo, infatti, serve a consentire al lavoratore, che effettui una prestazione lavorativa superiore a 6 ore, di recuperare le energie psico-fisiche e non c\u2019\u00e8 dubbio che a tal fine si debba\u00a0<strong>tenere conto di un\u2019attivit\u00e0 lavorativa effettivamente prestata<\/strong>\u00a0<strong>nella quale non possono rientrare le ore di permesso per allattamento.\u00a0<\/strong><\/p>\n<p>Da tali premesse discende che,<strong>\u00a0in caso di riposi per allattamento, il buono pasto spetta alla lavoratrice la cui giornata lavorativa si articoli in almeno 6 ore al netto delle ore di riposo per allattamento.\u00a0<\/strong><\/p>\n<h2><span style=\"color: #FF0000;\">Buoni pasto e responsabilit\u00e0 solidale nell\u2019appalto<\/span><\/h2>\n<p>Altra questione pi\u00f9 volte affrontata \u00e8 quella relativa all\u2019inclusione dei buoni pasto nella nozione di\u00a0<strong>trattamenti retributivi<\/strong>\u00a0oggetto di responsabilit\u00e0\u00a0<strong>solidale negli appalti<\/strong>.<\/p>\n<p>In particolare secondo l\u2019art. 29 D.lgs. 276\/2003\u00a0<strong>il committente \u00e8 obbligato in solido con l\u2019appaltatore<\/strong>, entro il limite di due anni dalla cessazione dell\u2019appalto, a corrispondere ai lavoratori i\u00a0<strong>trattamenti retributivi<\/strong>, comprese le quote di trattamento di fine rapporto, nonch\u00e9 i contributi previdenziali e i premi assicurativi dovuti in relazione al periodo di esecuzione del contratto di appalto.<\/p>\n<p>La Corte di Cassazione ha sottolineato che la locuzione \u201c<strong>trattamenti retributivi<\/strong>\u201d, utilizzata nell\u2019art. 29, deve essere\u00a0<strong>interpretata in senso stretto\u00a0<\/strong>e cio\u00e8 che le somme oggetto della responsabilit\u00e0 solidale del committente, terzo estraneo al rapporto di lavoro tra lavoratore e appaltatore, devono avere\u00a0<strong>con certezza natura retributiva<\/strong>\u00a0ed essere\u00a0<strong>corrispettivo obbligatorio della prestazione lavorativa<\/strong>\u00a0(Cass. 10354\/2016; Cass. 10543\/2016).<\/p>\n<p><strong>In tale nozione non possono rientrare i buoni pasto<\/strong>\u00a0che, salvo diverse disposizioni di legge o di contratto,\u00a0<strong>non hanno natura retributiva<\/strong>, come abbiamo visto. La fruizione della mensa o la consegna del buono pasto, infatti,\u00a0<strong>non sono in rapporto di corrispettivit\u00e0 con la prestazione lavorativa\u00a0<\/strong>e, pertanto, non sono un elemento della retribuzione.\u00a0<\/p>\n<p>Si tratta, invero, \u201cdi una prestazione di natura assistenziale, collegata solo occasionalmente con il rapporto di lavoro\u201d: il buono pasto non spetta per il solo fatto di svolgere la prestazione lavorativa, ma spetta se i tempi di lavoro effettivo siano tali da rendere necessaria una pausa per reintegrare le energie psico-fisiche (Trib. Milano 2928\/2018; Trib. Milano, 1305\/2018).<\/p>\n<h2><span style=\"color: #FF0000;\">Conclusioni<\/span><\/h2>\n<p>I buoni pasto non hanno natura retributiva, salvo che la contrattazione collettiva non preveda diversamente.\u00a0<\/p>\n<p>Essi, infatti, costituiscono un\u00a0<em>benefit\u00a0<\/em>che non spetta per il mero svolgimento della prestazione lavorativa.<\/p>\n<p>La funzione del buono pasto, infatti, \u00e8 quella di consentire al lavoratore la fruizione del pasto nell\u2019ambito di una giornata lavorativa che abbia una durata e un\u2019articolazione tali da rendere necessaria la pausa pranzo.<\/p>\n<p>Dalla natura non retributiva del buono pasto discende che esso non spetta al lavoratore in\u00a0<em>smart working<\/em>\u00a0che pu\u00f2 gestire la giornata lavorativa in maniera flessibile n\u00e9 alla lavoratrice che usufruendo dei permessi per allattamento non raggiunga le sei ore di lavoro che le consentono di maturare il diritto alla pausa pranzo. Di non poco conto \u00e8 anche la conseguenza dell\u2019esclusione del valore dei buoni pasto dai trattamenti retributivi oggetto di responsabilit\u00e0 solidale negli appalti.\u00a0<\/p>\n<p> &#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Di:\u00a0Avv. Wanda Falco Il buono basto (o\u00a0ticket restaurant) \u00e8 un documento, in formato cartaceo o elettronico, che d\u00e0 diritto a un\u00a0servizio\u00a0sostitutivo\u00a0di\u00a0mensa\u00a0aziendale\u00a0per un importo pari al suo valore. Si tratta di un\u00a0benefit\u00a0con cui il datore di lavoro assicura ai propri dipendenti\u00a0la somministrazione di pasti\u00a0da parte di pubblici esercizi convenzionati.\u00a0 La relativa disciplina \u00e8 stata riformata con &#8230; <a title=\"Buoni pasto: alcune conseguenze della natura non retributiva\" class=\"read-more\" href=\"https:\/\/toffolettodeluca.it\/en\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\/\" aria-label=\"Read more about Buoni pasto: alcune conseguenze della natura non retributiva\">Read more<\/a><\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[],"tags":[138,136,199],"class_list":["post-2956","post","type-post","status-publish","format-standard","hentry","tag-compensation-benefits-en","tag-buono-pasto-en","tag-smart-working-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Buoni pasto: alcune conseguenze della natura non retributiva - Toffoletto De Luca Tamajo e Soci<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toffolettodeluca.it\/en\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Buoni pasto: alcune conseguenze della natura non retributiva - Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"og:description\" content=\"Di:\u00a0Avv. Wanda Falco Il buono basto (o\u00a0ticket restaurant) \u00e8 un documento, in formato cartaceo o elettronico, che d\u00e0 diritto a un\u00a0servizio\u00a0sostitutivo\u00a0di\u00a0mensa\u00a0aziendale\u00a0per un importo pari al suo valore. Si tratta di un\u00a0benefit\u00a0con cui il datore di lavoro assicura ai propri dipendenti\u00a0la somministrazione di pasti\u00a0da parte di pubblici esercizi convenzionati.\u00a0 La relativa disciplina \u00e8 stata riformata con ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toffolettodeluca.it\/en\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\/\" \/>\n<meta property=\"og:site_name\" content=\"Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-13T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\"},\"headline\":\"Buoni pasto: alcune conseguenze della natura non retributiva\",\"datePublished\":\"2020-08-13T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\\\/\"},\"wordCount\":1616,\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"keywords\":[\"Compensation &amp; Benefits\",\"Meal Vouchers\",\"Smart working\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\\\/\",\"name\":\"Buoni pasto: alcune conseguenze della natura non retributiva - Toffoletto De Luca Tamajo e Soci\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\"},\"datePublished\":\"2020-08-13T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/studio-diritto-del-lavoro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Newsflash &amp; Insights\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/category\\\/newsflash-insight\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Buoni pasto: alcune conseguenze della natura non retributiva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"contentUrl\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"caption\":\"Toffoletto De Luca Tamajo e Soci\"},\"image\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Buoni pasto: alcune conseguenze della natura non retributiva - Toffoletto De Luca Tamajo e Soci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toffolettodeluca.it\/en\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\/","og_locale":"en_US","og_type":"article","og_title":"Buoni pasto: alcune conseguenze della natura non retributiva - Toffoletto De Luca Tamajo e Soci","og_description":"Di:\u00a0Avv. Wanda Falco Il buono basto (o\u00a0ticket restaurant) \u00e8 un documento, in formato cartaceo o elettronico, che d\u00e0 diritto a un\u00a0servizio\u00a0sostitutivo\u00a0di\u00a0mensa\u00a0aziendale\u00a0per un importo pari al suo valore. Si tratta di un\u00a0benefit\u00a0con cui il datore di lavoro assicura ai propri dipendenti\u00a0la somministrazione di pasti\u00a0da parte di pubblici esercizi convenzionati.\u00a0 La relativa disciplina \u00e8 stata riformata con ... Read more","og_url":"https:\/\/toffolettodeluca.it\/en\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\/","og_site_name":"Toffoletto De Luca Tamajo e Soci","article_published_time":"2020-08-13T00:00:00+00:00","author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redazione","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/toffolettodeluca.it\/en\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\/#article","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\/"},"author":{"name":"Redazione","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559"},"headline":"Buoni pasto: alcune conseguenze della natura non retributiva","datePublished":"2020-08-13T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/toffolettodeluca.it\/en\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\/"},"wordCount":1616,"publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"keywords":["Compensation &amp; Benefits","Meal Vouchers","Smart working"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/toffolettodeluca.it\/en\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\/","url":"https:\/\/toffolettodeluca.it\/en\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\/","name":"Buoni pasto: alcune conseguenze della natura non retributiva - Toffoletto De Luca Tamajo e Soci","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/#website"},"datePublished":"2020-08-13T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/toffolettodeluca.it\/en\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toffolettodeluca.it\/en\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/toffolettodeluca.it\/en\/buoni-pasto-alcune-conseguenze-della-natura-non-retributiva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toffolettodeluca.it\/en\/studio-diritto-del-lavoro\/"},{"@type":"ListItem","position":2,"name":"Newsflash &amp; Insights","item":"https:\/\/toffolettodeluca.it\/en\/category\/newsflash-insight\/"},{"@type":"ListItem","position":3,"name":"Buoni pasto: alcune conseguenze della natura non retributiva"}]},{"@type":"WebSite","@id":"https:\/\/toffolettodeluca.it\/en\/#website","url":"https:\/\/toffolettodeluca.it\/en\/","name":"Toffoletto De Luca Tamajo e Soci","description":"","publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toffolettodeluca.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/toffolettodeluca.it\/en\/#organization","name":"Toffoletto De Luca Tamajo e Soci","url":"https:\/\/toffolettodeluca.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","contentUrl":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","caption":"Toffoletto De Luca Tamajo e Soci"},"image":{"@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/toffolettodeluca.it\/en\/author\/redazione\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/2956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/comments?post=2956"}],"version-history":[{"count":0,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/2956\/revisions"}],"wp:attachment":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/media?parent=2956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/categories?post=2956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/tags?post=2956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}