{"id":2964,"date":"2020-08-04T00:00:00","date_gmt":"2020-08-04T00:00:00","guid":{"rendered":"https:\/\/toffolettodeluca.it\/\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\/"},"modified":"2020-08-04T00:00:00","modified_gmt":"2020-08-04T00:00:00","slug":"dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto","status":"publish","type":"post","link":"https:\/\/toffolettodeluca.it\/en\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\/","title":{"rendered":"Dall\u2019osservatorio sul diritto del lavoro di Toffoletto De Luca Tamajo: Congedi parentali &#8211; un obbligo o una scelta ma sempre un diritto"},"content":{"rendered":"<ul>\n<li>Solo il 16% dei Paesi a livello globale prevede un periodo di congedo della durata di circa un anno o superiore\u00a0<\/li>\n<li>Nel 38% dei Paesi, l\u2019indennit\u00e0 \u00e8 pari al 100% dello stipendio ed \u00e8 corrisposta dall\u2019ente previdenziale<\/li>\n<\/ul>\n<p>La maggior parte dei Paesi a livello mondiale \u00e8 sempre pi\u00f9 attenta alla conciliazione tra vita familiare e professionale, non solo attraverso forme di welfare, ma anche agendo a sostegno dei genitori con congedi di maternit\u00e0 e paternit\u00e0. Esistono tuttavia alcune realt\u00e0 in cui il periodo \u00e8 particolarmente breve o addirittura inesistente.\u00a0<\/p>\n<p><strong>L\u2019indagine<\/strong>, condotta dallo studio Toffoletto De Luca Tamajo specializzato in diritto del lavoro e sindacale per le imprese,\u00a0<strong>ha analizzato le normative di 40 Paesi in tutto il mondo<\/strong>\u00a0<strong>valutando la durata dei congedi parentali e gli oneri per il datore di lavoro<\/strong>. Il concetto di onerosit\u00e0 \u00e8 strettamente collegato alla lunghezza dei congedi in quanto, sebbene non sempre la retribuzione sia a carico del datore di lavoro, la prolungata assenza del lavoratore in congedo rappresenta un aggravio dal punto di vista organizzativo per il datore di lavoro.\u00a0<\/p>\n<p>Grazie ai dati raccolti \u00e8 stata realizzata la Law Map \u00abCongedi Parentali\u00bb che \u00e8 possibile consultare all\u2019indirizzo\u00a0 <a href=\"http:\/\/lawmaps.toffolettodeluca.it\/\"  target=\"_blank\">http:\/\/lawmaps.toffolettodeluca.it\/<\/a>  .\u00a0<\/p>\n<p>\u00abCi\u00f2 che emerge dalla ricerca \u00e8 che\u00a0<strong>sempre pi\u00f9 Paesi riconoscono una maggiore flessibilit\u00e0 nella fruizione del periodo di maternit\u00e0 obbligatoria, consentendo di scegliere in quale misura goderne pre e post nascita, oltre ad almeno alcuni giorni di congedo di paternit\u00e0 alla nascita del figlio<\/strong>\u00a0&#8211; sottolinea l\u2019avvocato Marcella De Luca Tamajo, associate dello studio Toffoletto De Luca Tamajo, che ha curato la ricerca. &#8211; In Italia, dal 2019 la maternit\u00e0 pu\u00f2 essere fruita interamente dopo la nascita e, dal 2020, i giorni di paternit\u00e0 sono stati aumentati da 5 a 7. Si differenziano molto, invece, i periodi di congedo parentale e la retribuzione. Pochi Paesi non la prevedono, mentre nella maggior parte dei casi il dipendente riceve tra l\u201980 ed il 100% della retribuzione dal sistema previdenziale.\u00bb\u00a0<\/p>\n<p>In Usa, Messico, Panama, Per\u00f9, Cina Emirati Arabi e Kazakhistan, il congedo di maternit\u00e0 si attesta di massina intorno ai tre mesi tra astensione prima e dopo il parto. In l\u2019India, sono previste 26 settimane, ma mancano il congedo di paternit\u00e0 ed i congedi parentali. Nessuno specifico congedo \u00e8 concesso al padre anche a Panama e in Kazakhistan. Emirati Arabi e Cina, invece, non disciplinano i congedi parentali.\u00a0<\/p>\n<p>Leggermente pi\u00f9 generosi i paesi come Grecia, Colombia, Germania, Brasile, Lettonia, Romania e Russia collocati nella fascia con congedi \u201cpoco onerosi\u201d in cui la maternit\u00e0 va dai 3 mesi e mezzo ai 5 mesi e sono previsti congedi parentali abbastanza estesi. La Germania, inoltre, non disciplina uno specifico congedo di paternit\u00e0 anche se dovr\u00e0 adeguarsi alla recente direttiva UE relativa \u201call&#8217;equilibrio tra attivit\u00e0 professionale e vita familiare per i genitori e i prestatori di assistenza\u201d, che impone agli Stati membri di garantire ai padri un minimo di 10 giorni di congedo retribuito.<\/p>\n<p>L\u2019estremo opposto della mappa \u2013 con congedi \u201cmolto onerosi\u201d &#8211; \u00e8 rappresentato da paesi come Austria, Irlanda, Norvegia e Regno Unito, nei quali la maternit\u00e0 \u00e8 vicina o addirittura supera l\u2019anno e la paternit\u00e0 \u00e8 sempre riconosciuta, oppure da paesi come la Repubblica Ceca dove i genitori possono chiedere fino a 3 anni di congedo.<\/p>\n<p>Paesi come Italia, Lussemburgo, Danimarca e Francia, con maternit\u00e0 media intorno ai 5 mesi, paternit\u00e0 tra 5 e 15 giorni e congedi che oscillano tra i 6 mesi e l\u2019anno, possono essere classificati in fascia media. In questi Paesi vi \u00e8 il maggior equilibrio tra l\u2019esigenza del lavoratore alla conciliazione vita-lavoro e quella del datore di lavoro, a cui non sono imposti obblighi troppo invasivi in materia di congedi di natura familiare.\u00a0Nella stessa ottica, in Italia si sta studiando la possibilit\u00e0 di ampliare il congedo di paternit\u00e0 ad un mese. La proposta in discussione consiste nell\u2019aumento della maternit\u00e0 obbligatoria da 5 a 6 mesi destinando, per\u00f2, i 30 giorni aggiuntivi al padre.<\/p>\n<p>Discorso a parte meritano quei paesi in cui \u00e8 consentito ai genitori optare \u2013 al posto del congedo parentale \u2013 per una conversione del rapporto in part-time. In Italia, Nuova Zelanda, Austria e Finlandia avviene mediante una riduzione dell\u2019orario di lavoro del 50%.<\/p>\n<h3><span style=\"color: #FF0000;\"><u>LA RICERCA\u00a0<\/u><\/span><\/h3>\n<table cellspacing=\"0\" border=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 274px; height: 55px;\">\n<p><strong><span style=\"color: #FF0000;\">ONEROSIT\u00c0 PER IL DATORE DI LAVORO\u00a0<\/span><\/strong><\/p>\n<\/td>\n<td style=\"width: 368px; height: 55px;\">\n<p><strong><span style=\"color: #FF0000;\">PAESI<\/span><\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 274px;\">\n<p>MOLTO ONEROSI<\/p>\n<\/td>\n<td style=\"width: 368px;\">\n<p>Austria, Irlanda, Norvegia, Regno Unito, Repubblica Ceca, Polonia, Nuova Zelanda<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 274px;\">\n<p>ONEROSI<\/p>\n<\/td>\n<td style=\"width: 368px;\">\n<p>Cile, Venezuela, Cipro, Finlandia, Lussemburgo, Spagna, Belgio, Danimarca, Francia, Italia, Paesi Bassi, Portogallo, Svezia, Slovacchia, Ucraina, Turchia, Israele<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 274px;\">\n<p>POCO ONEROSI<\/p>\n<\/td>\n<td style=\"width: 368px;\">\n<p>Argentina, Colombia, Germania, Grecia, Brasile, Lettonia, Romania, Russia<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 274px;\">\n<p>MOLTO POCO ONEROSI<\/p>\n<\/td>\n<td style=\"width: 368px;\">\n<p>Stati Uniti, Messico, Panama, Per\u00f9, Cina, Emirati Arabi Uniti, India, Kazakistan<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>I dati analizzati prendono in esame la disciplina ordinaria dei singoli Paesi e non tengono conto delle discipline speciali connesse all\u2019emergenza da COVID-19.<\/p>\n<p>L\u2019indagine ha esaminato la disciplina relativa ai congedi di maternit\u00e0, di paternit\u00e0 e parentali per la cura del figlio. Non prende in considerazione alcuna ulteriore tutela giuridica specifica, come: adozione, parti plurimi, interruzione della gravidanza, regole specifiche riguardo bambini disabili, possibili tutele dopo il parto (come la riduzione dell\u2019orario per allattamento). I dati contenuti nell\u2019indagine sono aggiornati ad agosto 2019 (con le sole eccezioni di: Belgio aggiornato ad Agosto 2017 e Irlanda a novembre 2018).<\/p>\n<p> &#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Solo il 16% dei Paesi a livello globale prevede un periodo di congedo della durata di circa un anno o superiore\u00a0 Nel 38% dei Paesi, l\u2019indennit\u00e0 \u00e8 pari al 100% dello stipendio ed \u00e8 corrisposta dall\u2019ente previdenziale La maggior parte dei Paesi a livello mondiale \u00e8 sempre pi\u00f9 attenta alla conciliazione tra vita familiare e &#8230; <a title=\"Dall\u2019osservatorio sul diritto del lavoro di Toffoletto De Luca Tamajo: Congedi parentali &#8211; un obbligo o una scelta ma sempre un diritto\" class=\"read-more\" href=\"https:\/\/toffolettodeluca.it\/en\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\/\" aria-label=\"Read more about Dall\u2019osservatorio sul diritto del lavoro di Toffoletto De Luca Tamajo: Congedi parentali &#8211; un obbligo o una scelta ma sempre un diritto\">Read more<\/a><\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[21],"tags":[171,140],"class_list":["post-2964","post","type-post","status-publish","format-standard","hentry","category-newsflash-insight","tag-law-maps-en","tag-congedi-parentali-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dall\u2019osservatorio sul diritto del lavoro di Toffoletto De Luca Tamajo: Congedi parentali - un obbligo o una scelta ma sempre un diritto - Toffoletto De Luca Tamajo e Soci<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toffolettodeluca.it\/en\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dall\u2019osservatorio sul diritto del lavoro di Toffoletto De Luca Tamajo: Congedi parentali - un obbligo o una scelta ma sempre un diritto - Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"og:description\" content=\"Solo il 16% dei Paesi a livello globale prevede un periodo di congedo della durata di circa un anno o superiore\u00a0 Nel 38% dei Paesi, l\u2019indennit\u00e0 \u00e8 pari al 100% dello stipendio ed \u00e8 corrisposta dall\u2019ente previdenziale La maggior parte dei Paesi a livello mondiale \u00e8 sempre pi\u00f9 attenta alla conciliazione tra vita familiare e ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toffolettodeluca.it\/en\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\/\" \/>\n<meta property=\"og:site_name\" content=\"Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-04T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\"},\"headline\":\"Dall\u2019osservatorio sul diritto del lavoro di Toffoletto De Luca Tamajo: Congedi parentali &#8211; un obbligo o una scelta ma sempre un diritto\",\"datePublished\":\"2020-08-04T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\\\/\"},\"wordCount\":857,\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"keywords\":[\"Law Maps\u2122\",\"Parental Leave\"],\"articleSection\":[\"Newsflash &amp; Insights\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\\\/\",\"name\":\"Dall\u2019osservatorio sul diritto del lavoro di Toffoletto De Luca Tamajo: Congedi parentali - un obbligo o una scelta ma sempre un diritto - Toffoletto De Luca Tamajo e Soci\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\"},\"datePublished\":\"2020-08-04T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/studio-diritto-del-lavoro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Learn & Connect\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/learn-connect\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Newsflash &amp; Insights\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/category\\\/newsflash-insight\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Dall\u2019osservatorio sul diritto del lavoro di Toffoletto De Luca Tamajo: Congedi parentali &#8211; un obbligo o una scelta ma sempre un diritto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"contentUrl\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"caption\":\"Toffoletto De Luca Tamajo e Soci\"},\"image\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dall\u2019osservatorio sul diritto del lavoro di Toffoletto De Luca Tamajo: Congedi parentali - un obbligo o una scelta ma sempre un diritto - Toffoletto De Luca Tamajo e Soci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toffolettodeluca.it\/en\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\/","og_locale":"en_US","og_type":"article","og_title":"Dall\u2019osservatorio sul diritto del lavoro di Toffoletto De Luca Tamajo: Congedi parentali - un obbligo o una scelta ma sempre un diritto - Toffoletto De Luca Tamajo e Soci","og_description":"Solo il 16% dei Paesi a livello globale prevede un periodo di congedo della durata di circa un anno o superiore\u00a0 Nel 38% dei Paesi, l\u2019indennit\u00e0 \u00e8 pari al 100% dello stipendio ed \u00e8 corrisposta dall\u2019ente previdenziale La maggior parte dei Paesi a livello mondiale \u00e8 sempre pi\u00f9 attenta alla conciliazione tra vita familiare e ... Read more","og_url":"https:\/\/toffolettodeluca.it\/en\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\/","og_site_name":"Toffoletto De Luca Tamajo e Soci","article_published_time":"2020-08-04T00:00:00+00:00","author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redazione","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/toffolettodeluca.it\/en\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\/#article","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\/"},"author":{"name":"Redazione","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559"},"headline":"Dall\u2019osservatorio sul diritto del lavoro di Toffoletto De Luca Tamajo: Congedi parentali &#8211; un obbligo o una scelta ma sempre un diritto","datePublished":"2020-08-04T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/toffolettodeluca.it\/en\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\/"},"wordCount":857,"publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"keywords":["Law Maps\u2122","Parental Leave"],"articleSection":["Newsflash &amp; Insights"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/toffolettodeluca.it\/en\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\/","url":"https:\/\/toffolettodeluca.it\/en\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\/","name":"Dall\u2019osservatorio sul diritto del lavoro di Toffoletto De Luca Tamajo: Congedi parentali - un obbligo o una scelta ma sempre un diritto - Toffoletto De Luca Tamajo e Soci","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/#website"},"datePublished":"2020-08-04T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/toffolettodeluca.it\/en\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toffolettodeluca.it\/en\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/toffolettodeluca.it\/en\/dallosservatorio-sul-diritto-del-lavoro-di-toffoletto-de-luca-tamajo-congedi-parentali-un-obbligo-o-una-scelta-ma-sempre-un-diritto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toffolettodeluca.it\/en\/studio-diritto-del-lavoro\/"},{"@type":"ListItem","position":2,"name":"Learn & Connect","item":"https:\/\/toffolettodeluca.it\/en\/learn-connect\/"},{"@type":"ListItem","position":3,"name":"Newsflash &amp; Insights","item":"https:\/\/toffolettodeluca.it\/en\/category\/newsflash-insight\/"},{"@type":"ListItem","position":4,"name":"Dall\u2019osservatorio sul diritto del lavoro di Toffoletto De Luca Tamajo: Congedi parentali &#8211; un obbligo o una scelta ma sempre un diritto"}]},{"@type":"WebSite","@id":"https:\/\/toffolettodeluca.it\/en\/#website","url":"https:\/\/toffolettodeluca.it\/en\/","name":"Toffoletto De Luca Tamajo e Soci","description":"","publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toffolettodeluca.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/toffolettodeluca.it\/en\/#organization","name":"Toffoletto De Luca Tamajo e Soci","url":"https:\/\/toffolettodeluca.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","contentUrl":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","caption":"Toffoletto De Luca Tamajo e Soci"},"image":{"@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/toffolettodeluca.it\/en\/author\/redazione\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/2964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/comments?post=2964"}],"version-history":[{"count":0,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/2964\/revisions"}],"wp:attachment":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/media?parent=2964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/categories?post=2964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/tags?post=2964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}