{"id":2973,"date":"2020-10-15T00:00:00","date_gmt":"2020-10-15T00:00:00","guid":{"rendered":"https:\/\/toffolettodeluca.it\/\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\/"},"modified":"2020-10-15T00:00:00","modified_gmt":"2020-10-15T00:00:00","slug":"newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio","status":"publish","type":"post","link":"https:\/\/toffolettodeluca.it\/en\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\/","title":{"rendered":"NEWSFLASH: Nuovi termini di isolamento e quarantena e nuove misure anti-contagio"},"content":{"rendered":"<p>Il Ministero della Salute con la Circolare n. 32850 del 12 ottobre 2020 ha aggiornato le indicazioni riguardo la durata e il termine dell\u2019isolamento e della quarantena in considerazione delle nuove evidenze scientifiche e delle indicazioni provenienti da alcuni organismi scientifici e internazionali.<\/p>\n<p>Inoltre, il 13 ottobre 2020 il Presidente del Consiglio dei Ministri, in considerazione dell\u2019evolversi della situazione epidemiologica e della proroga al 31 gennaio 2021 dello stato di emergenza sul territorio nazionale, ha firmato un nuovo DPCM recante ulteriori misure in materia di contenimento e gestione del virus COVID-19. Le nuove disposizioni si applicano a far data dal 14 ottobre u.s. e sono efficaci sino al 13 novembre 2020.<\/p>\n<p>Di seguito una sintesi delle principali disposizioni contenute nei citati provvedimenti.<\/p>\n<h2><span style=color: #FF0000;\">QUARANTENA E ISOLAMENTO\u00a0<\/span><\/h2>\n<p>In primo luogo, la circolare del Ministero della Salute chiarisce le nozioni di isolamento e quarantena. L\u2019isolamento si riferisce alla separazione delle persone infette dal resto della comunit\u00e0 per la durata del periodo di contagiosit\u00e0; la quarantena, invece, attiene alla restrizione dei movimenti di persone sane per la durata del periodo di incubazione, con l\u2019obiettivo di monitorare l\u2019eventuale comparsa di sintomi e identificare tempestivamente nuovi casi.<\/p>\n<p>Ci\u00f2 posto il Ministero distingue la gestione dei casi come segue.<\/p>\n<p class=\"lead\">Casi positivi asintomatici<\/p>\n<p>Le persone asintomatiche risultate positive possono rientrare in comunit\u00e0 dopo un periodo di isolamento di almeno 10 giorni dalla comparsa della positivit\u00e0, al termine del quale risulti eseguito un test molecolare con risultato negativo (10 giorni + test).<\/p>\n<p class=\"lead\">Casi positivi sintomatici<\/p>\n<p>Le persone sintomatiche risultate positive possono rientrare in comunit\u00e0 dopo un periodo di isolamento di almeno 10 giorni dalla comparsa dei sintomi, accompagnato da un test molecolare con riscontro negativo eseguito dopo almeno 3 giorni senza sintomi (10 giorni, di cui almeno 3 giorni senza sintomi + test).<\/p>\n<p class=\"lead\">Casi positivi a lungo termine<\/p>\n<p>Le persone che, pur non presentando pi\u00f9 sintomi, continuano a risultare positive, in caso di assenza di sintomatologia da almeno una settimana, potranno interrompere l\u2019isolamento dopo 21 giorni dalla comparsa dei sintomi. Questo criterio potr\u00e0 essere modulato dalle autorit\u00e0 sanitarie d\u2019intesa con gli esperti, tenendo conto dello stato immunitario delle persone interessate.<\/p>\n<p class=\"lead\">Contatti stretti asintomatici<\/p>\n<p>I contatti stretti di casi confermati devono osservare:<\/p>\n<ul>\n<li>un periodo di quarantena di 14 giorni dall\u2019ultima esposizione al caso; oppure<\/li>\n<li>un periodo di quarantena di 10 giorni dall\u2019ultima esposizione con un test antigenico o molecolare negativo effettuato il decimo giorno.<\/li>\n<\/ul>\n<p>Il provvedimento termina con le seguenti raccomandazioni:<\/p>\n<ul>\n<li>eseguire il test molecolare a fine quarantena a tutte le persone che vivono o entrano in contatto regolarmente con soggetti fragili e\/o a rischio;<\/li>\n<li>prevedere accessi al test differenziati per i bambini;<\/li>\n<li>non prevedere quarantena n\u00e9 test diagnostici per i contatti \u00abindiretti\u00bb (<i>i.e.<\/i> contatti di contatti stretti con un soggetto positivo) salvo che il contatto stretto del caso non risulti poi positivo o si renda opportuno uno screening di comunit\u00e0;<\/li>\n<li>promuovere l\u2019uso della App Immuni per supportare le attivit\u00e0 di <i>contact tracing<\/i>.<\/li>\n<\/ul>\n<h2><span style=\"color: #FF0000;\">ATTIVITA\u2019 PROFESSIONALI\u00a0<\/span><\/h2>\n<p>Confermate tutte le raccomandazioni per lo svolgimento delle attivit\u00e0 professionali tra cui l&#8217;utilizzo della modalit\u00e0 di lavoro agile, la fruizione delle ferie e dei congedi retribuiti per i dipendenti, l&#8217;applicazione dei protocolli anti-contagio con adozione di dispositivi di protezione individuale, laddove non fosse possibile rispettare la distanza interpersonale di almeno un metro e la sanificazione dei luoghi di lavoro, anche utilizzando a tal fine gli ammortizzatori sociali.<\/p>\n<h2><span style=\"color: #FF0000;\">ATTIVITA\u2019 PRODUTTIVE E COMMERCIALI\u00a0<\/span><\/h2>\n<p>Confermato l\u2019obbligo di rispettare le misure anti-contagio previste nei protocolli condivisi gi\u00e0 in vigore e propriamente:<\/p>\n<ul>\n<li>il Protocollo tra Governo e parti sociali del 24 aprile 2020 per gli ambienti di lavoro;<\/li>\n<li>il Protocollo tra il Ministero delle infrastrutture, il Ministero del Lavoro e parti sociali del 24 aprile 2020 per i cantieri;<\/li>\n<li>il Protocollo tra il Ministero delle infrastrutture, il Ministero dei Trasporti e parti sociali del 20 marzo 2020 per i settori del trasporto e della logistica.<\/li>\n<\/ul>\n<p>Consentito anche lo svolgimento delle attivit\u00e0 commerciali al dettaglio a condizione che si assicurino il distanziamento, ingressi dilazionati e il divieto di permanenza nei locali pi\u00f9 del tempo necessario all\u2019acquisto.<\/p>\n<h2><span style=\"color: #FF0000;\">SPOSTAMENTI DA E PER L\u2019ESTERO\u00a0<\/span><\/h2>\n<p>Confermato il divieto di ingresso in Italia a chi proviene da Armenia, Bahrein, Bangladesh, Bosnia Erzegovina, Brasile, Cile, Kuwait, Macedonia del nord, Moldova, Oman, Panama, Per\u00f9, Repubblica dominicana, Kosovo, Montenegro e Colombia e dagli altri Stati non compresi negli elenchi allegati al provvedimento. Sono parimenti vietati gli spostamenti verso tali paesi.<\/p>\n<p>Sono fatte salve le limitazioni eventualmente disposte per specifiche aree del territorio nazionale o per determinati Stati ai sensi del DL 33\/2020.<\/p>\n<p>I soggetti che entrano nel territorio italiano dall\u2019estero (dagli Stati espressamente individuati nel decreto) sono tenuti a rispettare, a seconda del paese di provenienza, specifichi obblighi quali: (i) auto-dichiarazione indicante lo Stato in cui si \u00e8 soggiornato, i motivi dello spostamento e i dati utili per il rintracciamento ai fini di una eventuale sorveglianza sanitaria; (ii) attestazione di essersi sottoposto al tampone con esito negativo nelle 72 ore antecedenti all\u2019ingresso o, in alcuni casi, obbligo ad effettuarlo entro le successive 48 ore, se prescritto dall&#8217;autorit\u00e0 sanitaria e (iii) sorveglianza sanitaria e isolamento fiduciario per 14 giorni presso la propria abitazione se disposti dagli operatori di pubblica sanit\u00e0.<\/p>\n<p>In ogni caso, sono esclusi (salvo che insorgano i sintomi del virus) dall\u2019applicazione dei menzionati obblighi:<\/p>\n<ul>\n<li>coloro che entrano in Italia per un periodo non superiore a 120 ore per motivi di lavoro, salute o urgenza;<\/li>\n<li>coloro che transitano nel territorio italiano per un periodo non superiore a 36 ore;<\/li>\n<li>i cittadini degli stati membri dell\u2019Unione Europea o di alcuni paesi extra-EU che entrano in Italia per motivi di lavoro;<\/li>\n<li>alcune categoria di lavoratori in ragione delle loro funzioni (<i>e.g<\/i>. personale sanitario, funzionari e agenti diplomatici, consoli, personale militare e forze di polizia);\u00a0<\/li>\n<li>i lavoratori transfrontalieri;<\/li>\n<li>il personale di imprese aventi sede (legale o secondaria) in Italia per spostamenti all\u2019estero per un periodo non superiore a 120 ore per motivi di lavoro;<\/li>\n<li>gli alunni frequentanti corsi di studio in Stati diversi da quello di residenza.<\/li>\n<\/ul>\n<h2><span style=\"color: #FF0000;\">MASCHERINE E DISTANZA\u00a0<\/span><\/h2>\n<p>Confermato l\u2019obbligo sull\u2019intero territorio nazionale di portare sempre con s\u00e9 la mascherina ed indossarla sia al chiuso (in luoghi diversi dalla propria abitazione) che all\u2019aperto ad eccezione dei casi in cui sia possibile mantenere l\u2019isolamento rispetto alle altre persone non conviventi. Sono in ogni caso fatti salvi i protocolli e le linee guida anti-contagio gi\u00e0 previsti per le attivit\u00e0 economiche e produttive.\u00a0<\/p>\n<p>Sono esclusi dall\u2019obbligo coloro che praticano attivit\u00e0 sportiva, i bambini al di sotto dei 6 anni e i soggetti con patologie incompatibili con tale dispositivo di protezione. Viene inoltre fortemente raccomandato di indossare la mascherina anche in casa in presenza di persone non conviventi.<\/p>\n<p>Sono, infine, confermati il divieto di assembramento, l\u2019obbligo di mantenere la distanza di sicurezza interpersonale di almeno un metro e tutte le altre misure di protezione volte alla riduzione del contagio ivi incluso l\u2019obbligo di permanenza domiciliare per coloro che presentino un\u2019infezione respiratoria con febbre superiore a 37,5\u00b0.<\/p>\n<h2><span style=\"color: #FF0000;\">SPORT \u00a0<\/span><\/h2>\n<p>Consentita per gli eventi e le competizioni sportive una capienza entro e non oltre il 15% di quella massima e, comunque, non superiore ai 1000 partecipanti all\u2019aperto e 200 al chiuso.\u00a0 Sono ammesse l\u2019attivit\u00e0 sportiva di base e quella motoria svolte presso palestre, piscine e circoli sportivi nel rispetto delle norme di distanziamento e senza alcun assembramento. \u00c8 vietato, invece, lo svolgimento a livello amatoriale degli sport di contatto (gare, competizioni e ogni altra attivit\u00e0 connessa) che saranno individuati con successivo provvedimento ministeriale.<\/p>\n<h2><span style=\"color: #FF0000;\">SPETTACOLI E MUSEI\u00a0<\/span><\/h2>\n<p>Confermato per gli spettacoli in teatri e cinema il limite di 200 spettatori al chiuso e 1000 all\u2019aperto; tra i posti necessariamente pre-assegnati deve inoltre essere rispettata la distanza minima di un metro. Qualora non sia possibile evitare assembramenti o applicare le condizioni prescritte, l\u2019evento \u00e8 sospeso. Assicurato anche il servizio di apertura al pubblico di musei e altri luoghi di cultura a condizione che si garantisca una modalit\u00e0 di fruizione contingentata e tale da evitare assembramenti.<\/p>\n<h2><span style=\"color: #FF0000;\">SCUOLA E VIAGGI DI ISTRUZIONE\u00a0<\/span><\/h2>\n<p>Confermata la prosecuzione delle attivit\u00e0 didattiche nelle scuole di ogni ordine e grado e nelle Universit\u00e0 mentre sono sospese le gite scolastiche, cos\u00ec come le iniziative di scambio e gemellaggio e qualsiasi altra uscita didattica, fatte salve le attivit\u00e0 inerenti ai tirocini e all\u2019orientamento.<\/p>\n<h2><span style=\"color: #FF0000;\">MOVIDA E FESTE\u00a0<\/span><\/h2>\n<p>Ammessi i servizi di ristorazione sino alle ore 24:00 con consumo al tavolo e, in mancanza, sino alle 21:00. Permessa anche la consegna a domicilio nonch\u00e9 la ristorazione da asporto ma con divieto di consumazione sul posto dopo le ore 21:00.\u00a0<\/p>\n<p>Restano precluse le attivit\u00e0 che abbiano luogo in discoteche e sale da ballo.\u00a0<\/p>\n<p>Sono, infine, consentite le cerimonie con la partecipazione massima di 30 persone mentre nelle abitazione private \u00e8 fortemente raccomandato di evitare feste e ricevere persone non conviventi in numero superiore a 6.<\/p>\n<p>\u00a0<\/p>\n<p> &#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Ministero della Salute con la Circolare n. 32850 del 12 ottobre 2020 ha aggiornato le indicazioni riguardo la durata e il termine dell\u2019isolamento e della quarantena in considerazione delle nuove evidenze scientifiche e delle indicazioni provenienti da alcuni organismi scientifici e internazionali. Inoltre, il 13 ottobre 2020 il Presidente del Consiglio dei Ministri, in &#8230; <a title=\"NEWSFLASH: Nuovi termini di isolamento e quarantena e nuove misure anti-contagio\" class=\"read-more\" href=\"https:\/\/toffolettodeluca.it\/en\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\/\" aria-label=\"Read more about NEWSFLASH: Nuovi termini di isolamento e quarantena e nuove misure anti-contagio\">Read more<\/a><\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[21],"tags":[145,146],"class_list":["post-2973","post","type-post","status-publish","format-standard","hentry","category-newsflash-insight","tag-coronavirus-en","tag-covid-19-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NEWSFLASH: Nuovi termini di isolamento e quarantena e nuove misure anti-contagio - Toffoletto De Luca Tamajo e Soci<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toffolettodeluca.it\/en\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NEWSFLASH: Nuovi termini di isolamento e quarantena e nuove misure anti-contagio - Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"og:description\" content=\"Il Ministero della Salute con la Circolare n. 32850 del 12 ottobre 2020 ha aggiornato le indicazioni riguardo la durata e il termine dell\u2019isolamento e della quarantena in considerazione delle nuove evidenze scientifiche e delle indicazioni provenienti da alcuni organismi scientifici e internazionali. Inoltre, il 13 ottobre 2020 il Presidente del Consiglio dei Ministri, in ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toffolettodeluca.it\/en\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\/\" \/>\n<meta property=\"og:site_name\" content=\"Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-15T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\"},\"headline\":\"NEWSFLASH: Nuovi termini di isolamento e quarantena e nuove misure anti-contagio\",\"datePublished\":\"2020-10-15T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\\\/\"},\"wordCount\":126,\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"keywords\":[\"Coronavirus\",\"Covid-19\"],\"articleSection\":[\"Newsflash &amp; Insights\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\\\/\",\"name\":\"NEWSFLASH: Nuovi termini di isolamento e quarantena e nuove misure anti-contagio - Toffoletto De Luca Tamajo e Soci\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\"},\"datePublished\":\"2020-10-15T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/studio-diritto-del-lavoro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Learn & Connect\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/learn-connect\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Newsflash &amp; Insights\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/category\\\/newsflash-insight\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"NEWSFLASH: Nuovi termini di isolamento e quarantena e nuove misure anti-contagio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"contentUrl\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"caption\":\"Toffoletto De Luca Tamajo e Soci\"},\"image\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NEWSFLASH: Nuovi termini di isolamento e quarantena e nuove misure anti-contagio - Toffoletto De Luca Tamajo e Soci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toffolettodeluca.it\/en\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\/","og_locale":"en_US","og_type":"article","og_title":"NEWSFLASH: Nuovi termini di isolamento e quarantena e nuove misure anti-contagio - Toffoletto De Luca Tamajo e Soci","og_description":"Il Ministero della Salute con la Circolare n. 32850 del 12 ottobre 2020 ha aggiornato le indicazioni riguardo la durata e il termine dell\u2019isolamento e della quarantena in considerazione delle nuove evidenze scientifiche e delle indicazioni provenienti da alcuni organismi scientifici e internazionali. Inoltre, il 13 ottobre 2020 il Presidente del Consiglio dei Ministri, in ... Read more","og_url":"https:\/\/toffolettodeluca.it\/en\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\/","og_site_name":"Toffoletto De Luca Tamajo e Soci","article_published_time":"2020-10-15T00:00:00+00:00","author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redazione","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/toffolettodeluca.it\/en\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\/#article","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\/"},"author":{"name":"Redazione","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559"},"headline":"NEWSFLASH: Nuovi termini di isolamento e quarantena e nuove misure anti-contagio","datePublished":"2020-10-15T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/toffolettodeluca.it\/en\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\/"},"wordCount":126,"publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"keywords":["Coronavirus","Covid-19"],"articleSection":["Newsflash &amp; Insights"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/toffolettodeluca.it\/en\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\/","url":"https:\/\/toffolettodeluca.it\/en\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\/","name":"NEWSFLASH: Nuovi termini di isolamento e quarantena e nuove misure anti-contagio - Toffoletto De Luca Tamajo e Soci","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/#website"},"datePublished":"2020-10-15T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/toffolettodeluca.it\/en\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toffolettodeluca.it\/en\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/toffolettodeluca.it\/en\/newsflash-nuovi-termini-di-isolamento-e-quarantena-e-nuove-misure-anti-contagio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toffolettodeluca.it\/en\/studio-diritto-del-lavoro\/"},{"@type":"ListItem","position":2,"name":"Learn & Connect","item":"https:\/\/toffolettodeluca.it\/en\/learn-connect\/"},{"@type":"ListItem","position":3,"name":"Newsflash &amp; Insights","item":"https:\/\/toffolettodeluca.it\/en\/category\/newsflash-insight\/"},{"@type":"ListItem","position":4,"name":"NEWSFLASH: Nuovi termini di isolamento e quarantena e nuove misure anti-contagio"}]},{"@type":"WebSite","@id":"https:\/\/toffolettodeluca.it\/en\/#website","url":"https:\/\/toffolettodeluca.it\/en\/","name":"Toffoletto De Luca Tamajo e Soci","description":"","publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toffolettodeluca.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/toffolettodeluca.it\/en\/#organization","name":"Toffoletto De Luca Tamajo e Soci","url":"https:\/\/toffolettodeluca.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","contentUrl":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","caption":"Toffoletto De Luca Tamajo e Soci"},"image":{"@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/toffolettodeluca.it\/en\/author\/redazione\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/2973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/comments?post=2973"}],"version-history":[{"count":0,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/2973\/revisions"}],"wp:attachment":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/media?parent=2973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/categories?post=2973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/tags?post=2973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}