{"id":3007,"date":"2021-04-20T00:00:00","date_gmt":"2021-04-20T00:00:00","guid":{"rendered":"https:\/\/toffolettodeluca.it\/\/50-congresso-nazionale-aidp-ripartire-da-nuove-organizzazioni-per-persone-nuove\/"},"modified":"2024-09-18T11:05:08","modified_gmt":"2024-09-18T11:05:08","slug":"50th-national-aidp-congress","status":"publish","type":"post","link":"https:\/\/toffolettodeluca.it\/en\/50th-national-aidp-congress\/","title":{"rendered":"50th National AIDP Congress: #Restarting with New Organizations for New People"},"content":{"rendered":"<p>Il 21 aprile e 21 maggio saremo al <strong>Congresso nazionale AIDP \u2013 Associazione Italiana Direttori del Personale<\/strong>. Un appuntamento importante per chi si occupa di <strong>risorse umane in azienda<\/strong>, soprattutto dopo un anno che ha messo a dura prova le <strong>organizzazioni<\/strong>.\u00a0<\/p>\n<p>Con la platea degli <strong>HR<\/strong> ci confronteremo sul futuro del lavoro, che si modifica grazie agli strumenti sperimentati come lo <strong>smart working<\/strong> ed evolve con una presenza sempre pi\u00f9 importante della <strong>digitalizzazione<\/strong>. Come dopo ogni crisi o rivoluzione, anche in questo caso assisteremo alla scomparsa di alcune professioni ed al cambiamento di molte altre.<\/p>\n<ul style=\">\n<li><strong>21 aprile 2021 ore 17:00 &#8211; #Snodo1 Digitale e intelligenza umana<\/strong><\/li>\n<\/ul>\n<p style=margin-left: 40px;\">Prima giornata di Congresso in cui interverr\u00e0 l\u2019avvocato Franco Toffoletto introducendo la lectio magistralis di Massimo Recalcati.\u00a0<\/p>\n<ul style=\"\">\n<li><strong>21 maggio 2021 ore 10:00 \u2013 Congresso nazionale AIDP giornata conclusiva<\/strong><\/li>\n<\/ul>\n<p style=\"margin-left: 40px;\">#snodo in azione Digitale e intelligenza umana<\/p>\n<p style=\"margin-left: 40px;\">Introduzione su Innovazione e smart working people da parte di Carlo Ratti Architetto, ingegnere, Direttore del Senseable City Laboratory al MIT, imprenditore<\/p>\n<p style=\"margin-left: 40px;\">Tavola rotonda su<strong> Digitale e Intelligenza <\/strong>umana con:\u00a0<\/p>\n<ul style=\"margin-left: 40px;\">\n<li>Franco Toffoletto, Managing Partner Toffoletto De Luca Tamajo<\/li>\n<li>Cinzia Campanini, Head of HR EMEA &amp; Global HRBP Vizrt<\/li>\n<li>Luigi Ruggerone, Head of Innovation Research and Development Intesa San Paolo<\/li>\n<li>Renato Mannozzi, Human Resources Manager IBM<\/li>\n<\/ul>\n<p>L\u2019avvocato Aldo Bottini, partner dello Studio, condurr\u00e0 il workshop speciale dedicato allo <strong>smart working<\/strong>, uno strumento per incrementare la produttivit\u00e0, abbassare i costi e soddisfare i propri dipendenti. In quali settori \u00e8 consigliato e come applicarlo al meglio con esempi concreti di chi lo ha sperimentato prima, durante e si sta preparando al dopo.<\/p>\n<ul style=\"\">\n<li><strong>Luned\u00ec 26 aprile<\/strong><\/li>\n<li><strong>Venerd\u00ec 7 maggio<\/strong><\/li>\n<\/ul>\n<p><strong>Dalle ore 17.00 alle ore 19.00<\/strong><\/p>\n<p>Con Aldo Bottini, Partner di Toffoletto De Luca Tamajo; Silvia Cassano, Head of Human Resources ING Bank Italia e Paola Magliano, AIDP<\/p>\n<p>Per l\u2019agenda completa e il link per l\u2019iscrizione:\u00a0<a href=\"https:\/\/congresso.aidp.it\/lagenda.php\">https:\/\/congresso.aidp.it\/lagenda.php<\/a><\/p>\n<p>\u00a0<\/p>\n<p> &#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 21 aprile e 21 maggio saremo al Congresso nazionale AIDP \u2013 Associazione Italiana Direttori del Personale. Un appuntamento importante per chi si occupa di risorse umane in azienda, soprattutto dopo un anno che ha messo a dura prova le organizzazioni.\u00a0 Con la platea degli HR ci confronteremo sul futuro del lavoro, che si modifica &#8230; <a title=\"50th National AIDP Congress: #Restarting with New Organizations for New People\" class=\"read-more\" href=\"https:\/\/toffolettodeluca.it\/en\/50th-national-aidp-congress\/\" aria-label=\"Read more about 50th National AIDP Congress: #Restarting with New Organizations for New People\">Read more<\/a><\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[21],"tags":[144],"class_list":["post-3007","post","type-post","status-publish","format-standard","hentry","category-newsflash-insight","tag-convegni-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>50th National AIDP Congress: #Restarting with New Organizations for New People P | Toffoletto De Luca Tamajo<\/title>\n<meta name=\"description\" content=\"50th National AIDP Congress: Restarting with New Organizations for New People. Visit toffolettodeluca.it\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toffolettodeluca.it\/en\/50th-national-aidp-congress\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"50th National AIDP Congress: #Restarting with New Organizations for New People P | Toffoletto De Luca Tamajo\" \/>\n<meta property=\"og:description\" content=\"50th National AIDP Congress: Restarting with New Organizations for New People. Visit toffolettodeluca.it\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toffolettodeluca.it\/en\/50th-national-aidp-congress\/\" \/>\n<meta property=\"og:site_name\" content=\"Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-20T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-18T11:05:08+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/50th-national-aidp-congress\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/50th-national-aidp-congress\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\"},\"headline\":\"50th National AIDP Congress: #Restarting with New Organizations for New People\",\"datePublished\":\"2021-04-20T00:00:00+00:00\",\"dateModified\":\"2024-09-18T11:05:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/50th-national-aidp-congress\\\/\"},\"wordCount\":300,\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"keywords\":[\"Conference\"],\"articleSection\":[\"Newsflash &amp; Insights\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/50th-national-aidp-congress\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/50th-national-aidp-congress\\\/\",\"name\":\"50th National AIDP Congress: #Restarting with New Organizations for New People P | Toffoletto De Luca Tamajo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\"},\"datePublished\":\"2021-04-20T00:00:00+00:00\",\"dateModified\":\"2024-09-18T11:05:08+00:00\",\"description\":\"50th National AIDP Congress: Restarting with New Organizations for New People. Visit toffolettodeluca.it\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/50th-national-aidp-congress\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/50th-national-aidp-congress\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/50th-national-aidp-congress\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/studio-diritto-del-lavoro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Learn & Connect\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/learn-connect\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Newsflash &amp; Insights\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/category\\\/newsflash-insight\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"50th National AIDP Congress: #Restarting with New Organizations for New People\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"contentUrl\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"caption\":\"Toffoletto De Luca Tamajo e Soci\"},\"image\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"50th National AIDP Congress: #Restarting with New Organizations for New People P | Toffoletto De Luca Tamajo","description":"50th National AIDP Congress: Restarting with New Organizations for New People. Visit toffolettodeluca.it","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toffolettodeluca.it\/en\/50th-national-aidp-congress\/","og_locale":"en_US","og_type":"article","og_title":"50th National AIDP Congress: #Restarting with New Organizations for New People P | Toffoletto De Luca Tamajo","og_description":"50th National AIDP Congress: Restarting with New Organizations for New People. Visit toffolettodeluca.it","og_url":"https:\/\/toffolettodeluca.it\/en\/50th-national-aidp-congress\/","og_site_name":"Toffoletto De Luca Tamajo e Soci","article_published_time":"2021-04-20T00:00:00+00:00","article_modified_time":"2024-09-18T11:05:08+00:00","author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redazione","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/toffolettodeluca.it\/en\/50th-national-aidp-congress\/#article","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/50th-national-aidp-congress\/"},"author":{"name":"Redazione","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559"},"headline":"50th National AIDP Congress: #Restarting with New Organizations for New People","datePublished":"2021-04-20T00:00:00+00:00","dateModified":"2024-09-18T11:05:08+00:00","mainEntityOfPage":{"@id":"https:\/\/toffolettodeluca.it\/en\/50th-national-aidp-congress\/"},"wordCount":300,"publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"keywords":["Conference"],"articleSection":["Newsflash &amp; Insights"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/toffolettodeluca.it\/en\/50th-national-aidp-congress\/","url":"https:\/\/toffolettodeluca.it\/en\/50th-national-aidp-congress\/","name":"50th National AIDP Congress: #Restarting with New Organizations for New People P | Toffoletto De Luca Tamajo","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/#website"},"datePublished":"2021-04-20T00:00:00+00:00","dateModified":"2024-09-18T11:05:08+00:00","description":"50th National AIDP Congress: Restarting with New Organizations for New People. Visit toffolettodeluca.it","breadcrumb":{"@id":"https:\/\/toffolettodeluca.it\/en\/50th-national-aidp-congress\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toffolettodeluca.it\/en\/50th-national-aidp-congress\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/toffolettodeluca.it\/en\/50th-national-aidp-congress\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toffolettodeluca.it\/en\/studio-diritto-del-lavoro\/"},{"@type":"ListItem","position":2,"name":"Learn & Connect","item":"https:\/\/toffolettodeluca.it\/en\/learn-connect\/"},{"@type":"ListItem","position":3,"name":"Newsflash &amp; Insights","item":"https:\/\/toffolettodeluca.it\/en\/category\/newsflash-insight\/"},{"@type":"ListItem","position":4,"name":"50th National AIDP Congress: #Restarting with New Organizations for New People"}]},{"@type":"WebSite","@id":"https:\/\/toffolettodeluca.it\/en\/#website","url":"https:\/\/toffolettodeluca.it\/en\/","name":"Toffoletto De Luca Tamajo e Soci","description":"","publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toffolettodeluca.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/toffolettodeluca.it\/en\/#organization","name":"Toffoletto De Luca Tamajo e Soci","url":"https:\/\/toffolettodeluca.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","contentUrl":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","caption":"Toffoletto De Luca Tamajo e Soci"},"image":{"@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/toffolettodeluca.it\/en\/author\/redazione\/"}]}},"modified_by":"Valentina Degirolamo","_links":{"self":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/3007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/comments?post=3007"}],"version-history":[{"count":2,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/3007\/revisions"}],"predecessor-version":[{"id":7814,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/3007\/revisions\/7814"}],"wp:attachment":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/media?parent=3007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/categories?post=3007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/tags?post=3007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}