{"id":3023,"date":"2018-05-15T00:00:00","date_gmt":"2018-05-15T00:00:00","guid":{"rendered":"https:\/\/toffolettodeluca.it\/\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\/"},"modified":"2018-05-15T00:00:00","modified_gmt":"2018-05-15T00:00:00","slug":"il-punto-sui-temi-caldi-nel-diritto-del-lavoro","status":"publish","type":"post","link":"https:\/\/toffolettodeluca.it\/en\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\/","title":{"rendered":"Il punto sui temi caldi nel diritto del lavoro"},"content":{"rendered":"<p>L\u2019avvocato  <a href=\"https:\/\/toffolettodeluca.it\/it\/avvocati-diritto-del-lavoro\/i-nostri-soci\/aldo.bottini\/\" >Aldo Bottini<\/a>  , partner dello Studio, coordiner\u00e0 il convegno \u201cHOT ISSUES NEL DIRITTO DEL LAVORO\u201d organizzato domani 16 maggio a Milano da AIDP Lombardia, AGI e Ordine degli Avvocati di Milano.\u00a0<br \/> \u00a0<br \/> Un appuntamento per fare il punto sui temi pi\u00f9 caldi del settore e approfondire le novit\u00e0 per le imprese e gli HR. Molti gli argomenti oggetto di approfondimenti da parte degli esperti di diritto del lavoro, dal whistleblowing alla delocalizzazione. dalle molestie sui luoghi di lavoro all\u2019assenteismo, fino alle nuove regole sulla privacy e sui controlli dei lavoratori. Per affrontare tutte queste novit\u00e0, Toffoletto De Luca Tamajo ha ideato dei prodotti dedicati: team specializzati &#8211; GDPR e Privacy, Procedure articolo 4 e utilizzo degli strumenti informatici, Whistleblowing, Welfare, Smart Working, Strumenti di incentivazione retributiva, Contratti su misura online &#8211; che offrono servizi specifici pi\u00f9 efficienti e ad alto valore aggiunto, con una qualit\u00e0 molto elevata, a un costo preciso e predefinito.\u00a0<\/p>\n<p> &#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019avvocato Aldo Bottini , partner dello Studio, coordiner\u00e0 il convegno \u201cHOT ISSUES NEL DIRITTO DEL LAVORO\u201d organizzato domani 16 maggio a Milano da AIDP Lombardia, AGI e Ordine degli Avvocati di Milano.\u00a0 \u00a0 Un appuntamento per fare il punto sui temi pi\u00f9 caldi del settore e approfondire le novit\u00e0 per le imprese e gli HR. &#8230; <a title=\"Il punto sui temi caldi nel diritto del lavoro\" class=\"read-more\" href=\"https:\/\/toffolettodeluca.it\/en\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\/\" aria-label=\"Read more about Il punto sui temi caldi nel diritto del lavoro\">Read more<\/a><\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[21],"tags":[144],"class_list":["post-3023","post","type-post","status-publish","format-standard","hentry","category-newsflash-insight","tag-convegni-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il punto sui temi caldi nel diritto del lavoro - Toffoletto De Luca Tamajo e Soci<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toffolettodeluca.it\/en\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il punto sui temi caldi nel diritto del lavoro - Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"og:description\" content=\"L\u2019avvocato Aldo Bottini , partner dello Studio, coordiner\u00e0 il convegno \u201cHOT ISSUES NEL DIRITTO DEL LAVORO\u201d organizzato domani 16 maggio a Milano da AIDP Lombardia, AGI e Ordine degli Avvocati di Milano.\u00a0 \u00a0 Un appuntamento per fare il punto sui temi pi\u00f9 caldi del settore e approfondire le novit\u00e0 per le imprese e gli HR. ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toffolettodeluca.it\/en\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\/\" \/>\n<meta property=\"og:site_name\" content=\"Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-15T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\"},\"headline\":\"Il punto sui temi caldi nel diritto del lavoro\",\"datePublished\":\"2018-05-15T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\\\/\"},\"wordCount\":161,\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"keywords\":[\"Conference\"],\"articleSection\":[\"Newsflash &amp; Insights\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\\\/\",\"name\":\"Il punto sui temi caldi nel diritto del lavoro - Toffoletto De Luca Tamajo e Soci\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\"},\"datePublished\":\"2018-05-15T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/studio-diritto-del-lavoro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Learn & Connect\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/learn-connect\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Newsflash &amp; Insights\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/category\\\/newsflash-insight\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Il punto sui temi caldi nel diritto del lavoro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"contentUrl\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"caption\":\"Toffoletto De Luca Tamajo e Soci\"},\"image\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il punto sui temi caldi nel diritto del lavoro - Toffoletto De Luca Tamajo e Soci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toffolettodeluca.it\/en\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\/","og_locale":"en_US","og_type":"article","og_title":"Il punto sui temi caldi nel diritto del lavoro - Toffoletto De Luca Tamajo e Soci","og_description":"L\u2019avvocato Aldo Bottini , partner dello Studio, coordiner\u00e0 il convegno \u201cHOT ISSUES NEL DIRITTO DEL LAVORO\u201d organizzato domani 16 maggio a Milano da AIDP Lombardia, AGI e Ordine degli Avvocati di Milano.\u00a0 \u00a0 Un appuntamento per fare il punto sui temi pi\u00f9 caldi del settore e approfondire le novit\u00e0 per le imprese e gli HR. ... Read more","og_url":"https:\/\/toffolettodeluca.it\/en\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\/","og_site_name":"Toffoletto De Luca Tamajo e Soci","article_published_time":"2018-05-15T00:00:00+00:00","author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redazione","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/toffolettodeluca.it\/en\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\/#article","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\/"},"author":{"name":"Redazione","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559"},"headline":"Il punto sui temi caldi nel diritto del lavoro","datePublished":"2018-05-15T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/toffolettodeluca.it\/en\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\/"},"wordCount":161,"publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"keywords":["Conference"],"articleSection":["Newsflash &amp; Insights"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/toffolettodeluca.it\/en\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\/","url":"https:\/\/toffolettodeluca.it\/en\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\/","name":"Il punto sui temi caldi nel diritto del lavoro - Toffoletto De Luca Tamajo e Soci","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/#website"},"datePublished":"2018-05-15T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/toffolettodeluca.it\/en\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toffolettodeluca.it\/en\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/toffolettodeluca.it\/en\/il-punto-sui-temi-caldi-nel-diritto-del-lavoro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toffolettodeluca.it\/en\/studio-diritto-del-lavoro\/"},{"@type":"ListItem","position":2,"name":"Learn & Connect","item":"https:\/\/toffolettodeluca.it\/en\/learn-connect\/"},{"@type":"ListItem","position":3,"name":"Newsflash &amp; Insights","item":"https:\/\/toffolettodeluca.it\/en\/category\/newsflash-insight\/"},{"@type":"ListItem","position":4,"name":"Il punto sui temi caldi nel diritto del lavoro"}]},{"@type":"WebSite","@id":"https:\/\/toffolettodeluca.it\/en\/#website","url":"https:\/\/toffolettodeluca.it\/en\/","name":"Toffoletto De Luca Tamajo e Soci","description":"","publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toffolettodeluca.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/toffolettodeluca.it\/en\/#organization","name":"Toffoletto De Luca Tamajo e Soci","url":"https:\/\/toffolettodeluca.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","contentUrl":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","caption":"Toffoletto De Luca Tamajo e Soci"},"image":{"@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/toffolettodeluca.it\/en\/author\/redazione\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/3023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/comments?post=3023"}],"version-history":[{"count":0,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/3023\/revisions"}],"wp:attachment":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/media?parent=3023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/categories?post=3023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/tags?post=3023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}