{"id":3044,"date":"2019-04-03T00:00:00","date_gmt":"2019-04-03T00:00:00","guid":{"rendered":"https:\/\/toffolettodeluca.it\/\/iba-annual-employment-and-diversity-law-conference-2019\/"},"modified":"2019-04-03T00:00:00","modified_gmt":"2019-04-03T00:00:00","slug":"iba-annual-employment-and-diversity-law-conference-2019","status":"publish","type":"post","link":"https:\/\/toffolettodeluca.it\/en\/iba-annual-employment-and-diversity-law-conference-2019\/","title":{"rendered":"IBA Annual employment and diversity law conference 2019"},"content":{"rendered":"<p>Il punto su diritto del lavoro e diversity sar\u00e0 al centro della conferenza annuale di<strong> IBA Employment and diversity law<\/strong>, in corso dal 3 al 5 aprile a Parigi.<\/p>\n<p>Toffoletto De Luca Tamajo interverr\u00e0 gioved\u00ec 4 ai tavoli di confronto su due temi cruciali per la gestione delle organizzazioni. L\u2019 <a href=\"https:\/\/toffolettodeluca.it\/it\/avvocati-diritto-del-lavoro\/i-nostri-soci\/Valeria.Morosini\/\" >avvocato Valeria Morosini<\/a>  , partner dello studio e co-chair di IBA Diversity and equality law committee, parteciper\u00e0 alla sessione \u00ab<em><strong>Communications in crisis management<\/strong><\/em>\u00bb, un focus sui rischi legali o legati alla brand reputation e le buone pratiche della comunicazione in un momento di crisi aziendale, anche in merito al rapporto tra advisor legali e consulenti di comunicazione.\u00a0<\/p>\n<p>L\u2019 <a href=\"https:\/\/toffolettodeluca.it\/en-gb\/our-employment-lawyers\/our-people\/Valeria.Morosini\/\" >avvocato Emanuela Nespoli<\/a>   interverr\u00e0 sui benefit aziendali in particolare al potenziale mantenimento al termine del contratto di lavoro nella tavola rotonda \u00ab<em><strong>Vanishing benefits: incentive compensation following dismissal<\/strong><\/em>\u00bb.<\/p>\n<p>A questo link il programma completo:\u00a0<a href=\"https:\/\/www.int-bar.org\/Conferences\/conf920\/binary\/Paris-Employment-2019%20programme.pdf\">https:\/\/www.int-bar.org\/Conferences\/conf920\/binary\/Paris-Employment-2019%20programme.pdf<\/a><\/p>\n<p> &#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il punto su diritto del lavoro e diversity sar\u00e0 al centro della conferenza annuale di IBA Employment and diversity law, in corso dal 3 al 5 aprile a Parigi. Toffoletto De Luca Tamajo interverr\u00e0 gioved\u00ec 4 ai tavoli di confronto su due temi cruciali per la gestione delle organizzazioni. L\u2019 avvocato Valeria Morosini , partner &#8230; <a title=\"IBA Annual employment and diversity law conference 2019\" class=\"read-more\" href=\"https:\/\/toffolettodeluca.it\/en\/iba-annual-employment-and-diversity-law-conference-2019\/\" aria-label=\"Read more about IBA Annual employment and diversity law conference 2019\">Read more<\/a><\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[21],"tags":[144,139],"class_list":["post-3044","post","type-post","status-publish","format-standard","hentry","category-newsflash-insight","tag-convegni-en","tag-conferences-and-seminars-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IBA Annual employment and diversity law conference 2019 - Toffoletto De Luca Tamajo e Soci<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toffolettodeluca.it\/en\/iba-annual-employment-and-diversity-law-conference-2019\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IBA Annual employment and diversity law conference 2019 - Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"og:description\" content=\"Il punto su diritto del lavoro e diversity sar\u00e0 al centro della conferenza annuale di IBA Employment and diversity law, in corso dal 3 al 5 aprile a Parigi. Toffoletto De Luca Tamajo interverr\u00e0 gioved\u00ec 4 ai tavoli di confronto su due temi cruciali per la gestione delle organizzazioni. L\u2019 avvocato Valeria Morosini , partner ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toffolettodeluca.it\/en\/iba-annual-employment-and-diversity-law-conference-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-03T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/iba-annual-employment-and-diversity-law-conference-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/iba-annual-employment-and-diversity-law-conference-2019\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\"},\"headline\":\"IBA Annual employment and diversity law conference 2019\",\"datePublished\":\"2019-04-03T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/iba-annual-employment-and-diversity-law-conference-2019\\\/\"},\"wordCount\":154,\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"keywords\":[\"Conference\",\"Conferences and Seminars\"],\"articleSection\":[\"Newsflash &amp; Insights\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/iba-annual-employment-and-diversity-law-conference-2019\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/iba-annual-employment-and-diversity-law-conference-2019\\\/\",\"name\":\"IBA Annual employment and diversity law conference 2019 - Toffoletto De Luca Tamajo e Soci\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\"},\"datePublished\":\"2019-04-03T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/iba-annual-employment-and-diversity-law-conference-2019\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/iba-annual-employment-and-diversity-law-conference-2019\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/iba-annual-employment-and-diversity-law-conference-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/studio-diritto-del-lavoro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Learn & Connect\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/learn-connect\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Newsflash &amp; Insights\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/category\\\/newsflash-insight\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"IBA Annual employment and diversity law conference 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"contentUrl\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"caption\":\"Toffoletto De Luca Tamajo e Soci\"},\"image\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IBA Annual employment and diversity law conference 2019 - Toffoletto De Luca Tamajo e Soci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toffolettodeluca.it\/en\/iba-annual-employment-and-diversity-law-conference-2019\/","og_locale":"en_US","og_type":"article","og_title":"IBA Annual employment and diversity law conference 2019 - Toffoletto De Luca Tamajo e Soci","og_description":"Il punto su diritto del lavoro e diversity sar\u00e0 al centro della conferenza annuale di IBA Employment and diversity law, in corso dal 3 al 5 aprile a Parigi. Toffoletto De Luca Tamajo interverr\u00e0 gioved\u00ec 4 ai tavoli di confronto su due temi cruciali per la gestione delle organizzazioni. L\u2019 avvocato Valeria Morosini , partner ... Read more","og_url":"https:\/\/toffolettodeluca.it\/en\/iba-annual-employment-and-diversity-law-conference-2019\/","og_site_name":"Toffoletto De Luca Tamajo e Soci","article_published_time":"2019-04-03T00:00:00+00:00","author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redazione","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/toffolettodeluca.it\/en\/iba-annual-employment-and-diversity-law-conference-2019\/#article","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/iba-annual-employment-and-diversity-law-conference-2019\/"},"author":{"name":"Redazione","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559"},"headline":"IBA Annual employment and diversity law conference 2019","datePublished":"2019-04-03T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/toffolettodeluca.it\/en\/iba-annual-employment-and-diversity-law-conference-2019\/"},"wordCount":154,"publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"keywords":["Conference","Conferences and Seminars"],"articleSection":["Newsflash &amp; Insights"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/toffolettodeluca.it\/en\/iba-annual-employment-and-diversity-law-conference-2019\/","url":"https:\/\/toffolettodeluca.it\/en\/iba-annual-employment-and-diversity-law-conference-2019\/","name":"IBA Annual employment and diversity law conference 2019 - Toffoletto De Luca Tamajo e Soci","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/#website"},"datePublished":"2019-04-03T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/toffolettodeluca.it\/en\/iba-annual-employment-and-diversity-law-conference-2019\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toffolettodeluca.it\/en\/iba-annual-employment-and-diversity-law-conference-2019\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/toffolettodeluca.it\/en\/iba-annual-employment-and-diversity-law-conference-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toffolettodeluca.it\/en\/studio-diritto-del-lavoro\/"},{"@type":"ListItem","position":2,"name":"Learn & Connect","item":"https:\/\/toffolettodeluca.it\/en\/learn-connect\/"},{"@type":"ListItem","position":3,"name":"Newsflash &amp; Insights","item":"https:\/\/toffolettodeluca.it\/en\/category\/newsflash-insight\/"},{"@type":"ListItem","position":4,"name":"IBA Annual employment and diversity law conference 2019"}]},{"@type":"WebSite","@id":"https:\/\/toffolettodeluca.it\/en\/#website","url":"https:\/\/toffolettodeluca.it\/en\/","name":"Toffoletto De Luca Tamajo e Soci","description":"","publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toffolettodeluca.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/toffolettodeluca.it\/en\/#organization","name":"Toffoletto De Luca Tamajo e Soci","url":"https:\/\/toffolettodeluca.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","contentUrl":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","caption":"Toffoletto De Luca Tamajo e Soci"},"image":{"@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/toffolettodeluca.it\/en\/author\/redazione\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/3044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/comments?post=3044"}],"version-history":[{"count":0,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/3044\/revisions"}],"wp:attachment":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/media?parent=3044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/categories?post=3044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/tags?post=3044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}