{"id":3105,"date":"2017-11-14T00:00:00","date_gmt":"2017-11-14T00:00:00","guid":{"rendered":"https:\/\/toffolettodeluca.it\/\/toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo\/"},"modified":"2017-11-14T00:00:00","modified_gmt":"2017-11-14T00:00:00","slug":"toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo","status":"publish","type":"post","link":"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo\/","title":{"rendered":"Toffoletto De Luca Tamajo: The new EU General Data Protection Regulation at Confindustria Bergamo"},"content":{"rendered":"<p>Bergamo, 14\/11\/2017.\u00a0<strong>Confindustria Bergamo<\/strong>, in collaborazione con <strong>Toffoletto De Luca Tamajo<\/strong>, organizza oggi a Bergamo il convegno \u201c<strong>Il nuovo Regolamento europeo sulla protezione dei dati personali<\/strong>\u201d\u00a0per approfondire le novit\u00e0 introdotte dal GDPR a soli sei mesi dalla sua efficacia, il <span style=color: #FF0000;\">25 maggio 2018<\/span>, e\u00a0direttamente applicabile a tutti gli Stati membri dell\u2019Unione Europea.\u00a0<\/p>\n<p>L\u2019 <a href=\"https:\/\/toffolettodeluca.it\/it\/avvocati-diritto-del-lavoro\/i-nostri-soci\/Paola.Pucci\/\" >avvocato Paola Pucci<\/a>  , partner di Toffoletto De Luca Tamajo e responsabile della\u00a0task force specializzata in consulenza alle imprese nel data privacy audit, presenter\u00e0, attraverso l\u2019analisi di un caso di data\u00a0breach,\u00a0la responsabilit\u00e0 in materia di trattamento dei dati personali e il risarcimento del danno, il nuovo regime sanzionatorio e gli accorgimenti operativi con cui le aziende si dovranno confrontare.\u00a0<\/p>\n<p> &#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bergamo, 14\/11\/2017.\u00a0Confindustria Bergamo, in collaborazione con Toffoletto De Luca Tamajo, organizza oggi a Bergamo il convegno \u201cIl nuovo Regolamento europeo sulla protezione dei dati personali\u201d\u00a0per approfondire le novit\u00e0 introdotte dal GDPR a soli sei mesi dalla sua efficacia, il<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[21],"tags":[],"class_list":["post-3105","post","type-post","status-publish","format-standard","hentry","category-newsflash-insight"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Toffoletto De Luca Tamajo: The new EU General Data Protection Regulation at Confindustria Bergamo - Toffoletto De Luca Tamajo e Soci<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Toffoletto De Luca Tamajo: The new EU General Data Protection Regulation at Confindustria Bergamo - Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"og:description\" content=\"Bergamo, 14\/11\/2017.\u00a0Confindustria Bergamo, in collaborazione con Toffoletto De Luca Tamajo, organizza oggi a Bergamo il convegno \u201cIl nuovo Regolamento europeo sulla protezione dei dati personali\u201d\u00a0per approfondire le novit\u00e0 introdotte dal GDPR a soli sei mesi dalla sua efficacia, il\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo\/\" \/>\n<meta property=\"og:site_name\" content=\"Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-14T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\"},\"headline\":\"Toffoletto De Luca Tamajo: The new EU General Data Protection Regulation at Confindustria Bergamo\",\"datePublished\":\"2017-11-14T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo\\\/\"},\"wordCount\":54,\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"articleSection\":[\"Newsflash &amp; Insights\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo\\\/\",\"name\":\"Toffoletto De Luca Tamajo: The new EU General Data Protection Regulation at Confindustria Bergamo - Toffoletto De Luca Tamajo e Soci\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\"},\"datePublished\":\"2017-11-14T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/studio-diritto-del-lavoro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Learn & Connect\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/learn-connect\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Newsflash &amp; Insights\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/category\\\/newsflash-insight\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Toffoletto De Luca Tamajo: The new EU General Data Protection Regulation at Confindustria Bergamo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"contentUrl\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"caption\":\"Toffoletto De Luca Tamajo e Soci\"},\"image\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Toffoletto De Luca Tamajo: The new EU General Data Protection Regulation at Confindustria Bergamo - Toffoletto De Luca Tamajo e Soci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo\/","og_locale":"en_US","og_type":"article","og_title":"Toffoletto De Luca Tamajo: The new EU General Data Protection Regulation at Confindustria Bergamo - Toffoletto De Luca Tamajo e Soci","og_description":"Bergamo, 14\/11\/2017.\u00a0Confindustria Bergamo, in collaborazione con Toffoletto De Luca Tamajo, organizza oggi a Bergamo il convegno \u201cIl nuovo Regolamento europeo sulla protezione dei dati personali\u201d\u00a0per approfondire le novit\u00e0 introdotte dal GDPR a soli sei mesi dalla sua efficacia, il","og_url":"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo\/","og_site_name":"Toffoletto De Luca Tamajo e Soci","article_published_time":"2017-11-14T00:00:00+00:00","author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo\/#article","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo\/"},"author":{"name":"Redazione","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559"},"headline":"Toffoletto De Luca Tamajo: The new EU General Data Protection Regulation at Confindustria Bergamo","datePublished":"2017-11-14T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo\/"},"wordCount":54,"publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"articleSection":["Newsflash &amp; Insights"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo\/","url":"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo\/","name":"Toffoletto De Luca Tamajo: The new EU General Data Protection Regulation at Confindustria Bergamo - Toffoletto De Luca Tamajo e Soci","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/#website"},"datePublished":"2017-11-14T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-the-new-eu-general-data-protection-regulation-at-confindustria-bergamo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toffolettodeluca.it\/en\/studio-diritto-del-lavoro\/"},{"@type":"ListItem","position":2,"name":"Learn & Connect","item":"https:\/\/toffolettodeluca.it\/en\/learn-connect\/"},{"@type":"ListItem","position":3,"name":"Newsflash &amp; Insights","item":"https:\/\/toffolettodeluca.it\/en\/category\/newsflash-insight\/"},{"@type":"ListItem","position":4,"name":"Toffoletto De Luca Tamajo: The new EU General Data Protection Regulation at Confindustria Bergamo"}]},{"@type":"WebSite","@id":"https:\/\/toffolettodeluca.it\/en\/#website","url":"https:\/\/toffolettodeluca.it\/en\/","name":"Toffoletto De Luca Tamajo e Soci","description":"","publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toffolettodeluca.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/toffolettodeluca.it\/en\/#organization","name":"Toffoletto De Luca Tamajo e Soci","url":"https:\/\/toffolettodeluca.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","contentUrl":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","caption":"Toffoletto De Luca Tamajo e Soci"},"image":{"@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/toffolettodeluca.it\/en\/author\/redazione\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/3105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/comments?post=3105"}],"version-history":[{"count":0,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/3105\/revisions"}],"wp:attachment":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/media?parent=3105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/categories?post=3105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/tags?post=3105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}