{"id":3118,"date":"2019-02-06T00:00:00","date_gmt":"2019-02-06T00:00:00","guid":{"rendered":"https:\/\/toffolettodeluca.it\/\/incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale\/"},"modified":"2019-02-06T00:00:00","modified_gmt":"2019-02-06T00:00:00","slug":"incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale","status":"publish","type":"post","link":"https:\/\/toffolettodeluca.it\/en\/incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale\/","title":{"rendered":"Incentivi per le assunzioni e per il ricambio generazionale"},"content":{"rendered":"<p>Di seguito l\u2019analisi delle principali misure introdotte dal Decreto Legge n. 4 del 28 gennaio 2019.<\/p>\n<p><span style=color: #FF0000;\"><b>INCENTIVI PER LE IMPRESE CHE ASSUMONO I BENEFICIARI DEL REDDITO DI CITTADINANZA (art. 8)<\/b><\/span><\/p>\n<p>Previsti incentivi per le imprese che assumono i titolari del reddito di cittadinanza (RDC), misura di contrasto\u00a0alla\u00a0povert\u00e0, operativa a decorrere da aprile 2019, consistente in un beneficio economico compreso tra euro 480 e 9.360 annui, che pu\u00f2 essere riconosciuto, sussistendone le condizioni, per un periodo continuativo non superiore a 18 mesi.<\/p>\n<p>In particolare, il datore di lavoro ottiene uno sgravio dei contributi per un periodo pari alla differenza tra 18 mesi (durata massima del beneficio) e il numero di mesi gi\u00e0 fruiti dal beneficiario, con un minimo di 5 mesi e per un valore mensile massimo di 780 euro. Se l\u2019assunzione avviene in seguito ad un percorso formativo promosso da un ente di formazione accreditato, lo sgravio contributivo \u00e8 ripartito tra il datore di lavoro e l\u2019ente di formazione. Per poterne fruire, l\u2019impresa deve:<\/p>\n<ul>\n<li>aver comunicato al portale del programma (SIULP) la disponibilit\u00e0 dei posti vacanti;<\/li>\n<li>aver proceduto all&#8217;assunzione a tempo pieno e indeterminato del beneficiario;<\/li>\n<li>realizzare un incremento di personale netto a tempo pieno e indeterminato.<\/li>\n<\/ul>\n<p>In caso di successivo licenziamento del beneficiario, il datore di lavoro e&#8217; tenuto alla restituzione dell&#8217;incentivo fruito maggiorato delle sanzioni civili, a meno che il licenziamento non avvenga per giusta causa o per giustificato motivo.<\/p>\n<p>L\u2019agevolazione contributiva prevista per l\u2019assunzione dei beneficiari di RDC \u00e8 compatibile e aggiuntiva rispetto a quelle previste dalla Legge di Bilancio 2019, riguardanti l\u2019assunzione di soggetti che non abbiano compiuto trentacinque anni di et\u00e0, ovvero di soggetti di almeno trentacinque anni di et\u00e0 privi di un impiego regolarmente retribuito da almeno sei mesi.<\/p>\n<p><span style=\"color: #FF0000;\"><b>QUOTA 100 E RICAMBIO GENERAZIONALE (artt. 14 e 22)<\/b><\/span><\/p>\n<p>Introdotta in via sperimentale per il triennio 2019-2021 la possibilit\u00e0 di accedere ad un trattamento pensionistico anticipato, a condizione di avere almeno 62 anni di et\u00e0 e 38 anni di contributi versati. La pensione c.d. \u201cquota 100\u201d non \u00e8 cumulabile, fino alla data di maturazione del requisito anagrafico per la pensione di vecchiaia, con i redditi da lavoro dipendente o autonomo, ad eccezione di quelli derivanti da lavoro autonomo occasionale nel limite di 5.000 euro lordi annui. Il trattamento pensionistico decorre trascorsi tre mesi dalla maturazione dei requisiti.<\/p>\n<p>E&#8217; inoltre prevista la possibilit\u00e0, al fine di favorire percorsi di ricambio generazionale, di accompagnare al pensionamento coloro che raggiungano i requisiti previsti per l\u2019opzione quota 100 entro il 31 dicembre 2021, mediante l\u2019erogazione, da parte dai Fondi di solidariet\u00e0 bilaterali di settore, di un assegno straordinario a sostegno del reddito, finanziato dalle imprese. Tale assegno potr\u00e0 essere erogato solo in presenza di accordi sindacali a livello territoriale o aziendale, che stabiliscano il numero di lavoratori da assumere in sostituzione di quelli che accedono alla prestazione. Tale accordi, ai fini della loro efficacia, devono essere depositati in via telematica presso l\u2019Ispettorato del Lavoro competente, entro 30 giorni dalla sottoscrizione.<\/p>\n<p>E\u2019, inoltre, stabilito che il raggiungimento dei requisiti minimi per l\u2019accesso a qualunque diritto alla pensione, anticipata o di vecchiaia, possa essere agevolato grazie al versamento da parte dei Fondi di solidariet\u00e0 bilaterali della contribuzione correlata a periodi riscattabili o ricongiungibili. Le relative risorse, versate dai datori di lavoro ai Fondi di solidariet\u00e0, sono deducibili dal reddito d\u2019impresa.<\/p>\n<p><span style=\"color: #FF0000;\"><b>PENSIONE ANTICIPATA (artt. 15 e 17)<\/b><\/span><\/p>\n<p>Per l\u2019accesso al pensionamento anticipato, indipendente dall\u2019et\u00e0 anagrafica, il requisito contributivo \u00e8 congelato dal 2019 al 2026, non applicandosi in tale periodo gli adeguamenti alla speranza di vita, ed \u00e8 fissato in:<\/p>\n<ul>\n<li>42 anni e 10 mesi per gli uomini\u00a0<\/li>\n<li>41 anni e 10 mesi per le donne<\/li>\n<li>41 anni per i c.d. precoci (chi ha almeno 12 mesi di contribuzione versata prima dei 19 anni di et\u00e0).<\/li>\n<\/ul>\n<p>Anche in questo caso, il trattamento pensionistico decorre trascorsi tre mesi dalla maturazione dei requisiti.\u00a0<\/p>\n<p><span style=\"color: #FF0000;\"><b>OPZIONE DONNA (art. 16)<\/b><\/span><\/p>\n<p>E\u2019 prevista un\u2019ulteriore possibilit\u00e0 di pensione anticipata (c.d. Opzione donna) per le lavoratrici che, entro il 31 dicembre 2018, abbiano almeno 35 anni di contributi e un\u2019et\u00e0 anagrafica minima di 58 anni, se dipendenti, e di 59 anni, se autonome.\u00a0<\/p>\n<p>In questo caso, il trattamento pensionistico decorre trascorsi 12 mesi dalla maturazione dei requisiti, per le lavoratrici dipendenti, e trascorsi 18 mesi per le lavoratrici autonome.<\/p>\n<p><span style=\"color: #FF0000;\"><b>APE SOCIALE (art. 18)<\/b><\/span><\/p>\n<p>Prorogata fino al 31 dicembre 2019 l&#8217;APE sociale (Anticipo finanziario a garanzia pensionistica), ovvero l\u2019indennit\u00e0 a carico dello Stato cui possono accedere coloro che abbiano compiuto 63 anni, abbiano un\u2019anzianit\u00e0 contributiva di almeno 30 anni (36 per coloro che hanno svolto lavori usuranti) ed appartengano ad una delle 4 categorie individuate dalla legge (disoccupati di lunga durata, soggetti che assistono familiari con handicap in situazione di gravit\u00e0, soggetti con riduzione della capacit\u00e0 lavorativa superiore o uguale al 74%, soggetti che svolgono da almeno 6 anni lavori considerati usuranti).<\/p>\n<p>Si ricorda che anche l\u2019APE volontario e l\u2019APE aziendale sono operativi fino al 31 dicembre 2019, per effetto della proroga stabilita dalla Legge di bilancio dello scorso anno.<\/p>\n<p><span style=\"color: #FF0000;\"><b>RISCATTO PERIODI NON COPERTI DA CONTRIBUZIONE (art. 20)<\/b><\/span><\/p>\n<p>Introdotta in via sperimentale per il triennio 2019-2021 la facolt\u00e0 per gli iscritti alla gestione ordinaria e alla gestione separata dell&#8217;INPS, privi di anzianit\u00e0 contributiva al 31 dicembre 1995, di riscattare eventuali periodi non coperti da contribuzione, compresi tra la data del primo e quella dell&#8217;ultimo contributo comunque accreditato.<\/p>\n<p>Il riscatto pu\u00f2 riguardare periodi anche non continuativi, nella misura massima di 5 anni. Gli importi versati sono detraibili dall\u2019imposta del soggetto richiedente nella misura del 50%.\u00a0<\/p>\n<p>Per i lavoratori del settore privato l&#8217;onere per il riscatto pu\u00f2 essere sostenuto anche dal datore di lavoro, destinando, a tal fine, i premi di produzione spettanti al lavoratore stesso. In tale caso, l\u2019onere \u00e8 deducibile dal reddito di impresa.\u00a0<\/p>\n<p>E\u2019 inoltre prevista, sino al compimento del quarantacinquesimo anno di et\u00e0, la facolt\u00e0 di riscatto agevolato, al costo di circa euro 5.000 per anno, dei periodi corrispondenti alla durata dei corsi legali di studio universitario.<\/p>\n<p> &#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Di seguito l\u2019analisi delle principali misure introdotte dal Decreto Legge n. 4 del 28 gennaio 2019.<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[21],"tags":[],"class_list":["post-3118","post","type-post","status-publish","format-standard","hentry","category-newsflash-insight"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Incentivi per le assunzioni e per il ricambio generazionale - Toffoletto De Luca Tamajo e Soci<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toffolettodeluca.it\/en\/incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Incentivi per le assunzioni e per il ricambio generazionale - Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"og:description\" content=\"Di seguito l\u2019analisi delle principali misure introdotte dal Decreto Legge n. 4 del 28 gennaio 2019.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toffolettodeluca.it\/en\/incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale\/\" \/>\n<meta property=\"og:site_name\" content=\"Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-06T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\"},\"headline\":\"Incentivi per le assunzioni e per il ricambio generazionale\",\"datePublished\":\"2019-02-06T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale\\\/\"},\"wordCount\":23,\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"articleSection\":[\"Newsflash &amp; Insights\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale\\\/\",\"name\":\"Incentivi per le assunzioni e per il ricambio generazionale - Toffoletto De Luca Tamajo e Soci\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\"},\"datePublished\":\"2019-02-06T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/studio-diritto-del-lavoro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Learn & Connect\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/learn-connect\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Newsflash &amp; Insights\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/category\\\/newsflash-insight\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Incentivi per le assunzioni e per il ricambio generazionale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"contentUrl\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"caption\":\"Toffoletto De Luca Tamajo e Soci\"},\"image\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Incentivi per le assunzioni e per il ricambio generazionale - Toffoletto De Luca Tamajo e Soci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toffolettodeluca.it\/en\/incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale\/","og_locale":"en_US","og_type":"article","og_title":"Incentivi per le assunzioni e per il ricambio generazionale - Toffoletto De Luca Tamajo e Soci","og_description":"Di seguito l\u2019analisi delle principali misure introdotte dal Decreto Legge n. 4 del 28 gennaio 2019.","og_url":"https:\/\/toffolettodeluca.it\/en\/incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale\/","og_site_name":"Toffoletto De Luca Tamajo e Soci","article_published_time":"2019-02-06T00:00:00+00:00","author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/toffolettodeluca.it\/en\/incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale\/#article","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale\/"},"author":{"name":"Redazione","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559"},"headline":"Incentivi per le assunzioni e per il ricambio generazionale","datePublished":"2019-02-06T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/toffolettodeluca.it\/en\/incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale\/"},"wordCount":23,"publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"articleSection":["Newsflash &amp; Insights"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/toffolettodeluca.it\/en\/incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale\/","url":"https:\/\/toffolettodeluca.it\/en\/incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale\/","name":"Incentivi per le assunzioni e per il ricambio generazionale - Toffoletto De Luca Tamajo e Soci","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/#website"},"datePublished":"2019-02-06T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/toffolettodeluca.it\/en\/incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toffolettodeluca.it\/en\/incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/toffolettodeluca.it\/en\/incentivi-per-le-assunzioni-e-per-il-ricambio-generazionale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toffolettodeluca.it\/en\/studio-diritto-del-lavoro\/"},{"@type":"ListItem","position":2,"name":"Learn & Connect","item":"https:\/\/toffolettodeluca.it\/en\/learn-connect\/"},{"@type":"ListItem","position":3,"name":"Newsflash &amp; Insights","item":"https:\/\/toffolettodeluca.it\/en\/category\/newsflash-insight\/"},{"@type":"ListItem","position":4,"name":"Incentivi per le assunzioni e per il ricambio generazionale"}]},{"@type":"WebSite","@id":"https:\/\/toffolettodeluca.it\/en\/#website","url":"https:\/\/toffolettodeluca.it\/en\/","name":"Toffoletto De Luca Tamajo e Soci","description":"","publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toffolettodeluca.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/toffolettodeluca.it\/en\/#organization","name":"Toffoletto De Luca Tamajo e Soci","url":"https:\/\/toffolettodeluca.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","contentUrl":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","caption":"Toffoletto De Luca Tamajo e Soci"},"image":{"@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/toffolettodeluca.it\/en\/author\/redazione\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/3118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/comments?post=3118"}],"version-history":[{"count":0,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/3118\/revisions"}],"wp:attachment":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/media?parent=3118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/categories?post=3118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/tags?post=3118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}