{"id":3132,"date":"2015-10-05T00:00:00","date_gmt":"2015-10-05T00:00:00","guid":{"rendered":"https:\/\/toffolettodeluca.it\/\/toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference\/"},"modified":"2015-10-05T00:00:00","modified_gmt":"2015-10-05T00:00:00","slug":"toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference","status":"publish","type":"post","link":"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference\/","title":{"rendered":"Toffoletto De Luca Tamajo e Soci at the International Bar Association Annual Conference"},"content":{"rendered":"<div class=dettaglio\" style=\"margin: 0px; padding: 0px; color: rgb(35, 31, 32); font-family: Arial, Helvetica, sans-serif; font-size: 11px; line-height: normal;\">\n<div class=\"article-content\" style=\"margin: 0px; padding: 0px; clear: both;\">\n<h4 style=\"margin: 0px; padding: 0px 0px 5px; font-size: 13px; line-height: 25px; text-align: justify;\">I Partner Valeria Morosini e Aldo Palumbo partecipano in qualit\u00e0 di relatori<\/h4>\n<\/p><\/div>\n<\/p><\/div>\n<div class=\"modulo\" style=\"margin: 0px; padding: 0px; color: rgb(35, 31, 32); font-family: Arial, Helvetica, sans-serif; font-size: 11px; line-height: normal;\">\n<h3 class=\"contentheading\" style=\"margin: 0px; padding: 4px 0px 0px; font-size: 12px; font-weight: bold;\">\u00a0<\/h3>\n<div class=\"article-content\" style=\"margin: 0px; padding: 0px; clear: both;\">\n<p style=\"margin: 0px; padding: 0px 0px 5px; font-size: 13px; line-height: 25px; text-align: justify;\">Gli avvocati Valeria Morosini e Aldo Palumbo, Partner dello studio legale Toffoletto De Luca Tamajo e Soci, partecipano in qualit\u00e0 di relatori alla conferenza annuale dell\u2019International Bar Association, in corso a Vienna fino al 9 ottobre 2015.<\/p>\n<p style=\"margin: 0px; padding: 0px 0px 5px; font-size: 13px; line-height: 25px; text-align: justify;\">\u00a0<\/p>\n<p style=\"margin: 0px; padding: 0px 0px 5px; font-size: 13px; line-height: 25px; text-align: justify;\">L\u2019Avvocato Valeria Morosini, Officer del Discrimination and Equality Law Committee dell\u2019International Bar Association (IBA), prende parte oggi luned\u00ec 5 ottobre, alla sessione \u00abRemoving the glass ceiling from above: diversity as a leadership challenge\u00bb, che analizzer\u00e0 quali cambiamenti strutturali e di atteggiamento possono essere messi in atto per favorire l&#8217;equilibrio tra i generi e l\u2019ingresso delle donne nelle posizioni di leadership.<\/p>\n<p style=\"margin: 0px; padding: 0px 0px 5px; font-size: 13px; line-height: 25px; text-align: justify;\">\u00a0<\/p>\n<p style=\"margin: 0px; padding: 0px 0px 5px; font-size: 13px; line-height: 25px; text-align: justify;\">\u00abI dati appena pubblicati dalla commissione europea sono confortanti &#8211; osserva l\u2019Avvocato Morosini. &#8211; In Europa si evidenza un incremento di presenza femminile media nei consigli di amministrazione delle maggiori imprese quotate dall&#8217;11,9% nel 2010 al 20,2% nel 2015. Naturalmente, per\u00f2, le realt\u00e0 sono molto diverse tra un Paese e l&#8217;altro. L&#8217;Italia, che nel 2011 ha introdotto per via legislativa le cosiddette quote rosa, sembra poter diventare un modello per l&#8217;Europa. Dai primi studi svolti dal dipartimento pari opportunit\u00e0 della presidenza del consiglio dei ministri con il supporto dell&#8217;Universit\u00e0 Bocconi, risulta che la presenza femminile nei consigli di amministrazione nel nostro Paese \u00e8 notevolmente aumentata, uno dei maggiori incrementi in Europa, dal 6,8% nel 2010 a quasi 23% nel 2015. Non solo, anche la qualit\u00e0 della governance \u00e8 migliorata, portando il livello di istruzione nei consigli di amministrazione ad una media superiore sia per le donne che per gli uomini.\u00bb<\/p>\n<p style=\"margin: 0px; padding: 0px 0px 5px; font-size: 13px; line-height: 25px; text-align: justify;\">\u00a0<\/p>\n<p style=\"margin: 0px; padding: 0px 0px 5px; font-size: 13px; line-height: 25px; text-align: justify;\">L\u2019Avvocato Aldo Palumbo sar\u00e0, invece, tra i relatori dell\u2019incontro \u00abQuotas, penalties and other approaches to disability equality: are they working and what is the best approach?\u00bb, in programma mercoled\u00ec 7 ottobre, che verter\u00e0 sull\u2019impatto delle pratiche legislative e normative volte a rafforzare la disability equality. I partecipanti si confronteranno su quali azioni vengano maggiormente applicate e siano effettivamente efficaci.<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p> &#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":25,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[21],"tags":[],"class_list":["post-3132","post","type-post","status-publish","format-standard","hentry","category-newsflash-insight"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Toffoletto De Luca Tamajo e Soci at the International Bar Association Annual Conference - Toffoletto De Luca Tamajo e Soci<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Toffoletto De Luca Tamajo e Soci at the International Bar Association Annual Conference - Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference\/\" \/>\n<meta property=\"og:site_name\" content=\"Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-05T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\"},\"headline\":\"Toffoletto De Luca Tamajo e Soci at the International Bar Association Annual Conference\",\"datePublished\":\"2015-10-05T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference\\\/\"},\"wordCount\":13,\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"articleSection\":[\"Newsflash &amp; Insights\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference\\\/\",\"name\":\"Toffoletto De Luca Tamajo e Soci at the International Bar Association Annual Conference - Toffoletto De Luca Tamajo e Soci\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\"},\"datePublished\":\"2015-10-05T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/studio-diritto-del-lavoro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Learn & Connect\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/learn-connect\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Newsflash &amp; Insights\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/category\\\/newsflash-insight\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Toffoletto De Luca Tamajo e Soci at the International Bar Association Annual Conference\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"contentUrl\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"caption\":\"Toffoletto De Luca Tamajo e Soci\"},\"image\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Toffoletto De Luca Tamajo e Soci at the International Bar Association Annual Conference - Toffoletto De Luca Tamajo e Soci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference\/","og_locale":"en_US","og_type":"article","og_title":"Toffoletto De Luca Tamajo e Soci at the International Bar Association Annual Conference - Toffoletto De Luca Tamajo e Soci","og_url":"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference\/","og_site_name":"Toffoletto De Luca Tamajo e Soci","article_published_time":"2015-10-05T00:00:00+00:00","author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference\/#article","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference\/"},"author":{"name":"Redazione","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559"},"headline":"Toffoletto De Luca Tamajo e Soci at the International Bar Association Annual Conference","datePublished":"2015-10-05T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference\/"},"wordCount":13,"publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"articleSection":["Newsflash &amp; Insights"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference\/","url":"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference\/","name":"Toffoletto De Luca Tamajo e Soci at the International Bar Association Annual Conference - Toffoletto De Luca Tamajo e Soci","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/#website"},"datePublished":"2015-10-05T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/toffolettodeluca.it\/en\/toffoletto-de-luca-tamajo-e-soci-at-the-international-bar-association-annual-conference\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toffolettodeluca.it\/en\/studio-diritto-del-lavoro\/"},{"@type":"ListItem","position":2,"name":"Learn & Connect","item":"https:\/\/toffolettodeluca.it\/en\/learn-connect\/"},{"@type":"ListItem","position":3,"name":"Newsflash &amp; Insights","item":"https:\/\/toffolettodeluca.it\/en\/category\/newsflash-insight\/"},{"@type":"ListItem","position":4,"name":"Toffoletto De Luca Tamajo e Soci at the International Bar Association Annual Conference"}]},{"@type":"WebSite","@id":"https:\/\/toffolettodeluca.it\/en\/#website","url":"https:\/\/toffolettodeluca.it\/en\/","name":"Toffoletto De Luca Tamajo e Soci","description":"","publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toffolettodeluca.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/toffolettodeluca.it\/en\/#organization","name":"Toffoletto De Luca Tamajo e Soci","url":"https:\/\/toffolettodeluca.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","contentUrl":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","caption":"Toffoletto De Luca Tamajo e Soci"},"image":{"@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/toffolettodeluca.it\/en\/author\/redazione\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/3132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/comments?post=3132"}],"version-history":[{"count":0,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/3132\/revisions"}],"wp:attachment":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/media?parent=3132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/categories?post=3132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/tags?post=3132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}