{"id":3187,"date":"2015-11-06T00:00:00","date_gmt":"2015-11-06T00:00:00","guid":{"rendered":"https:\/\/toffolettodeluca.it\/\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\/"},"modified":"2015-11-06T00:00:00","modified_gmt":"2015-11-06T00:00:00","slug":"ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe","status":"publish","type":"post","link":"https:\/\/toffolettodeluca.it\/en\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\/","title":{"rendered":"Ius Laboris grows in the Netherlands and strengthens its coverage in Europe"},"content":{"rendered":"<p>Ius Laboris, la pi\u00f9 grande alleanza mondiale di specialisti in diritto del lavoro e delle risorse umane \u2013 rappresentata in Italia da Toffoletto De Luca Tamajo e Soci che ha contribuito alla sua fondazione nel 2001 &#8211; annuncia l\u2019ingresso di Veugelers Advocatuur, studio olandese specializzato in diritto pensionistico e previdenza sociale.<\/p>\n<p>Fondato nel 2009 dall\u2019avvocato Roel Veugelers, uno dei pi\u00f9 importanti specialisti in pensions law e spesso consulente dei Ministeri delle Finanze e delle Politiche Sociali in Olanda, Veugelers Advocatuur amplia la presenza nel Paese affiancandosi all\u2019attuale membro di Ius Laboris Bronsgeest Deur Advocaten, studio legale che si occupa esclusivamente di diritto del lavoro.<\/p>\n<p>\u00abIl sistema legislativo olandese \u00e8 improntato fortemente sul welfare &#8211; ha dichiarato Sam Everatt, Executive Director di Ius Laboris &#8211; Con una previsione patrimoniale per il 2020 pari a oltre 135 miliardi di euro, \u00e8 di fondamentale importanza una consulenza specializzata in tema pensionistico per tutte le aziende, soprattutto internazionali, che operano in questa giurisdizione e necessitano di una conoscenza puntuale della legislazione locale in relazione al contesto globale.\u00bb<\/p>\n<p>L\u2019ingresso di Veugelers Advocatuur rappresenta un ulteriore passo nella strategia di crescita dell\u2019Alleanza, che vanta una copertura mondiale capillare con professionisti di altissima qualit\u00e0, specializzati in diritto del lavoro e che operano con successo a livello nazionale e internazionale.<\/p>\n<p>Ius Laboris conta oggi pi\u00f9 di 1.400 avvocati giuslavoristi e una presenza in 47 Paesi e in 160 citt\u00e0 nel mondo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ius Laboris, la pi\u00f9 grande alleanza mondiale di specialisti in diritto del lavoro e delle risorse umane \u2013 rappresentata in Italia da Toffoletto De Luca Tamajo e Soci che ha contribuito alla sua fondazione nel 2001 &#8211; annuncia l\u2019ingresso di Veugelers Advocatuur, studio olandese specializzato in diritto pensionistico e previdenza sociale. Fondato nel 2009 dall\u2019avvocato &#8230; <a title=\"Ius Laboris grows in the Netherlands and strengthens its coverage in Europe\" class=\"read-more\" href=\"https:\/\/toffolettodeluca.it\/en\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\/\" aria-label=\"Read more about Ius Laboris grows in the Netherlands and strengthens its coverage in Europe\">Read more<\/a><\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[21],"tags":[],"class_list":["post-3187","post","type-post","status-publish","format-standard","hentry","category-newsflash-insight"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ius Laboris grows in the Netherlands and strengthens its coverage in Europe - Toffoletto De Luca Tamajo e Soci<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toffolettodeluca.it\/en\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ius Laboris grows in the Netherlands and strengthens its coverage in Europe - Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"og:description\" content=\"Ius Laboris, la pi\u00f9 grande alleanza mondiale di specialisti in diritto del lavoro e delle risorse umane \u2013 rappresentata in Italia da Toffoletto De Luca Tamajo e Soci che ha contribuito alla sua fondazione nel 2001 &#8211; annuncia l\u2019ingresso di Veugelers Advocatuur, studio olandese specializzato in diritto pensionistico e previdenza sociale. Fondato nel 2009 dall\u2019avvocato ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toffolettodeluca.it\/en\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\/\" \/>\n<meta property=\"og:site_name\" content=\"Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-06T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\"},\"headline\":\"Ius Laboris grows in the Netherlands and strengthens its coverage in Europe\",\"datePublished\":\"2015-11-06T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\\\/\"},\"wordCount\":240,\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"articleSection\":[\"Newsflash &amp; Insights\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\\\/\",\"name\":\"Ius Laboris grows in the Netherlands and strengthens its coverage in Europe - Toffoletto De Luca Tamajo e Soci\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\"},\"datePublished\":\"2015-11-06T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/studio-diritto-del-lavoro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Learn & Connect\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/learn-connect\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Newsflash &amp; Insights\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/category\\\/newsflash-insight\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Ius Laboris grows in the Netherlands and strengthens its coverage in Europe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"contentUrl\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"caption\":\"Toffoletto De Luca Tamajo e Soci\"},\"image\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ius Laboris grows in the Netherlands and strengthens its coverage in Europe - Toffoletto De Luca Tamajo e Soci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toffolettodeluca.it\/en\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\/","og_locale":"en_US","og_type":"article","og_title":"Ius Laboris grows in the Netherlands and strengthens its coverage in Europe - Toffoletto De Luca Tamajo e Soci","og_description":"Ius Laboris, la pi\u00f9 grande alleanza mondiale di specialisti in diritto del lavoro e delle risorse umane \u2013 rappresentata in Italia da Toffoletto De Luca Tamajo e Soci che ha contribuito alla sua fondazione nel 2001 &#8211; annuncia l\u2019ingresso di Veugelers Advocatuur, studio olandese specializzato in diritto pensionistico e previdenza sociale. Fondato nel 2009 dall\u2019avvocato ... Read more","og_url":"https:\/\/toffolettodeluca.it\/en\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\/","og_site_name":"Toffoletto De Luca Tamajo e Soci","article_published_time":"2015-11-06T00:00:00+00:00","author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redazione","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/toffolettodeluca.it\/en\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\/#article","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\/"},"author":{"name":"Redazione","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559"},"headline":"Ius Laboris grows in the Netherlands and strengthens its coverage in Europe","datePublished":"2015-11-06T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/toffolettodeluca.it\/en\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\/"},"wordCount":240,"publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"articleSection":["Newsflash &amp; Insights"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/toffolettodeluca.it\/en\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\/","url":"https:\/\/toffolettodeluca.it\/en\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\/","name":"Ius Laboris grows in the Netherlands and strengthens its coverage in Europe - Toffoletto De Luca Tamajo e Soci","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/#website"},"datePublished":"2015-11-06T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/toffolettodeluca.it\/en\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toffolettodeluca.it\/en\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/toffolettodeluca.it\/en\/ius-laboris-grows-in-the-netherlands-and-strengthens-its-coverage-in-europe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toffolettodeluca.it\/en\/studio-diritto-del-lavoro\/"},{"@type":"ListItem","position":2,"name":"Learn & Connect","item":"https:\/\/toffolettodeluca.it\/en\/learn-connect\/"},{"@type":"ListItem","position":3,"name":"Newsflash &amp; Insights","item":"https:\/\/toffolettodeluca.it\/en\/category\/newsflash-insight\/"},{"@type":"ListItem","position":4,"name":"Ius Laboris grows in the Netherlands and strengthens its coverage in Europe"}]},{"@type":"WebSite","@id":"https:\/\/toffolettodeluca.it\/en\/#website","url":"https:\/\/toffolettodeluca.it\/en\/","name":"Toffoletto De Luca Tamajo e Soci","description":"","publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toffolettodeluca.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/toffolettodeluca.it\/en\/#organization","name":"Toffoletto De Luca Tamajo e Soci","url":"https:\/\/toffolettodeluca.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","contentUrl":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","caption":"Toffoletto De Luca Tamajo e Soci"},"image":{"@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/toffolettodeluca.it\/en\/author\/redazione\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/3187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/comments?post=3187"}],"version-history":[{"count":0,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/3187\/revisions"}],"wp:attachment":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/media?parent=3187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/categories?post=3187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/tags?post=3187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}