{"id":3195,"date":"2016-03-30T00:00:00","date_gmt":"2016-03-30T00:00:00","guid":{"rendered":"https:\/\/toffolettodeluca.it\/\/faq-on-resignations\/"},"modified":"2016-03-30T00:00:00","modified_gmt":"2016-03-30T00:00:00","slug":"faq-on-resignations","status":"publish","type":"post","link":"https:\/\/toffolettodeluca.it\/en\/faq-on-resignations\/","title":{"rendered":"FAQ on resignations"},"content":{"rendered":"<h4><sub><span style=color: rgb(255, 0, 0);\">1. La nuova procedura vale anche per i dirigenti?<\/span><\/sub><\/h4>\n<p>Si, la nuova procedura vale per tutti i lavoratori subordinati.\u00a0<\/p>\n<h4><span style=\"color: rgb(255, 0, 0);\"><sub>2.\u00a0La nuova procedura vale anche per gli stagisti?<\/sub><\/span><\/h4>\n<p>No, il requisito di forma &#8220;telematica&#8221; di dimissioni e risoluzione consensuale vale solo per i lavoratori subordinati, e lo stage non \u00e8 un rapporto di lavoro subordinato.<\/p>\n<h4><sub><span style=\"color: rgb(255, 0, 0);\">3. La nuova procedura vale anche per i collaboratori con contratto di collaborazione autonoma coordinata e continuativa?<\/span><\/sub><\/h4>\n<p>No, la nuova procedura si applica solo ai lavoratori subordinati. Il recesso del collaboratore autonomo non \u00e8 soggetto a regole di forma particolari.<\/p>\n<h4><sub><span style=\"color: rgb(255, 0, 0);\">4.\u00a0\u00e8 necessaria la forma scritta per esonerare il lavoratore dal preavviso?<\/span><\/sub><\/h4>\n<p>Non \u00e8 a rigore necessaria, ma \u00e8 opportuna e consigliabile per giustificare la diversa data di cessazione del rapporto che risulter\u00e0 dalla comunicazione al centro per l\u2019impiego.<\/p>\n<h4><span style=\"color: rgb(255, 0, 0);\"><sub>5.\u00a0\u00e8 necessaria la firma digitale del lavoratore nel caso questi proceda autonomamente?<\/sub><\/span><\/h4>\n<p>No, basta il PIN rilasciato dall&#8217;INPS.<\/p>\n<h4><sub><span style=\"color: rgb(255, 0, 0);\">6. Nel caso in cui il lavoratore comunichi una data di decorrenza che non rispetti il preavviso e poi intenda invece rispettarlo, deve\/pu\u00f2 comunicare in modalit\u00e0 telematica la data corretta?<\/span><\/sub><\/h4>\n<p>La procedura telematica non ammette rettifiche. Una volta inviato il modulo, le dimissioni possono solo essere revocate (nei sette giorni successivi) e poi eventualmente ridate facendo nuovamente la procedura. Se le dimissioni sono state date senza preavviso \u00e8 consigliabile non ammettere al lavoro il dipendente nel relativo periodo, per evitare il rischio che il rapporto di lavoro possa intendersi ricostruito.<\/p>\n<h4><sub><span style=\"color: rgb(255, 0, 0);\">7. Come ci si comporta nei passaggi di societ\u00e0 infragruppo?<\/span><\/sub><\/h4>\n<p>Se ci sono dimissioni, deve essere seguita la nuova procedura. \u00a0<\/p>\n<p>Se il passaggio \u00e8 realizzato con una cessione di contratto, il rapporto di lavoro non si interrompe, in quanto la cessione comporta solo la sostituzione di un datore di lavoro con un altro. Quindi la procedura telematica per le dimissioni non si applica.<\/p>\n<h4><sub><span style=\"color: rgb(255, 0, 0);\">8. Per le dimissioni presentate prima del 12\/03\/2016 e con data cessazione successiva al 12\/03\/2016 quale procedura si adotta?<\/span><\/sub><\/h4>\n<p>Non \u00e8 prevista una disciplina transitoria. Pertanto, se le dimissioni sono state presentate prima del 12 marzo 2016 trova applicazione la normativa di cui alla legge n. 92\/2012, anche se la cessazione del rapporto \u00e8 successiva.\u00a0<\/p>\n<h4><sub><span style=\"color: rgb(255, 0, 0);\">9.\u00a0La data comunicata dal dipendente pu\u00f2 essere modificata dal datore di lavoro se non rispetta il preavviso previsto?<\/span><\/sub><\/h4>\n<p>Il datore di lavoro non pu\u00f2 modificare il contenuto della comunicazione, in quanto quest\u2019ultima \u00e8 accessibile nel portale in sola lettura per il datore di lavoro e per la DTL.<\/p>\n<h4><sub><span style=\"color: rgb(255, 0, 0);\">10. Se il dipendente ci ripensa ed effettua la revoca delle dimissioni volontarie entro sette giorni, il datore annulla la comunicazione al centro per l\u2019impiego ma poi come si considerano le giornate di \u201cstop\u201d?<\/span><\/sub><\/h4>\n<p>Se c\u2019\u00e8 la revoca delle dimissioni il rapporto di lavoro continua come se non si fosse mai interrotto. In ogni caso, se il dipendente non ha reso la prestazione lavorativa, il datore di lavoro non deve corrispondere la retribuzione per i giorni corrispondenti.<\/p>\n<h4><sub><span style=\"color: rgb(255, 0, 0);\">11. Il datore di lavoro pu\u00f2 mettere a disposizione del lavoratore che si vuole dimettere il proprio PC, perch\u00e9 il dipendente a casa ne \u00e8 sprovvisto?\u00a0<\/span><\/sub><\/h4>\n<p>S\u00ec. Il lavoratore, con il suo PIN identificativo, pu\u00f2 accedere al portale per la comunicazione delle dimissioni indifferentemente da qualsiasi PC.<\/p>\n<p> &#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":25,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[21],"tags":[],"class_list":["post-3195","post","type-post","status-publish","format-standard","hentry","category-newsflash-insight"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FAQ on resignations - Toffoletto De Luca Tamajo e Soci<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toffolettodeluca.it\/en\/faq-on-resignations\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FAQ on resignations - Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toffolettodeluca.it\/en\/faq-on-resignations\/\" \/>\n<meta property=\"og:site_name\" content=\"Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-30T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/faq-on-resignations\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/faq-on-resignations\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\"},\"headline\":\"FAQ on resignations\",\"datePublished\":\"2016-03-30T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/faq-on-resignations\\\/\"},\"wordCount\":3,\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"articleSection\":[\"Newsflash &amp; Insights\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/faq-on-resignations\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/faq-on-resignations\\\/\",\"name\":\"FAQ on resignations - Toffoletto De Luca Tamajo e Soci\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\"},\"datePublished\":\"2016-03-30T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/faq-on-resignations\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/faq-on-resignations\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/faq-on-resignations\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/studio-diritto-del-lavoro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Learn & Connect\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/learn-connect\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Newsflash &amp; Insights\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/category\\\/newsflash-insight\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"FAQ on resignations\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"contentUrl\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"caption\":\"Toffoletto De Luca Tamajo e Soci\"},\"image\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FAQ on resignations - Toffoletto De Luca Tamajo e Soci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toffolettodeluca.it\/en\/faq-on-resignations\/","og_locale":"en_US","og_type":"article","og_title":"FAQ on resignations - Toffoletto De Luca Tamajo e Soci","og_url":"https:\/\/toffolettodeluca.it\/en\/faq-on-resignations\/","og_site_name":"Toffoletto De Luca Tamajo e Soci","article_published_time":"2016-03-30T00:00:00+00:00","author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/toffolettodeluca.it\/en\/faq-on-resignations\/#article","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/faq-on-resignations\/"},"author":{"name":"Redazione","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559"},"headline":"FAQ on resignations","datePublished":"2016-03-30T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/toffolettodeluca.it\/en\/faq-on-resignations\/"},"wordCount":3,"publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"articleSection":["Newsflash &amp; Insights"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/toffolettodeluca.it\/en\/faq-on-resignations\/","url":"https:\/\/toffolettodeluca.it\/en\/faq-on-resignations\/","name":"FAQ on resignations - Toffoletto De Luca Tamajo e Soci","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/#website"},"datePublished":"2016-03-30T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/toffolettodeluca.it\/en\/faq-on-resignations\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toffolettodeluca.it\/en\/faq-on-resignations\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/toffolettodeluca.it\/en\/faq-on-resignations\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toffolettodeluca.it\/en\/studio-diritto-del-lavoro\/"},{"@type":"ListItem","position":2,"name":"Learn & Connect","item":"https:\/\/toffolettodeluca.it\/en\/learn-connect\/"},{"@type":"ListItem","position":3,"name":"Newsflash &amp; Insights","item":"https:\/\/toffolettodeluca.it\/en\/category\/newsflash-insight\/"},{"@type":"ListItem","position":4,"name":"FAQ on resignations"}]},{"@type":"WebSite","@id":"https:\/\/toffolettodeluca.it\/en\/#website","url":"https:\/\/toffolettodeluca.it\/en\/","name":"Toffoletto De Luca Tamajo e Soci","description":"","publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toffolettodeluca.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/toffolettodeluca.it\/en\/#organization","name":"Toffoletto De Luca Tamajo e Soci","url":"https:\/\/toffolettodeluca.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","contentUrl":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","caption":"Toffoletto De Luca Tamajo e Soci"},"image":{"@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/toffolettodeluca.it\/en\/author\/redazione\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/3195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/comments?post=3195"}],"version-history":[{"count":0,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/3195\/revisions"}],"wp:attachment":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/media?parent=3195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/categories?post=3195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/tags?post=3195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}