{"id":3254,"date":"2019-08-06T00:00:00","date_gmt":"2019-08-06T00:00:00","guid":{"rendered":"https:\/\/toffolettodeluca.it\/\/gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019\/"},"modified":"2019-08-06T00:00:00","modified_gmt":"2019-08-06T00:00:00","slug":"gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019","status":"publish","type":"post","link":"https:\/\/toffolettodeluca.it\/en\/gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019\/","title":{"rendered":"Gig economy: quando il lavoro incontra la tecnologia (aggiornato al DL Rider 2019)"},"content":{"rendered":"<p>Di:  <a href=\/None\/our-employment-lawyers\/redazione\/\" >Avv. Wanda Falco<\/a>  <\/p>\n<p><span style=\"color: #A9A9A9;\"><em>*Questo articolo \u00e8 stato aggiornato il 23 settembre 2019<\/em><\/span><\/p>\n<p>La\u00a0<strong><em>Gig economy<\/em>,\u00a0<\/strong>letteralmente \u201ceconomia dei lavoretti\u201d, \u00e8 un modello economico che si \u00e8 sviluppato negli ultimi anni grazie alla diffusione di numerose piattaforme digitali che offrono servizi personalizzati\u00a0<em>on demand\u00a0<\/em>ad un numero sempre pi\u00f9 ampio di utenti. Il\u00a0XVII Rapporto dell&#8217;INPS\u00a0\u00a0dedica un intero capitolo a questa nuova forma di economia e di lavoro e lo definisce proprio come \u201cun modello di lavoro su richiesta, dove domanda e offerta si incontrano\u00a0<em>on-line\u00a0<\/em>attraverso apposite piattaforme digitali\u201d.\u00a0<\/p>\n<h2><span style=\"color: #FF0000;\"><strong>Qual \u00e8 il significato di\u00a0<em>Gig economy<\/em>?<\/strong><\/span><\/h2>\n<p>Nell\u2019ambito della Gig economy si distinguono alcune tipologie quali il\u00a0<strong>lavoro\u00a0<em>on demand\u00a0<\/em>tramite app\u00a0<\/strong>(si pensi a Deliveroo, Uber, Foodora), il\u00a0<strong><em>crowdwork<\/em><\/strong>, tipico di programmatori,\u00a0<em>freelance<\/em>, informatici, professionisti che da casa propria o dal proprio studio si rendono disponibili a svolgere una moltitudine di differenti attivit\u00e0 e\u00a0<em>l\u2019asset rental<\/em>, che consiste nell\u2019<strong>affitto e noleggio di beni\u00a0<\/strong>(si pensi a BlaBlaCar e AirBnb).<\/p>\n<p>In Italia, in particolare, la Gig economy ha avuto grande diffusione nel settore della ristorazione mediante l\u2019<strong>ordinazione del cibo tramite app\u00a0<\/strong>e la consegna a domicilio da parte dei cosiddetti\u00a0<em>rider.\u00a0<\/em>Sono state proprio le notevoli dimensioni del fenomeno a fare luce su alcune problematiche particolarmente spinose quali la qualificazione dei rapporti di lavoro intercorrenti tra i\u00a0<em>rider\u00a0<\/em>e la piattaforma digitale e, dunque, le tutele spettanti ai medesimi.\u00a0L\u2019analisi che segue \u00e8 proprio finalizzata ad esaminare lo stato dell\u2019arte alla luce delle recenti pronunce di merito e delle prime iniziative a livello locale volte a riconoscere alcune tutele ai lavoratori digitali.<\/p>\n<h2><span style=\"color: #FF0000;\"><strong>Gig economy e lavoro: i\u00a0<em>rider\u00a0<\/em>sono subordinati o autonomi?\u00a0<\/strong><\/span><\/h2>\n<ol>\n<li>\n<h3><strong>La sentenza del Tribunale di Torino 2018<\/strong><\/h3>\n<\/li>\n<\/ol>\n<p>In Italia la prima sentenza che si \u00e8 pronunciata sulla problematica della qualificazione dei rapporti di lavoro dei\u00a0<em>rider\u00a0<\/em>\u00e8\u00a0Tribunale di Torino, sez. Lavoro, Sentenza del 07\/05\/2018, n. 778, che\u00a0ha respinto il ricorso di sei ciclofattorini di Foodora che avevano intentato una causa contro la societ\u00e0 tedesca di\u00a0<em>food delivery<\/em>, rivendicando la natura subordinata del loro rapporto di lavoro. Per il giudice torinese il rapporto in questione va qualificato come di lavoro autonomo in quanto non sussiste alcuna etero-organizzazione: la determinazione del luogo e dell\u2019orario di lavoro non viene imposta unilateralmente dall\u2019azienda che si limita a pubblicare sulla piattaforma gli slot con i turni di lavoro, lasciando i rider liberi di dare o meno la propria disponibilit\u00e0, cos\u00ec come sono liberi di rinunciare al turno gi\u00e0 confermato o di non presentarsi senza alcuna comunicazione preventiva. In tali casi, la conseguenza \u00e8 l\u2019esclusione temporanea dai turni di lavoro, che non costituisce una sanzione disciplinare cos\u00ec come non pu\u00f2 essere considerata emanazione di un ordine specifico la telefonata di sollecito fatta durante l\u2019effettuazione della consegna quando emerge il ritardo del fattorino.\u00a0<\/p>\n<p>In sostanza il rapporto di lavoro intercorso tra le parti \u00e8 caratterizzato dal fatto che i lavoratori non hanno l\u2019obbligo di effettuare la prestazione lavorativa e la societ\u00e0 non ha l\u2019obbligo di riceverla: i\u00a0<em>rider\u00a0<\/em>possono dare la propria disponibilit\u00e0 per uno dei turni indicati da Foodora, ma non sono obbligati a farlo; a sua volta la societ\u00e0 pu\u00f2 accettare la disponibilit\u00e0 data dai fattorini e inserirli nei turni da loro richiesti, ma pu\u00f2 anche non farlo. Infatti, il profilo della\u00a0<strong>non obbligatoriet\u00e0 della prestazione lavorativa\u00a0<\/strong>esclude in radice la subordinazione perch\u00e9 l\u2019etero-direzione \u00e8 incompatibile con la libert\u00e0 della parte che deve rendere la prestazione di rifiutarla.<\/p>\n<ol>\n<li value=\"2\">\n<h3><strong>La sentenza del Tribunale di Milano 2018<\/strong><\/h3>\n<\/li>\n<\/ol>\n<p>Dopo la sentenza del Tribunale di Torino di maggio 2018 anche il\u00a0Tribunale di Milano, sez. Lavoro, Sentenza del 10\/09\/2018, n. 1853\u00a0haconfermato la natura autonoma del rapporto di lavoro dei\u00a0<em>rider\u00a0<\/em>in quanto caratterizzato dalla possibilit\u00e0 per il prestatore di determinare quantit\u00e0 e tempi della propria attivit\u00e0. Non rileva, infatti, che una volta manifestata la disponibilit\u00e0 a prestare l\u2019attivit\u00e0 in una determinata fascia oraria, le modalit\u00e0 della prestazione siano standardizzate in base a regole prefissate dalla societ\u00e0 (es. l\u2019immediata esecuzione delle consegne nel minor tempo possibile). Anche nel lavoro autonomo, infatti, il committente impartisce istruzioni in ordine al contenuto e agli obiettivi dell\u2019incarico affidato e fissa standard qualitativi e quantitativi delle prestazioni concordate, verificando il rispetto degli stessi da parte del prestatore.\u00a0<\/p>\n<p>I\u00a0<em>rider,\u00a0<\/em>in quanto autonomi, sono liberi di determinare se e quando lavorare e tale libert\u00e0 viene esercitata nel momento in cui scelgono o meno di accedere al sistema e scelgono quali proposte di consegna accettare: ci\u00f2 non avviene assolutamente in un rapporto di lavoro subordinato. Inoltre, non pu\u00f2 essere assimilata all\u2019esercizio del potere disciplinare la scelta della piattaforma di attribuire un punteggio pi\u00f9 basso ai\u00a0<em>rider\u00a0<\/em>che vengono meno agli impegni presi sebbene abbiano dichiarato la propria disponibilit\u00e0 per una data fascia oraria: il sistema di punteggio, che impedisce ai\u00a0<em>rider\u00a0<\/em>con uno\u00a0<em>score\u00a0<\/em>basso di ricevere pi\u00f9 proposte di consegna, infatti, non comporta vere conseguenze disciplinari (nessun licenziamento, sospensione o sanzione).\u00a0\u00a0<\/p>\n<h2><span style=\"color: #FF0000;\"><strong>Il caso Foodora 2019<\/strong><\/span><\/h2>\n<p>Rispetto alle pronunce esaminate nel paragrafo precedente, la\u00a0Corte d&#8217;Appello di Torino, sez. Lavoro, Sentenza del 04\/02\/2019, n. 26 qualifica diversamente\u00a0\u00a0il rapporto di lavoro dei ciclofattorini di Foodora.\u00a0I giudici di II grado, infatti, spiegano che il rapporto di lavoro intercorrente tra il\u00a0<em>rider\u00a0<\/em>e Foodora \u00e8\u00a0<strong>riconducibile alla collaborazione etero-organizzata\u00a0<\/strong>di cui all\u2019art. 2 d.lgs. 81\/15. Si tratta di un terzo genere di rapporto che si affianca al lavoro subordinato di cui all\u2019art. 2094 c.c. e alla co.co.co. di cui all\u2019art. 409, n. 3 c.p.c: tale rapporto \u00e8 caratterizzato dal fatto che il committente ha il potere di determinare le modalit\u00e0 di esecuzione della prestazione lavorativa stabilendo anche i tempi e i luoghi di lavoro senza, per\u00f2, sconfinare nell\u2019esercizio del potere gerarchico e disciplinare che sono alla base dell\u2019etero-direzione.\u00a0<\/p>\n<p>Come spiegano i giudici, la collaborazione \u00e8 qualificabile come etero-organizzata quando \u00e8 ravvisabile un\u2019effettiva integrazione funzionale del lavoratore nell\u2019organizzazione produttiva del committente; in tal modo la prestazione lavorativa finisce con l\u2019essere strutturalmente legata all\u2019organizzazione del committente e si pone come \u201cun qualcosa che va oltre la semplice coordinazione di cui all\u2019articolo 409 n. 3 c.p.c., in cui il collaboratore, pur coordinandosi con il committente, organizza autonomamente la propria attivit\u00e0 lavorativa\u201d.\u00a0<\/p>\n<p>Da ci\u00f2 discende che siffatti rapporti restano tecnicamente autonomi, ma per quel che riguarda sicurezza e igiene, retribuzione diretta e differita, limiti di orario, ferie e previdenza, sono\u00a0<strong>regolati dalla disciplina del lavoro subordinato<\/strong>, come espressamente previsto dall\u2019art. 2 d.lgs. 81\/15.\u00a0<\/p>\n<p>Nel caso in esame, come evidenziano i Giudici di Appello, i\u00a0<em>rider\u00a0<\/em>di Foodora lavorano sulla base di una turnistica stabilita dalla societ\u00e0, le zone di partenza sono determinate dalla committente, gli indirizzi presso cui di volta in volta effettuare la consegna vengono comunicati tramite app e i tempi di consegna sono predeterminati (30 minuti dall\u2019orario indicato per il ritiro del cibo).\u00a0\u00a0Indubbiamente le modalit\u00e0 di esecuzione sono organizzate dalla committente quanto ai tempi e ai luoghi di lavoro, ma non esiste alcun obbligo di eseguire la prestazione in quanto i\u00a0<em>rider\u00a0<\/em>devono candidarsi a svolgere l\u2019attivit\u00e0 nelle fasce orarie stabilite e possono revocare la disponibilit\u00e0 data senza alcuna conseguenza sanzionatoria.\u00a0<\/p>\n<p>La sentenza in commento ha, pertanto, accolto parzialmente il ricorso negando il rapporto di lavoro subordinato, ma riconoscendo il diritto alla retribuzione stabilita per i dipendenti del V livello CCNL Trasposto e Logistica.<\/p>\n<h2><span style=\"color: #FF0000;\"><strong>Lavori digitali: alcune iniziative locali per tutelarli<\/strong><\/span><\/h2>\n<p>A seguito delle sollecitazioni provenienti dalla larga diffusione in Italia del fenomeno e dal grande scalpore destato dalla pronunce di merito appena esaminate, la Regione Lazio con la legge regionale n. 4\/2019 ha previsto\u00a0<strong>tutele\u00a0<em>ad hoc\u00a0<\/em>per i lavoratori digitali\u00a0<\/strong>in tema di salute, sicurezza, previdenza, assistenza e compenso.\u00a0<\/p>\n<p>Gli obiettivi prefissati sono il miglioramento della trasparenza del mercato del lavoro digitale e il contrasto al lavoro non sicuro e a\u00a0<strong>ogni forma di diseguaglianza e di sfruttamento<\/strong>. In particolare, la piattaforma digitale \u00e8 tenuta a fornire al lavoratore dispositivi di protezione conformi alla disciplina in materia di salute e di sicurezza sul lavoro, ad attivare\u00a0\u00a0l\u2019<strong>assicurazione contro gli infortuni sul lavoro\u00a0<\/strong>e le\u00a0<strong>malattie professionali\u00a0<\/strong>in favore del lavoratore digitale, quella per danni cagionati a terzi durante lo svolgimento dell\u2019attivit\u00e0 di servizio nonch\u00e9 quella per la\u00a0<strong>tutela della maternit\u00e0 e della paternit\u00e0<\/strong>. Inoltre, la piattaforma \u00e8 tenuta a pagare un compenso non inferiore alla misura oraria minima determinata dai contratti collettivi di lavoro sottoscritti dalle organizzazioni sindacali comparativamente pi\u00f9 rappresentative.<\/p>\n<p>Come evidenziato dall\u2019 <a href=\"https:\/\/toffolettodeluca.it\/it\/avvocati-diritto-del-lavoro\/i-nostri-soci\/aldo.bottini\/\" >avv. Bottini<\/a>  , partner dello studio Toffoletto De Luca Tamajo, in un articolo pubblicato sul Sole 24 Ore,\u00a0 <a href=\"http:\/\/quotidianolavoro.ilsole24ore.com\/art\/contratti-lavoro\/2019-04-29\/dalla-regione-lazio-legge-i-lavoratori-digitali-185142.php?uuid=ABimcpsB\" target=\"_blank\" rel=\"noopener\">\u201cLavori digitali: dalla Regione Lazio una legge ad hoc\u201d<\/a>  ,\u00a0il provvedimento suscita molti dubbi: in particolare, si segnala che ai lavoratori digitali devono essere garantiti diritti di informazione e di formazione sulle modalit\u00e0 di svolgimento dell\u2019attivit\u00e0 e sui relativi rischi nonch\u00e9 sulle modalit\u00e0 con cui l\u2019algoritmo determina l\u2019incontro fra la domanda e l\u2019offerta di servizio. Quest\u2019ultima previsione \u00e8 alquanto problematica stanti i profili di segreto industriale coinvolti. A ci\u00f2 si aggiunga che, come visto sopra, la Legge regionale detta addirittura regole sul compenso dovuto ai lavoratori digitali. In sostanza ci troviamo in presenza di un provvedimento ad alto rischio di incostituzionalit\u00e0 in quanto si spinge nel terreno della regolamentazione del rapporto di lavoro, terreno che rientra nell\u2019ordinamento civile, materia di potest\u00e0 legislativa statale esclusiva.\u00a0<\/p>\n<p>Accanto all\u2019iniziativa della Regione Lazio si colloca quella del Comune di Bologna che il 31 maggio 2018 ha emanato la \u201cCarta dei diritti fondamentali del lavoro digitale nel contesto urbano\u201d. All&#8217;esito di una mobilitazione che ha visto protagonisti i lavoratori del\u00a0<em>food delivery\u00a0<\/em>riuniti nella\u00a0<em>Riders Union\u00a0<\/em>Bologna, \u00e8 stata sottoscritta da sindacati, Comune e alcune piattaforme locali la Carta dei diritti fondamentali dei\u00a0<em>riders\u00a0<\/em>che costituisce il primo esperimento in Europa di riconoscimento dei diritti dei lavoratori digitali. Tra i pi\u00f9 rilevanti diritti contenuti nel testo si rinvengono il\u00a0<strong>compenso orario fisso equo e dignitoso<\/strong>, non inferiore ai minimi tabellari sanciti dai contratti collettivi di settore, le\u00a0<strong>maggiorazioni per lavoro festivo<\/strong>, notturno o svolto in condizioni meteo sfavorevoli, la\u00a0<strong>tutela della salute e della sicurezza\u00a0<\/strong>dei lavoratori indipendentemente dalla qualificazione giuridica del rapporto e la\u00a0<strong>copertura assicurativa contro infortuni e malattie sul lavoro<\/strong>.<\/p>\n<h2><span style=\"color: #FF0000;\"><strong>In GU il decreto-legge sui\u00a0<em>rider<\/em><\/strong><\/span><\/h2>\n<p>L\u2019intervento legislativo tanto atteso in materia di lavoro digitale \u00e8 stato pubblicato in Gazzetta Ufficiale il 4 settembre 2019. Si tratta del DL 101\/2019 contenente \u201cMisure urgenti per la tutela del lavoro e la risoluzione di crisi aziendali\u201d, approvato dal Consiglio dei Ministri lo scorso 6 agosto.<\/p>\n<p>Il provvedimento, in particolare, interviene sul D.Lgs. 81\/2015 estendendo la disciplina del rapporto di lavoro subordinato alle collaborazioni le cui \u201cmodalit\u00e0 di esecuzione della prestazione siano organizzate mediante piattaforme anche digitali\u201d (art. 2, comma 1 rubricato \u201ccollaborazioni organizzate dal committente\u201d). In sostanza, \u00e8 prevista l\u2019applicazione della disciplina del rapporto di lavoro subordinato a tutti i lavoratori su piattaforma (digitale e non) purch\u00e9 il rapporto di lavoro presenti le caratteristiche proprie della collaborazione etero-organizzata.<\/p>\n<p>In tal modo il legislatore ha cristallizzato in una norma ci\u00f2 che i giudici del caso Foodora 2019 avevano gi\u00e0 dedotto dall\u2019interpretazione dell\u2019art. 2 comma 1 D.Lgs 81\/2015: se la prestazione del lavoratore, organizzata mediante piattaforma, si svolge nelle forme tipiche delle collaborazioni organizzate dal committente, si applicano la disciplina e, quindi, le tutele del lavoro subordinato. In altre parole, si lascia ai giudici campo libero nella valutazione delle caratteristiche dei rapporti di lavoro \u201cdigitali\u201d, senza sostanzialmente aggiungere un tassello nuovo al quadro gi\u00e0 delineato dalla giurisprudenza, cosa che, invece, ci si aspettava da questo DL.\u00a0<\/p>\n<p>Accanto a questa previsione si segnala che il DL ha inserito nel D.Lgs 81\/2015 anche un intero capo (V-bis) in cui sono previste specifiche tutele per i\u00a0<em>rider<\/em>, definiti come \u201clavoratori impiegati nelle attivit\u00e0 di consegna di beni per conto altrui, in ambito urbano e con l\u2019ausilio di velocipedi o veicoli a motore\u201d.<\/p>\n<p>In particolare, \u00e8 prevista la possibilit\u00e0 di determinare il compenso in base alle consegne effettuate (cottimo) purch\u00e9 in misura non prevalente, nonch\u00e9 la possibilit\u00e0 di riconoscere un compenso orario a condizione che, per ciascuna ora, il lavoratore accetti almeno una chiamata. A ci\u00f2 si aggiunga anche che i\u00a0<em>rider<\/em>sono soggetti alla copertura assicurativa obbligatoria contro gli infortuni sul lavoro e le malattie professionali, che sar\u00e0 a totale carico dell\u2019impresa.<\/p>\n<p>Si segnala che le tutele contenute nel capo V-bis del D.Lgs. 81\/2015 si applicheranno decorsi 180 giorni dalla data di entrata in vigore della legge di conversione del DL.<\/p>\n<h2><span style=\"color: #FF0000;\"><strong>Conclusioni<\/strong><\/span><\/h2>\n<p>Dalla breve analisi delle problematiche della\u00a0<em>gig economy\u00a0<\/em>emerge come ancora siano molto labili i confini tra autonomia e subordinazione e che proprio nel momento storico in cui sembrava raggiunto un equilibrio anche giurisprudenziale nell\u2019applicazione degli indici rivelatori della subordinazione, l\u2019esplodere del lavoro digitale ha rimesso in discussione le poche certezze raggiunte. Ancora una volta i confini sembrano labili, le Corti di merito altalenanti e non resta che attendere fiduciosi una pronuncia di legittimit\u00e0 che definisca nel modo pi\u00f9 ragionevole e di buon senso i criteri in base ai quali qualificare questi nuovi lavori.<\/p>\n<p>Alle problematiche in materia di qualificazione dei rapporti di lavoro in questione non sembra, poi, aver dato congrua risposta il recentissimo intervento normativo: il DL 2019, infatti, non ha fornito criteri specifici per la qualificazione dei rapporti di lavoro digitali. Esso si \u00e8 limitato a prevedere espressamente che anche ai lavoratori digitali, il cui rapporto abbia la forma della collaborazione etero-organizzata, si applica la disciplina del rapporto di lavoro subordinato (soluzione, come visto, gi\u00e0 individuata dalla giurisprudenza) e a riconoscere alcune tutele nel caso in cui i\u00a0<em>rider<\/em>non siano n\u00e9 lavoratori subordinati n\u00e9 collaboratori ex art. 1 D.lgs. 81\/2015.<\/p>\n<p> &#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Di:<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","_lmt_disableupdate":"","_lmt_disable":"","footnotes":""},"categories":[],"tags":[165],"class_list":["post-3254","post","type-post","status-publish","format-standard","hentry","tag-gig-economy-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gig economy: quando il lavoro incontra la tecnologia (aggiornato al DL Rider 2019) - Toffoletto De Luca Tamajo e Soci<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/toffolettodeluca.it\/en\/gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gig economy: quando il lavoro incontra la tecnologia (aggiornato al DL Rider 2019) - Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"og:description\" content=\"Di:\" \/>\n<meta property=\"og:url\" content=\"https:\/\/toffolettodeluca.it\/en\/gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Toffoletto De Luca Tamajo e Soci\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-06T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\"},\"headline\":\"Gig economy: quando il lavoro incontra la tecnologia (aggiornato al DL Rider 2019)\",\"datePublished\":\"2019-08-06T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019\\\/\"},\"wordCount\":13,\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"keywords\":[\"Gig economy\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019\\\/\",\"name\":\"Gig economy: quando il lavoro incontra la tecnologia (aggiornato al DL Rider 2019) - Toffoletto De Luca Tamajo e Soci\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\"},\"datePublished\":\"2019-08-06T00:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/studio-diritto-del-lavoro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Newsflash &amp; Insights\",\"item\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/category\\\/newsflash-insight\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gig economy: quando il lavoro incontra la tecnologia (aggiornato al DL Rider 2019)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#organization\",\"name\":\"Toffoletto De Luca Tamajo e Soci\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"contentUrl\":\"https:\\\/\\\/toffolettodeluca.it\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/logo_100anni.svg\",\"caption\":\"Toffoletto De Luca Tamajo e Soci\"},\"image\":{\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/#\\\/schema\\\/person\\\/5af8f8d6da381ab29594446f2f961559\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/toffolettodeluca.it\\\/en\\\/author\\\/redazione\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gig economy: quando il lavoro incontra la tecnologia (aggiornato al DL Rider 2019) - Toffoletto De Luca Tamajo e Soci","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/toffolettodeluca.it\/en\/gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019\/","og_locale":"en_US","og_type":"article","og_title":"Gig economy: quando il lavoro incontra la tecnologia (aggiornato al DL Rider 2019) - Toffoletto De Luca Tamajo e Soci","og_description":"Di:","og_url":"https:\/\/toffolettodeluca.it\/en\/gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019\/","og_site_name":"Toffoletto De Luca Tamajo e Soci","article_published_time":"2019-08-06T00:00:00+00:00","author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Redazione"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/toffolettodeluca.it\/en\/gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019\/#article","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019\/"},"author":{"name":"Redazione","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559"},"headline":"Gig economy: quando il lavoro incontra la tecnologia (aggiornato al DL Rider 2019)","datePublished":"2019-08-06T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/toffolettodeluca.it\/en\/gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019\/"},"wordCount":13,"publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"keywords":["Gig economy"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/toffolettodeluca.it\/en\/gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019\/","url":"https:\/\/toffolettodeluca.it\/en\/gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019\/","name":"Gig economy: quando il lavoro incontra la tecnologia (aggiornato al DL Rider 2019) - Toffoletto De Luca Tamajo e Soci","isPartOf":{"@id":"https:\/\/toffolettodeluca.it\/en\/#website"},"datePublished":"2019-08-06T00:00:00+00:00","breadcrumb":{"@id":"https:\/\/toffolettodeluca.it\/en\/gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/toffolettodeluca.it\/en\/gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/toffolettodeluca.it\/en\/gig-economy-quando-il-lavoro-incontra-la-tecnologia-aggiornato-al-dl-rider-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/toffolettodeluca.it\/en\/studio-diritto-del-lavoro\/"},{"@type":"ListItem","position":2,"name":"Newsflash &amp; Insights","item":"https:\/\/toffolettodeluca.it\/en\/category\/newsflash-insight\/"},{"@type":"ListItem","position":3,"name":"Gig economy: quando il lavoro incontra la tecnologia (aggiornato al DL Rider 2019)"}]},{"@type":"WebSite","@id":"https:\/\/toffolettodeluca.it\/en\/#website","url":"https:\/\/toffolettodeluca.it\/en\/","name":"Toffoletto De Luca Tamajo e Soci","description":"","publisher":{"@id":"https:\/\/toffolettodeluca.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/toffolettodeluca.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/toffolettodeluca.it\/en\/#organization","name":"Toffoletto De Luca Tamajo e Soci","url":"https:\/\/toffolettodeluca.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","contentUrl":"https:\/\/toffolettodeluca.it\/wp-content\/uploads\/2025\/04\/logo_100anni.svg","caption":"Toffoletto De Luca Tamajo e Soci"},"image":{"@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/toffolettodeluca.it\/en\/#\/schema\/person\/5af8f8d6da381ab29594446f2f961559","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8185611aa32d596559515f3a5b9b81ac5e1c4ca55d57079dc140388ca8946e36?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/toffolettodeluca.it\/en\/author\/redazione\/"}]}},"modified_by":null,"_links":{"self":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/3254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/comments?post=3254"}],"version-history":[{"count":0,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/posts\/3254\/revisions"}],"wp:attachment":[{"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/media?parent=3254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/categories?post=3254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/toffolettodeluca.it\/en\/wp-json\/wp\/v2\/tags?post=3254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}